{"id":151492,"date":"2020-10-06T14:09:00","date_gmt":"2020-10-06T18:09:00","guid":{"rendered":"https:\/\/www.noticel.com\/cuidate\/vida\/20201006\/disponible-nuevo-tratamiento-para-artritis-infantil\/"},"modified":"2025-07-16T16:52:49","modified_gmt":"2025-07-16T16:52:49","slug":"disponible-nuevo-tratamiento-para-artritis-infantil","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20201006\/disponible-nuevo-tratamiento-para-artritis-infantil\/","title":{"rendered":"Disponible nuevo tratamiento para artritis infantil"},"content":{"rendered":"<h3>Se aprobaron dos formulaciones, una tableta y una soluci\u00f3n oral y sus dosis son basadas en el peso<\/h3>\n<p>Pfizer Inc. anunci\u00f3 que la Administraci\u00f3n de Drogas y Alimentos de los Estados Unidos (FDA) aprob\u00f3 XELJANZ\u00ae (tofacitinib) para el tratamiento de ni\u00f1os y adolescentes de dos a\u00f1os en adelante con artritis idiop\u00e1tica juvenil de curso poliarticular (pcJIA por sus siglas en ingl\u00e9s).<\/p>\n<p>Se inform\u00f3 que se aprobaron dos formulaciones, una tableta y una soluci\u00f3n oral y sus dosis son basadas en el peso. Esta aprobaci\u00f3n convierte a XELJANZ el primer y \u00fanico inhibidor de la quinasa de Janus (JAK por sus siglas en ingl\u00e9s) aprobado en los Estados Unidos para el tratamiento de la pcJIA.<\/p>\n<p>\u201cLa artritis idiop\u00e1tica juvenil de curso poliarticular, o pcJIA, es una enfermedad debilitante ya que causa dolor articular significativo y limita la participaci\u00f3n en actividades apropiadas para los ni\u00f1os\u201d, dijo la doctora Hermine Brunner, directora de la Divisi\u00f3n de Reumatolog\u00eda del Hospital Infantil de Cincinnati y directora cient\u00edfica del Grupo de Estudio Colaborativo de Reumatolog\u00eda Pedi\u00e1trica.<\/p>\n<p>\u201cA pesar de que ya hay varios tratamientos avanzados disponibles, tofacitinib ser\u00e1 una nueva y atractiva opci\u00f3n tanto para los ni\u00f1os con pcJIA como para sus cuidadores. La aprobaci\u00f3n de la FDA de XELJANZ para la pcJIA es una noticia positiva para esta comunidad ya que provee una nueva opci\u00f3n de tratamiento avanzado en formulaci\u00f3n oral\u201d, indic\u00f3.<\/p>\n<p>Esta aprobaci\u00f3n se bas\u00f3 en datos de un estudio Fase 3 que incluy\u00f3 dos fases: una fase de rodaje abierta de 18 semanas (incluidos 225 pacientes), seguida de una fase de retirada doble ciega, controlada por placebo y aleatoria de 26 semanas (incluidos 173 pacientes), con una duraci\u00f3n total de 44 semanas.<\/p>\n<p>El estudio evalu\u00f3 la eficacia y seguridad de tofacitinib tomado como una tableta de 5mg o como soluci\u00f3n oral de 1mg\/mL dos veces al d\u00eda, bas\u00e1ndose en el peso corporal del sujeto (&lt;40 kg para la soluci\u00f3n oral) y\/o en la preferencia del paciente.<\/p>\n<p>\u201cMuchos de esos ni\u00f1os y adolescentes que viven artritis idiop\u00e1tica juvenil de curso poliarticular o pcJIA necesitan opciones avanzadas de tratamiento oral. Por eso estamos orgullosos de ofrecer XELJANZ a esta comunidad de pacientes\u201d, dijo Michael Corbo, director principal de desarrollo, Inflamaci\u00f3n e Inmunolog\u00eda, Desarrollo de Productos Globales de Pfizer.<\/p>\n<p>\u201cEsta aprobaci\u00f3n es la cuarta indicaci\u00f3n para XELJANZ y refuerza su utilidad en el tratamiento de condiciones inflamatorias mediadas por el sistema inmune y demuestra adem\u00e1s nuestra experticia en la ciencia del JAK\u201d.<\/p>\n<p>Se anticipa que la soluci\u00f3n oral de XELJANZ est\u00e9 disponible para el primer semestre de 2021. Las tabletas de 5mg de XELJANZ est\u00e1n disponibles inmediatamente.<\/p>","protected":false},"excerpt":{"rendered":"<p>Se aprobaron dos formulaciones, una tableta y una soluci\u00f3n oral y sus dosis son basadas en el peso Pfizer Inc. anunci\u00f3 que la Administraci\u00f3n de Drogas y Alimentos de los Estados Unidos (FDA) aprob\u00f3 XELJANZ\u00ae (tofacitinib) para el tratamiento de ni\u00f1os y adolescentes de dos a\u00f1os en adelante con artritis idiop\u00e1tica juvenil de curso poliarticular [&hellip;]<\/p>","protected":false},"author":0,"featured_media":460392,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-151492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/151492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=151492"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/151492\/revisions"}],"predecessor-version":[{"id":460394,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/151492\/revisions\/460394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/460392"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=151492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=151492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=151492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}