{"id":15074,"date":"2015-03-23T00:00:00","date_gmt":"2015-03-23T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/negocio-de-la-salud\/20150323\/falta-de-acceso-e-informacion-coartan-el-derecho-a-la-salud-galeria\/"},"modified":"2025-07-16T23:34:48","modified_gmt":"2025-07-16T23:34:48","slug":"falta-de-acceso-e-informacion-coartan-el-derecho-a-la-salud-galeria","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20150323\/falta-de-acceso-e-informacion-coartan-el-derecho-a-la-salud-galeria\/","title":{"rendered":"Falta de acceso e informaci\u00f3n coartan el derecho a la salud (galer\u00eda)"},"content":{"rendered":"<p>La tercera edici\u00f3n de la campa\u00f1a de educaci\u00f3n y concienciaci\u00f3n de los derechos humanos y civiles, Trayecto Dignidad, finaliz\u00f3 hoy lunes en el ala norte del Capitolio, luego de dos intensos d\u00edas de recorrido por el pa\u00eds para auscultar la situaci\u00f3n general de acceso a la salud.<\/p>\n<p>&#8216;La dignidad es el principio fundamental de todos los derechos que cobija nuestra Constituci\u00f3n, y esa dignidad se viola diariamente al neg\u00e1rsele a la gente servicios de salud&#8217;, denunci\u00f3 el profesor de la Facultad de Derecho de la Universidad Interamericana, Juan Correa Luna. Con el objetivo de rescatar las historias de primera mano para adentrarse en las fallas del sistema, se gest\u00f3 el Trayecto.<\/p>\n<p>El grupo de profesores, estudiantes, organizaciones, l\u00edderes comunitarios, y artistas, parti\u00f3 en la ma\u00f1ana del s\u00e1bado en tres guaguas escolares para enfilarse en tres rutas por el noroeste, noreste y centro del Pa\u00eds. A su paso, visitaron diversas comunidades en las que administraron encuestas para recopilar informaci\u00f3n sobre las experiencias de la gente con el sistema de salud del pa\u00eds.<\/p>\n<p>Tambi\u00e9n llevaron consigo cl\u00ednicas de salud ambulantes dirigidas por m\u00e9dicos voluntarios, y performances del colectivo Sembrando Conciencia, quienes, a trav\u00e9s del arte y la expresi\u00f3n corporal, denunciaron el atropello a los derechos humanos en Puerto Rico.<\/p>\n<p>Aunque ahora toca tabular los resultados de la jornada, el tambi\u00e9n profesor de la Facultad de Derecho de la Universidad Interamericana, Osvaldo Burgos, asegur\u00f3 que los resultados son alarmantes. Voces diversas casi de forma un\u00e1nime reconocieron problemas de acceso a la salud, optando incluso por abandonar el pa\u00eds para recibir un mejor tratamiento.<\/p>\n<p>Se enfrentaron a fuertes palabras como: &#8216;El sistema es parte de la muerte temprana de mis hijos&#8217;. Escucharon relatos de indignaci\u00f3n de gente que pasan horas en salas de espera, para luego enfrentarse a la mala calidad del servicio, la falta de referidos y los tratamientos no cubiertos por el plan. Brotaron l\u00e1grimas y muestras de solidaridad.<\/p>\n<p>La falta de conocimiento se col\u00f3 tambi\u00e9n recurrentemente en las respuestas de la poblaci\u00f3n. El profesor Correa Luna cont\u00f3 que muchos desconoc\u00edan la existencia de una Oficina del Procurador del Paciente, las ventajas del Obama Care, los efectos secundarios de ciertas medicinas, entre otros.<\/p>\n<p>Luego de documentar los hallazgos, pretenden comenzar un proceso de divulgaci\u00f3n a trav\u00e9s de publicaciones en revistas jur\u00eddicas, art\u00edculos, conferencias de prensa, foros, entre otros. A la par, intentan fomentar la creaci\u00f3n de pol\u00edticas p\u00fablicas tomando en consideraci\u00f3n los datos obtenidos.<\/p>\n<p>Varios miembros del Colectivo expresaron que el sistema de lucro en la salud es parte intr\u00ednseca del problema. Correa Luna denunci\u00f3 que Puerto Rico cuenta con un sistema de salud, donde &#8216;la mayor parte del presupuesto, se destina a llenarle los bolsillos a los altos ejecutivos de las grandes aseguradoras&#8217;.<\/p>\n<p>&#8216;Hay que sacar del medio a las aseguradoras y comenzar a establecer un sistema que responda a la dignidad de las personas&#8217;, agreg\u00f3.<\/p>\n<p>Por eso, la profesora e investigadora de la Escuela de Derecho de la Universidad de Puerto Rico, Marinilda Rivera D\u00edaz, invit\u00f3 a la comunidad a participar este martes, a partir de las 10 de la ma\u00f1ana, de la discusi\u00f3n del Proyecto de la C\u00e1mara 1185, que podr\u00eda &#8216;estudiar la viabilidad de un sistema universal de salud&#8217;, dijo.<\/p>\n<p>A su vez, la profesora de la misma Escuela, Nylca Mu\u00f1oz Sosa, recalc\u00f3 que este proyecto de ley ha fallado en proponer un mecanismo de concertaci\u00f3n social para que la poblaci\u00f3n afectada tenga voz directa en el dise\u00f1o de la pol\u00edtica p\u00fablica. &#8216;M\u00e1s que estudiar, es qui\u00e9nes lo van a estudiar&#8217;, cuestion\u00f3 la profesora.<\/p><div class=\"notic-content-middle\" id=\"notic-776827065\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/01063907\/CST_Suma-Pasa-La-Llave_970x250.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/01063907\/CST_Suma-Pasa-La-Llave_970x250.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/01063907\/CST_Suma-Pasa-La-Llave_970x250-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/01063907\/CST_Suma-Pasa-La-Llave_970x250-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/01063907\/CST_Suma-Pasa-La-Llave_970x250-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Junto a los profesores, se encontraban estudiantes de la Escuela Graduada de Salud P\u00fablica, de Trabajo Social y de la Escuela de Derecho del sistema p\u00fablico y privado. &#8216;Estos j\u00f3venes saben de primera mano cu\u00e1n disfuncional es el sistema no porque lo esucharon de los legisladores, sino porque lo escucharon del pueblo&#8217;, asegur\u00f3 Correa Luna.<\/p>\n<p>La estudiante graduada de Trabajo Social, Neysha Serrrano, particip\u00f3 por primera vez del Trayecto. &#8216;Fue poner en pr\u00e1ctica lo que recibo en la Universidad desde la teor\u00eda, fue estar cerca de la gente, ver que no somos pocos lo que piensan que necesitamos un cambio de sistema. Muchas personas mueren y pasan muchas necesidades por el sistema actual de salud. Hay que promover un sistema distinto&#8217;, enfatiz\u00f3.<\/p>\n<p>Ismael, un estudiante de la Escuela de Derecho de la Universidad de Puerto Rico, habl\u00f3 al micr\u00f3fono. &#8216;Nos involucramos porque entendemos que el derecho no solo se hace en la Legislatura y los tribunales&#8230; el derecho se hace en la calle, con la gente&#8217;.<\/p>\n<p>La Fundaci\u00f3n M\u00e9dica del Colegio de M\u00e9dicos Cirujanos de Puerto Rico, junto a las dos instituciones universitarias antes mencionadas, apoyaron con el financiamiento de la actividad. Corrrea Luna denunci\u00f3 que las agencias, m\u00e1s que apoyar, colocaban obst\u00e1culos, como la entrega de material educativo.<\/p>\n<p>En el Trayecto particip\u00f3 tambi\u00e9n el Colectivo Comunitario G8, que agrupa las ocho comunidades aleda\u00f1as al Ca\u00f1o Mart\u00edn Pe\u00f1a, que exigi\u00f3 el dragado como una urgencia de salud como derecho. Adem\u00e1s, participaron la Alianza de Salud para el Pueblo, el Programa Pro Bono de Justicia en Salud, entre otros.<\/p>\n<p><strong>El inseguro camino de los derechos humanos<\/strong><\/p>\n<p>El Colectivo Somos Dign@s surgi\u00f3 en 2010 somo respuesta a la violaci\u00f3n de derechos humanos. Entonces, en el marco de protesta estudiantil, los actos de violencia y represi\u00f3n a la libertad de expresi\u00f3n que se suscitaron precisamente en los alrededores del Capitolio, fueron punto de partida para que se unieran organizaciones e individuos preocupados por &#8216;la crisis de derechos humanos&#8217;.<\/p>\n<p>La intenci\u00f3n de Trayecto Dignidad es recopilar informaci\u00f3n que sirva como base investigativa para construir un panorama sobre la experiencia del pueblo en t\u00e9rminos de derechos humanos y civiles. Por eso, el primer Trayecto se llev\u00f3 a cabo en el 2011, y trabaj\u00f3 el tema de los derechos humanos en general.<\/p>\n<p>Los resultados de aquella encuesta condujeron a resultados alarmantes, coincidieron. La \u00faltima vez que se hab\u00eda realizado una iniciativa similar fue en el a\u00f1o 1959, y esta vez repitieron una pregunta formulada en aquel entonces: Conoces alg\u00fan derecho civil? Mientras que en 1959, un 46% no supo contestar, en el 2011, un 54.3% tampoco supo mencionar un derecho civil y el 59% no supo mencionar un derecho humano.<\/p>\n<p>Esta situaci\u00f3n provoc\u00f3 que el Colectivo propiciara un proyecto de ley que implantara como requisito de graduaci\u00f3n en el sistema de educaci\u00f3n p\u00fablica del pa\u00eds un programa para la ense\u00f1anza de derechos humanos, civiles y constitucionales. Este proyecto est\u00e1 atascado en la Legislatura, denunci\u00f3 Burgos.<\/p>\n<p>Adem\u00e1s de integrar clases de derechos humanos, Correa Luna a\u00f1adi\u00f3 que debe implementarse un curr\u00edculo que atienda el problema del racismo y con perspectiva de g\u00e9nero. Cont\u00f3 que en el segundo Trayecto Dignidad, orientado al racismo, aflor\u00f3 que el rostro m\u00e1s discriminado era la mujer negra.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"610382729\" embed-content-groupid=\"593030471\" embed-content-id=\"610382730\" embed-content-index=\"0\" embed-content-type=\"GALLERY\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2015\/03\/23\/a44dc71a3e50ad6307bd4812f57a1228_8148076_ver1.0_320_240.jpg\"\/>\u00a0\u00a0\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>La tercera edici\u00f3n de la campa\u00f1a de educaci\u00f3n y concienciaci\u00f3n de los derechos humanos y civiles, Trayecto Dignidad, finaliz\u00f3 hoy lunes en el ala norte del Capitolio, luego de dos intensos d\u00edas de recorrido por el pa\u00eds para auscultar la situaci\u00f3n general de acceso a la salud. &#8216;La dignidad es el principio fundamental de todos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":481429,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-15074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/15074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=15074"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/15074\/revisions"}],"predecessor-version":[{"id":481441,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/15074\/revisions\/481441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/481429"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=15074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=15074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=15074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}