{"id":14980,"date":"2018-07-18T00:00:00","date_gmt":"2018-07-18T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/gobierno\/top-stories\/20180718\/rossello-tambien-gasto-miles-en-guagua-blindada\/"},"modified":"2025-07-16T23:46:43","modified_gmt":"2025-07-16T23:46:43","slug":"rossello-tambien-gasto-miles-en-guagua-blindada","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20180718\/rossello-tambien-gasto-miles-en-guagua-blindada\/","title":{"rendered":"Rossell\u00f3 tambi\u00e9n gast\u00f3 miles en guagua blindada"},"content":{"rendered":"<p><i>Alega fue una recomendaci\u00f3n de Seguridad P\u00fablica.<\/i><\/p>\n<p>El gobernador Ricardo Rossell\u00f3 autoriz\u00f3 la compra de una guagua blindada que incluye unas amenidades de lujo por el costo de unos $245 mil.<\/p>\n<p>Seg\u00fan trascendi\u00f3 en el programa &#8216;Jay y sus Rayos X&#8217;, el autom\u00f3vil marca Chevrolet ten\u00eda un costo total de $86,950, sumado a blindaje recomendado por el departamento de Seguridad P\u00fablica por un total de $85 mil, equipo de blindaje en $41,650, y un paquete de lujo que le tra\u00eda descansa pies, techo m\u00e1s alto, sillas personalizadas y servicio de telefono satelital entre otras amenidades, en un paquete de lujo con un costo total adicional de $58,950.<\/p><div class=\"notic-content-middle\" id=\"notic-2949393851\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Texas Armoring Corporation (TAC) fue la empresa que recibi\u00f3 la orden de compra y prepar\u00f3 el veh\u00edculo.<\/p>\n<p>Seg\u00fan declaraciones que se expusieron en ese programa, Rossell\u00f3 no supo del precio del carro y tras el secretario de Seguridad P\u00fablica, Hector Pesquera, present\u00e1rselo, orden\u00f3 a transferirlo para el uso de las Unidades Especiales de la Polic\u00eda de Puerto Rico.<\/p>\n<p>La revelaci\u00f3n de este nuevo veh\u00edculo llega a solo 1 semana de que se difundiera en el mismo espacio que la comisionada residente Jenniffer Gonz\u00e1lez hab\u00eda solicitado la aprobaci\u00f3n de una <a href=\"https:\/\/noticel.com\/en\/ahora\/politica\/pnp\/nuevo-vehiculo-de-jgo-le-cuesta-mas-de-60-mil-a-pr\/766512260\/\" target=\"_blank\">guagua personalizada de unos $60 mil<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Alega fue una recomendaci\u00f3n de Seguridad P\u00fablica. El gobernador Ricardo Rossell\u00f3 autoriz\u00f3 la compra de una guagua blindada que incluye unas amenidades de lujo por el costo de unos $245 mil. Seg\u00fan trascendi\u00f3 en el programa &#8216;Jay y sus Rayos X&#8217;, el autom\u00f3vil marca Chevrolet ten\u00eda un costo total de $86,950, sumado a blindaje recomendado [&hellip;]<\/p>","protected":false},"author":0,"featured_media":481959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-14980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/14980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=14980"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/14980\/revisions"}],"predecessor-version":[{"id":481962,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/14980\/revisions\/481962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/481959"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=14980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=14980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=14980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}