{"id":149302,"date":"2020-08-12T06:52:00","date_gmt":"2020-08-12T10:52:00","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/policiacas\/top-stories\/20200812\/arrestan-al-septimo-acusado-en-caso-de-julia-keleher\/"},"modified":"2025-07-16T20:49:18","modified_gmt":"2025-07-16T20:49:18","slug":"pliego-acusatorio-menciona-a-rossello-nevares-con-consultor-de-ases-acusado","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20200812\/pliego-acusatorio-menciona-a-rossello-nevares-con-consultor-de-ases-acusado\/","title":{"rendered":"Pliego acusatorio menciona a Rossell\u00f3 Nevares con consultor de ASES acusado"},"content":{"rendered":"<h3>Se trata de la acusaci\u00f3n enmendada que a\u00f1adi\u00f3 tambi\u00e9n como acusado al contador p\u00fablico autorizado An\u00edbal Jover Pages.<\/h3>\n<p>La acusaci\u00f3n federal enmendada en el primer caso contra la exsecretaria de Educaci\u00f3n, Julia B. Keleher, no solo a\u00f1ade como acusado al contador p\u00fablico autorizado (CPA), An\u00edbal Jover Pages, sino que consigna c\u00f3mo el exgobernador Ricardo Rossell\u00f3 Nevares personalmente reclut\u00f3 al consultor Alberto Vel\u00e1zquez Pi\u00f1ol, uno de los coacusados, para trabajar varios asuntos en su administraci\u00f3n.<\/p>\n<p>Se trata de informaci\u00f3n nueva divulgada para este caso y, que se conozca hasta ahora, de la primera vez que Rossell\u00f3 Nevares aparece consignado en una acusaci\u00f3n, aunque no est\u00e1 acusado ni se le identifica como un \u00abcoconspirador no acusado\u00bb.<\/p>\n<p>\u00abEntre 2017 y 2018, Vel\u00e1zquez tuvo numerosas comunicaciones por correo electr\u00f3nico con el Gobernador de Puerto Rico, incluyendo el siguiente intercambio el 17 de marzo de 2017\u00bb, dice el pliego.<\/p>\n<p>El intercambio lo origin\u00f3 Rossell\u00f3 Nevares escribiendo, a las 6:07 am, \u00abAlberto me gustar\u00eda hablar contigo para varios asuntos; incluyendo el nuevo modelo de salud que he dise\u00f1ado. Tambi\u00e9n \u00e1reas que entiendas tengamos escasos recursos en Salud y ASES; para solicitar mediante la Junta de Supervisi\u00f3n recursos federales que nos complementen en el esfuerzo. Me alegra mucho saber que est\u00e1s en el equipo. Un fuerte abrazo\u00bb.<\/p>\n<p>Vel\u00e1zquez respondi\u00f3 a las 6:20 am \u00abGobernador! Para mi es un privilegio poder cooperar y aportar apoy\u00e1ndote. Estoy disponible a tu mejor conveniencia. Recibe un fuerte abrazo, Alberto\u00bb.<\/p>\n<p>Vea: <a href=\"https:\/\/noticel.com\/en\/gobierno\/ahora\/top-stories\/20190622\/quien-es-el-consultor-de-bdo-alberto-velazquez-pinol\/\" id=\"link-09d1f5118e39b27da6d9c3584e78af44\" target=\"_blank\">\u00bfQui\u00e9n es el consultor de BDO, Alberto Vel\u00e1zquez Pi\u00f1ol? <\/a><\/p>\n<p>La acusaci\u00f3n incluye un segundo mensaje, que no est\u00e1 claro que Vel\u00e1zquez Pi\u00f1ol haya enviado porque el pliego s\u00f3lo dice que el mensaje qued\u00f3 \u00abmemorializado\u00bb en su cuenta de Gmail el 10 de enero de 2017 y dice:<\/p>\n<p>\u00abGob! Voy a  estar ayudando a [Rafael Rodr\u00edguez Mercado, secretario de Salud] en Salud\/Ases. S\u00e9 q est\u00e1s evaluando candidatos para Dir Ej de Ases y q Angie \u00c1vila est\u00e1 interina. Quiero aportarte mi opini\u00f3n por si es de ayuda antes de q tomes una decisi\u00f3n final sobre el tema. No creo q haya nadie q conozca el programa t\u00e9cnicamente mejor q Angie. Ella es extremadamente respetada en CMS. Esa relaci\u00f3n es cr\u00edtica para mover la agenda hacia adelante &#8230;&#8230;&#8230;. \u00ab.<\/p>\n<p>Vel\u00e1zquez Pi\u00f1ol se refer\u00eda a \u00c1ngela \u00c1vila Marrero, la exadministradora de la Administraci\u00f3n de Seguros de Salud (ASES) y coacusada en el caso que, seg\u00fan los nuevos cargos, viol\u00f3 la ley con Vel\u00e1zquez Pi\u00f1ol y con Jover Pages para dar contratos en la agencia a la entidad de Jover Pages, Intelligent Grant Solutions LLC (IGS).<\/p>\n<p>El 11 de julio pasado, un d\u00eda despu\u00e9s del arresto de Vel\u00e1zquez Pi\u00f1ol, el exgobernador hizo su \u00faltima conferencia de prensa para atender las primeras publicaciones del chat de Telegram que provocar\u00eda su renuncia al cargo el 24 de julio. En esa conferencia, dijo que Vel\u00e1zquez Pi\u00f1ol \u00ab<a href=\"https:\/\/twitter.com\/adrianadesala\/status\/1149493724658860034\" id=\"link-14f9527f6d2b807b77815cdfb08391c2\" target=\"_blank\">colabor\u00f3 en unas iniciativas del Plan para Puerto Rico&#8230;el rol de \u00e9l era consultor. Los consultores no pueden tomar decisiones<\/a>\u00ab.<\/p><div class=\"notic-content-middle\" id=\"notic-1442420249\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El Negociado Federal de Investigaciones (FBI) arrest\u00f3 esta madrugada a Jover Pages en su casa, siendo el s\u00e9ptimo acusado en el caso que involucra a Keleher, \u00c1vila Marrero y Vel\u00e1zquez Pi\u00f1ol.<\/p>\n<p>La fiscal\u00eda recomend\u00f3 una fianza de $200,000 pero en una vista el magistrado Marshall Morgan la aument\u00f3 a $250,000 y concedi\u00f3 20 d\u00edas para prestarla. Jover Pages, de 60 a\u00f1os, se declar\u00f3 no culpable de cinco cargos de fraude electr\u00f3nico (por manejo ilegal de informaci\u00f3n confidencial de ASES), un cargo de conspiraci\u00f3n, siete cargos de fraude electr\u00f3nico (por pago ilegal de comisiones), otro cargo de conspiraci\u00f3n por esos pagos y un cargo de confiscaci\u00f3n, para 14 cargos en total.<\/p>\n<p><iframe loading=\"lazy\" title=\"Abogado de An\u00edbal Jover ofrece detalles del caso tras alegaci\u00f3n de no culpabilidad\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/1OVDt0f442Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Al terminar la vista, Jover Pages sali\u00f3 del edificio que alberga las oficinas de la fiscal\u00eda federal por una puerta de servicio y literalmente corri\u00f3 para evadir a los medios de comunicaci\u00f3n.<\/p>\n<p>Seg\u00fan el pliego acusatorio, Jover Pages pag\u00f3 comisiones a Vel\u00e1zquez Pi\u00f1ol para obtener contratos en ASES con IGS, de manera similar a la que se imput\u00f3 a la firma de contabilidad BDO Puerto Rico, cuyo expresidente, Fernando Scherrer Caillet, es otro coacusado en el caso. Marrero \u00c1vila comparti\u00f3 informaci\u00f3n con Vel\u00e1zquez Pi\u00f1ol sobre contratos y propuestas de ciertos suplidores que el consultor, a su vez, comparti\u00f3 con Jover Pages para que \u00e9ste confeccionara la propuesta de IGS.<\/p>\n<p>Los delitos relativos a los pagos a Vel\u00e1zquez Pi\u00f1ol se habr\u00edan configurado porque el contrato de IGS con ASES prohib\u00eda que IGS pagara a subcontratistas. Sin embargo, en las facturas se representaba que Vel\u00e1zquez Pi\u00f1ol como un \u201csocio\u201d de IGS y se representaban a subcontratistas como si fueran empleados de IGS.<\/p>\n<p><strong id=\"strong-167fe151571dddac59ad4f23b4901e2b\">Para ver la acusaci\u00f3n enmendada, pulse aqu\u00ed: <\/strong><\/p>\n<p><strong id=\"strong-b254277aaccc04d048c74b77adb683f3\">Vea tambi\u00e9n:<\/strong><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/gobierno\/ahora\/top-stories\/20190711\/todo-lo-que-debes-saber-sobre-el-destape-de-fraude-en-educacion-y-ases\/\" id=\"link-aa267dc42c16d99b4fea73878ff3c6e2\" target=\"_blank\">Todo lo que debes saber sobre el destape de fraude en Educaci\u00f3n y ASES<\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/gobierno\/ahora\/tribunales\/top-stories\/20190711\/quien-es-el-acusado-federal-fernando-scherrer-caillet\/\" id=\"link-f474ae6bfceede8b03d0590c334e86ab\" target=\"_blank\">\u00bfQui\u00e9n es el acusado federal Fernando Scherrer Caillet? <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Se trata de la acusaci\u00f3n enmendada que a\u00f1adi\u00f3 tambi\u00e9n como acusado al contador p\u00fablico autorizado An\u00edbal Jover Pages. La acusaci\u00f3n federal enmendada en el primer caso contra la exsecretaria de Educaci\u00f3n, Julia B. Keleher, no solo a\u00f1ade como acusado al contador p\u00fablico autorizado (CPA), An\u00edbal Jover Pages, sino que consigna c\u00f3mo el exgobernador Ricardo Rossell\u00f3 [&hellip;]<\/p>","protected":false},"author":17,"featured_media":474164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15],"tags":[],"class_list":["post-149302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/149302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=149302"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/149302\/revisions"}],"predecessor-version":[{"id":474166,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/149302\/revisions\/474166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/474164"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=149302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=149302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=149302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}