{"id":148915,"date":"2020-08-03T12:03:00","date_gmt":"2020-08-03T16:03:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/top-stories\/20200803\/director-ejecutivo-de-la-aee-jose-ortiz-presenta-su-renuncia\/"},"modified":"2025-07-16T21:26:06","modified_gmt":"2025-07-16T21:26:06","slug":"director-ejecutivo-de-la-aee-jose-ortiz-presenta-su-renuncia","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200803\/director-ejecutivo-de-la-aee-jose-ortiz-presenta-su-renuncia\/","title":{"rendered":"Director ejecutivo de la AEE Jos\u00e9 Ortiz presenta su renuncia"},"content":{"rendered":"<h3>Es efectiva el 5 de agosto.<\/h3>\n<p>La Junta de Gobierno de la Autoridad de Energ\u00eda El\u00e9ctrica (AEE) recibi\u00f3 hoy la renuncia del ingeniero Jos\u00e9 Ortiz V\u00e1zquez como director ejecutivo de la corporaci\u00f3n p\u00fablica.<\/p>\n<p>La renuncia ser\u00e1 efectiva el mi\u00e9rcoles, 5 de agosto de 2020.<\/p>\n<p>Ortiz present\u00f3 su renuncia un d\u00eda despu\u00e9s de que la gobernadora Wanda V\u00e1zquez Garced se reuniera en La Fortaleza con el presidente de la Junta de Directores de la corporaci\u00f3n p\u00fablica, Ralph Kreil Rivera.<\/p>\n<p>\u00abHemos aceptado la renuncia de Ortiz con agradecimiento por el trabajo que ha realizado\u00bb, afirm\u00f3 Kreil Rivera en declaraciones escritas.<\/p>\n<p>Kreil Rivera tambi\u00e9n elogi\u00f3 el trabajo del Ortiz, pese a las cr\u00edticas que ha recibido por su gesti\u00f3n, particularmente en los pasados d\u00edas por la respuesta ineficiente que ofreci\u00f3 la corporaci\u00f3n p\u00fablica ante la emergencia causada por la tormenta tropical Isa\u00edas.<\/p>\n<p>\u00abCuando el Ing. Ortiz se hizo cargo de la AEE, ni siquiera se hab\u00eda completado un Plan Integrado de Recursos (PIR) y est\u00e1bamos luchando por desarrollar una relaci\u00f3n de trabajo con reguladores como el Negociado de Energ\u00eda de Puerto Rico (NEPR) y la Junta de Supervisi\u00f3n Fiscal de Puerto Rico (JSF). Desde entonces, hemos tenido tres planes fiscales aprobados por la JSF y el NEPR est\u00e1 llegando a la conclusi\u00f3n de sus vistas sobre el Plan Integrado de Recursos. Trabajando mano a mano con Ortiz, desarrollamos una s\u00f3lida relaci\u00f3n de trabajo en Washington D.C., logrando credibilidad con el gobierno federal. Entre otros logros, la AEE cre\u00f3 la Oficina de Gesti\u00f3n de Proyectos, que ha sido fundamental para que Costa Sur 5 vuelva a estar en servicio; inici\u00f3 el contrato con LUMA para un mejor servicio de transmisi\u00f3n y distribuci\u00f3n a nuestros abonados y se renegoci\u00f3 el contrato de EcoEl\u00e9ctrica para mejorar la confiabilidad y reducir los costos para los consumidores\u00bb, apunt\u00f3 Kreil Rivera.<\/p>\n<p>\u00abAdem\u00e1s, la visi\u00f3n de Ortiz contribuy\u00f3 a la conversi\u00f3n de San Juan 5 y 6 a gas natural, resolvi\u00f3 asuntos de energ\u00eda renovable, llevando a la mayor\u00eda de los proyectos activos un paso adelante para convertirse en una realidad para los puertorrique\u00f1os. Asimismo, implement\u00f3 una disciplina de procesos de compra m\u00e1s transparente en la AEE\u00bb, agreg\u00f3.<\/p>\n<p>Ortiz, por su parte, asegur\u00f3 que su salida ocurre en un momento \u00abapropiado\u00bb, a pesar de los asuntos pendientes que quedan sin resolver como el pol\u00e9mico acuerdo de restructuraci\u00f3n de la deuda de la AEE.<\/p>\n<p>\u201cCuando originalmente me pidieron que asumiera el cargo de Director Ejecutivo de la AEE, me compromet\u00ed a dos a\u00f1os de servicio; han transcurrido 24 meses. Mi renuncia surge en un momento apropiado en la transformaci\u00f3n de la AEE a la moderna compa\u00f1\u00eda el\u00e9ctrica que todos los puertorrique\u00f1os merecen. A lo largo de estos dos a\u00f1os, en la AEE nos comprometimos con la fiabilidad, la sostenibilidad, la asequibilidad y el desarrollo econ\u00f3mico, seg\u00fan previsto en la Ley 17 de 2018\u201d, dijo Ortiz.<\/p>\n<p>El presidente de la Junta de Gobierno dese\u00f3 \u00e9xito a Ortiz, cuya salida se anticipaba desde el viernes pasado, en su pr\u00f3xima encomienda.<\/p>\n<p>\u201cAunque en ocasiones Ortiz y la Junta pudimos haber tenido puntos de vista diferentes, siempre pudimos encontrar una manera de trabajar juntos de manera positiva por el mejor inter\u00e9s de nuestros ciudadanos. Todos los miembros de nuestra Junta le desean el mayor \u00e9xito en su futuro personal y profesional\u201d, concluy\u00f3 Kreil Rivera.<\/p>\n<p>El viernes, V\u00e1zquez Garced se\u00f1al\u00f3 que estaba insatisfecha con la respuesta de la corporaci\u00f3n p\u00fablica, que confront\u00f3 problemas para atender las aver\u00edas que las copiosas lluvias y vientos de la tormenta tropical causaron al sistema el\u00e9ctrica.<\/p>\n<p>Cuatro d\u00edas antes, un apag\u00f3n afect\u00f3 a alrededor de 400,000 clientes de al corporaci\u00f3n p\u00fablica, un evento que Ortiz catalog\u00f3 como un acto de terrorismo interno y que todav\u00eda no ha sido explicado con detenimiento.<\/p><div class=\"notic-content-middle\" id=\"notic-632988062\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese Noticel_JUL-AGO 970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30144630\/Acodese-Noticel_JUL-AGO-970x250-1.png\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30144630\/Acodese-Noticel_JUL-AGO-970x250-1.png 970w, https:\/\/cdn.noticel.com\/2026\/07\/30144630\/Acodese-Noticel_JUL-AGO-970x250-1-300x77.png 300w, https:\/\/cdn.noticel.com\/2026\/07\/30144630\/Acodese-Noticel_JUL-AGO-970x250-1-768x198.png 768w, https:\/\/cdn.noticel.com\/2026\/07\/30144630\/Acodese-Noticel_JUL-AGO-970x250-1-18x5.png 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Pero el presidente de la Uni\u00f3n de Trabajadores de la Industria El\u00e9ctrica y Riego (Utier), \u00c1ngel Figueroa Jaramillo, refut\u00f3 esas expresiones al indicar que el apag\u00f3n masivo obedeci\u00f3 a un problema de falta de mantenimiento en las l\u00edneas de distribuci\u00f3n.<\/p>\n<p>Figueroa Jaramillo explic\u00f3 que la falta de desganche o de poda de ramas de \u00e1rboles que se enredan en el tendido el\u00e9ctrico.<\/p>\n<p>Dos d\u00edas despu\u00e9s de ese apag\u00f3n, las r\u00e1fagas y las lluvias de Isa\u00edas dejaron a 402,000 abonados sin energ\u00eda el\u00e9ctrica. El pasado viernes, todav\u00eda quedaban 135,000 abonados sin servicio el\u00e9ctrico. Ese d\u00eda la mandataria lanz\u00f3 su advertencia.<\/p>\n<p>Entonces, ayer en la tarde colg\u00f3 en su cuenta de Twitter una fotograf\u00eda junto a presidente de la Junta de Directores de la AEE, Ralph Kreil Rivera con el siguiente calce: \u00abconvoqu\u00e9 al presidente de la Junta de la @aeeonline, Ralph Kreil Rivera, ante las incidencias y la cuestionada respuesta en el manejo de la tormenta Isa\u00edas, de modo que se tomen todas las medidas necesarias sobre el personal directivo y las acciones a eventos futuros\u00bb.<\/p>\n<p><strong id=\"strong-9152dbd0fc6e948a8fc638aec614c34c\">Gobernadora ten\u00eda la petici\u00f3n de renuncia sobre la mesa<\/strong><\/p>\n<p>Minutos despu\u00e9s de la renuncia, V\u00e1zquez Garced dijo que la renuncia era producto de una petici\u00f3n que le realiz\u00f3 a la Junta de Gobierno de la AEE.<\/p>\n<p>\u00abEstamos empezando la temporada pico de huracanes, necesito una respuesta certera y eficiente. Si el ingeniero (Ortiz) renunci\u00f3, respondi\u00f3 una petici\u00f3n de investigaci\u00f3n que le hice al presidente de la Junta de Gobierno, para que se analizara c\u00f3mo hab\u00eda sido la respuesta\u00bb, expres\u00f3 la mandataria en conferencia de prensa.<\/p>\n<p>Sin embargo, la mandataria luego indic\u00f3 que todav\u00eda no hab\u00eda recibido el informe que encamin\u00f3 al presidente de la Junta de Gobierno. \u00abEl resultado de la investigaci\u00f3n no me ha llegado. Entendemos que debemos recibir esa informaci\u00f3n tan pronto est\u00e9 disponible\u00bb.<\/p>\n<p>Al increparle directamente si fue ella quien solicit\u00f3 la renuncia del ingeniero, en la reuni\u00f3n con el presidente de la Junta de Gobierno, la gobernadora confirm\u00f3 que lo hab\u00eda planteado.<\/p>\n<p>\u00abYo hab\u00eda hecho unas expresiones unos d\u00edas antes con relaci\u00f3n a la insatisfacci\u00f3n de la respuesta, as\u00ed que al ver que pasaban los d\u00edas y todav\u00eda los ciudadanos todav\u00eda no ten\u00edan energ\u00eda el\u00e9ctrica y que eso afectaba el suministro de agua, me re\u00fano con el presidente de la junta y le pido, yo necesito las explicaciones y si hay que tomar determinaciones con relaci\u00f3n a la direcci\u00f3n y a todos los directores y qui\u00e9n manej\u00f3 o c\u00f3mo se manej\u00f3 la respuesta, pues hay que tomar las decisiones\u00bb, dijo la gobernadora.<\/p>\n<p>Ante preguntas de los medios, V\u00e1zquez Garced indic\u00f3 que todav\u00eda no tiene una recomendaci\u00f3n sobre qui\u00e9n podr\u00eda ser el sucesor de Ortiz.<\/p>\n<p><strong id=\"strong-75f048cbfeb2dd72a9ad74439d96f4a0\">Vea el comunicado oprimiendo aqu\u00ed o accede a continuaci\u00f3n: <\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Es efectiva el 5 de agosto. La Junta de Gobierno de la Autoridad de Energ\u00eda El\u00e9ctrica (AEE) recibi\u00f3 hoy la renuncia del ingeniero Jos\u00e9 Ortiz V\u00e1zquez como director ejecutivo de la corporaci\u00f3n p\u00fablica. La renuncia ser\u00e1 efectiva el mi\u00e9rcoles, 5 de agosto de 2020. Ortiz present\u00f3 su renuncia un d\u00eda despu\u00e9s de que la gobernadora [&hellip;]<\/p>","protected":false},"author":0,"featured_media":475798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-148915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/148915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=148915"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/148915\/revisions"}],"predecessor-version":[{"id":475802,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/148915\/revisions\/475802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/475798"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=148915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=148915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=148915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}