{"id":148730,"date":"2020-07-29T12:54:00","date_gmt":"2020-07-29T16:54:00","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/policiacas\/20200729\/declaraciones-de-jovenes-involucrados-en-fraude-a-pua-apuntan-a-otros-30-estudiantes-del-colegio-san\/"},"modified":"2025-07-16T21:48:54","modified_gmt":"2025-07-16T21:48:54","slug":"declaraciones-de-jovenes-involucrados-en-fraude-a-pua-apuntan-a-otros-30-estudiantes-del-colegio-san","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20200729\/declaraciones-de-jovenes-involucrados-en-fraude-a-pua-apuntan-a-otros-30-estudiantes-del-colegio-san\/","title":{"rendered":"Declaraciones de j\u00f3venes involucrados en fraude a PUA apuntan a otros 30 estudiantes del Colegio San"},"content":{"rendered":"<h3>El FBI ya fue informado del asunto.<\/h3>\n<p>El Negociado de la Polic\u00eda de Puerto Rico recibi\u00f3 declaraciones de dos de los j\u00f3venes involucrados en el fraude a la Asistencia por Desempleo Pand\u00e9mico (PUA, por sus siglas en ingl\u00e9s), que apuntan a que son cerca de 30 los estudiantes del Colegio San Ignacio de Loyola,  involucrados en el alegado esquema.<\/p>\n<p>Jos\u00e9 Ayala, director de la Divisi\u00f3n de Robos a Bancos del Negociado de la Polic\u00eda de Puerto Rico, afirm\u00f3 en entrevista con el programa &#8216;Sin Tapujos&#8217;, que emite la emisora radial WIAC 740, que fueron alertados de las movidas por dos madres que encontraron cheques de PUA a nombre de sus hijos.<\/p>\n<p>\u00abLo que tenemos es dos cheques, por la cantidad de $7,458 y otro cheque por la cantidad de $6,126, referentes a cheques de PUA, que fueron entregados por las madres\u00bb, sentenci\u00f3 Ayala al mismo tiempo que dijo que hoy mismo estar\u00e1n requiriendo al referido colegio, una lista de sus alumnos.<\/p>\n<p><strong id=\"strong-fe829bd404ae7b39c808c30d396a74c6\">Mira tambi\u00e9n<\/strong>: <a href=\"https:\/\/noticel.com\/en\/la-calle\/20200728\/estudiantes-de-colegio-en-san-juan-usaban-direcciones-de-adultos-mayores-para-recibir-cheques-de-pua\/\" id=\"link-19cae51f8076cbdcbd0a310041602e1f\">Estudiantes de colegio en San Juan usaban direcciones de adultos mayores para recibir cheques de PUA<\/a><\/p>\n<p>Con esa movida buscan comparar los nombres de los alumnos, con las listas del Departamento del Trabajo.<\/p>\n<p>\u00abBueno, seg\u00fan las versiones, la versi\u00f3n que ellos (los dos j\u00f3venes involucrados) dieron al Departamento del Trabajo, hay m\u00e1s estudiantes que solicitaron este dinero del PUA. (Los otros estudiantes que solicitaron son) del mismo Colegio, eso es correcto. Por eso estamos solicitando la lista de estudiantes del Colegio, para compararla con la lista del Departamento del Trabajo&#8230;Ya tenemos asignado un agente de ac\u00e1 de la oficina ( a la investigaci\u00f3n)\u00bb, expuso tambi\u00e9n el uniformado.<\/p>\n<p>Al momento, la informaci\u00f3n que ha trascendido aborda un esquema de fraude a PUA, donde estudiantes del Colegio San Ignacio utilizaron sus direcciones, y otros casos las direcciones de adultos mayores, para cobrar cheques de desempleo por miles de d\u00f3lares. Algunos reportes indican que padres de alumnos, adultos comerciantes, ayudaron a los estudiantes en el esquema.<\/p>\n<p>\u00abEso tambi\u00e9n&#8230; Eso es parte de la investigaci\u00f3n\u00bb, sostuvo al respecto Ayala cuando le cuestionaron sobre la implicaci\u00f3n de adultos.<\/p>\n<p>Mediante declaraciones escritas colgadas en sus redes sociales ayer, el Colegio San Ignacio reaccion\u00f3 al asunto alegando que de ser cierto el asunto, \u00abse tomar\u00e1n las m\u00e1s serias sanciones disciplinarias\u00bb.<\/p>\n<p>\u00abEl Colegio San Ignacio tiene cero tolerancia con la comisi\u00f3n de cualquier delito y, de resultar ciertas las alegaciones, se tomar\u00e1n las m\u00e1s serias sanciones disciplinarias\u00bb, expresaron en una publicaci\u00f3n en Twitter.<\/p>\n<p><strong id=\"strong-0372f6f4b6110ef674ba55d82c51ec35\">Lee tambi\u00e9n<\/strong>: <a href=\"https:\/\/noticel.com\/en\/la-calle\/policiacas\/20200727\/otro-arrestado-por-fraude-a-los-fondos-pua\/\" id=\"link-3ba14342e3de521e1e9019fd8734c488\">Otro arrestado por fraude a los fondos PUA<\/a><\/p>\n<p>\u00abHacemos un llamado a la prudencia para que se lleven a cabo las investigaciones que correspondan\u00bb, finalizaron.<\/p>\n<p>El Negociado Federal de Investigaciones Criminales (FBI), ya est\u00e1 al tanto de la pesquisa.<\/p>\n<p>\u00abEste caso se est\u00e1 trabajando con el Departamento de Justicia. Con el fiscal Manuel Santiago Quiles, de la Fiscal\u00eda de San Juan y en el d\u00eda de hoy entiendo que va a entrar tambi\u00e9n la Divisi\u00f3n de Delitos Econ\u00f3micos del Departamento de Justicia. Se ha consultado tambi\u00e9n a nivel federal, con el FBI\u00bb, finaliz\u00f3 diciendo el agente.<\/p>","protected":false},"excerpt":{"rendered":"<p>El FBI ya fue informado del asunto. El Negociado de la Polic\u00eda de Puerto Rico recibi\u00f3 declaraciones de dos de los j\u00f3venes involucrados en el fraude a la Asistencia por Desempleo Pand\u00e9mico (PUA, por sus siglas en ingl\u00e9s), que apuntan a que son cerca de 30 los estudiantes del Colegio San Ignacio de Loyola, involucrados [&hellip;]<\/p>","protected":false},"author":0,"featured_media":476739,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15],"tags":[],"class_list":["post-148730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/148730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=148730"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/148730\/revisions"}],"predecessor-version":[{"id":476741,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/148730\/revisions\/476741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/476739"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=148730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=148730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=148730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}