{"id":148632,"date":"2020-07-26T18:11:00","date_gmt":"2020-07-26T22:11:00","guid":{"rendered":"https:\/\/www.noticel.com\/galeria\/20200726\/turistas-siguen-sin-mascarillas-y-en-la-playa-aun-con-advertencia-de-policia\/"},"modified":"2025-07-16T22:00:11","modified_gmt":"2025-07-16T22:00:11","slug":"turistas-y-locales-siguen-sin-mascarillas-y-en-la-playa-aun-con-advertencia-de-policia","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/videos-y-fotos\/fotos\/20200726\/turistas-y-locales-siguen-sin-mascarillas-y-en-la-playa-aun-con-advertencia-de-policia\/","title":{"rendered":"Turistas y locales siguen sin mascarillas y en la playa a\u00fan con advertencia de polic\u00eda"},"content":{"rendered":"<h3>La gran mayor\u00eda de los turistas caminan por las calles sin mascarilla y disfrutan de las playas, seg\u00fan se pudo observar en un recorrido realizado por NotiCel.<\/h3>\n<p>Tras enmiendas a la Orden Ejecutiva 2020-054, la gobernadora Wanda V\u00e1zquez Garced anunci\u00f3, que hoy domingo, 26 de julio, los negocios permanecer\u00e1n cerrados, excepto farmacias, supermercados, gasolineras y restaurantes, y se prohibir\u00e1 la venta de bebidas alcoh\u00f3licas.<\/p><div class=\"notic-content-middle\" id=\"notic-295327066\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>La gran mayor\u00eda de los turistas caminan por las calles sin mascarilla y disfrutan de las playas, seg\u00fan se pudo observar en un recorrido realizado por NotiCel. Tras enmiendas a la Orden Ejecutiva 2020-054, la gobernadora Wanda V\u00e1zquez Garced anunci\u00f3, que hoy domingo, 26 de julio, los negocios permanecer\u00e1n cerrados, excepto farmacias, supermercados, gasolineras y [&hellip;]<\/p>","protected":false},"author":19,"featured_media":477144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[60],"tags":[],"class_list":["post-148632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotos"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/148632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=148632"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/148632\/revisions"}],"predecessor-version":[{"id":477215,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/148632\/revisions\/477215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/477144"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=148632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=148632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=148632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}