{"id":147375,"date":"2020-06-23T08:39:00","date_gmt":"2020-06-23T12:39:00","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/20200623\/a-punto-de-racionamiento-el-area-metropolitana\/"},"modified":"2025-07-17T00:04:23","modified_gmt":"2025-07-17T00:04:23","slug":"a-punto-de-racionamiento-el-area-metropolitana","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20200623\/a-punto-de-racionamiento-el-area-metropolitana\/","title":{"rendered":"A punto de racionamiento el \u00e1rea metropolitana"},"content":{"rendered":"<h3>El embalse Carra\u00edzo ya est\u00e1 cerca del nivel de control<\/h3>\n<p>La Autoridad de Acueductos y Alcantarillados (AAA) tomar\u00e1 esta semana la determinaci\u00f3n de un posible racionamiento del servicio a los clientes que se sirven del embalse Carra\u00edzo, que cada d\u00eda disminuye su nivel debido a la sequ\u00eda.<\/p>\n<p>En la ma\u00f1ana del martes, Carra\u00edzo presenta un nivel de 37.75 metros y se mantiene en el nivel de ajustes operacionales, pero llegando al nivel de control, que es de 37.20 metros.<\/p>\n<p>\u201cContin\u00faa bajando Carra\u00edzo. No nos ha beneficiado las pocas lluvias\u201d, dijo la presidenta de la AAA, Doriel Pag\u00e1n, en entrevista radial (WKAQ). \u201cEl consumo sigue pr\u00e1cticamente igual y la nube del Sahara no ayuda a las lluvias. El embalse Carra\u00edzo es el de mayor preocupaci\u00f3n\u201d, afirm\u00f3.<\/p>\n<p>\u201cEstamos haciendo todo lo posible para evitar el racionamiento. Tenemos hoy la reuni\u00f3n interagencial para actualizar informaci\u00f3n y pron\u00f3stico y estaremos tomando determinaciones. Algunos ajustes que hemos hecho no han resultado tan efectivos como pens\u00e1bamos\u201d, reconoci\u00f3 la funcionaria.<\/p>\n<p>Puerto Rico ha enfrentado un evento de sequ\u00eda progresivo que la semana pasada aument\u00f3 a 25% el nivel severo.<\/p>\n<p>180 mil clientes de la zona metropolitana se afectar\u00edan con un plan de racionamiento en Carra\u00edzo.<\/p>\n<p>https:\/\/twitter.com\/ACUEDUCTOSPR\/status\/1275384902729502720https:\/\/twitter.com\/ACUEDUCTOSPR\/status\/1275386113117630464<\/p>","protected":false},"excerpt":{"rendered":"<p>El embalse Carra\u00edzo ya est\u00e1 cerca del nivel de control La Autoridad de Acueductos y Alcantarillados (AAA) tomar\u00e1 esta semana la determinaci\u00f3n de un posible racionamiento del servicio a los clientes que se sirven del embalse Carra\u00edzo, que cada d\u00eda disminuye su nivel debido a la sequ\u00eda. En la ma\u00f1ana del martes, Carra\u00edzo presenta un [&hellip;]<\/p>","protected":false},"author":0,"featured_media":482839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-147375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/147375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=147375"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/147375\/revisions"}],"predecessor-version":[{"id":482841,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/147375\/revisions\/482841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/482839"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=147375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=147375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=147375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}