{"id":145613,"date":"2012-08-09T22:12:00","date_gmt":"2012-08-10T02:12:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/20120809\/se-quejan-de\/"},"modified":"2025-07-17T01:28:46","modified_gmt":"2025-07-17T01:28:46","slug":"se-quejan-de","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20120809\/se-quejan-de\/","title":{"rendered":"Se quejan de"},"content":{"rendered":"<p>Indignados por lo que han llamado una relaci\u00f3n de ?panismo? entre la Agencia Federal de Protecci\u00f3n Ambiental de los Estados Unidos (EPA) y los desarrolladores de una planta incineradora de basura en Arecibo, opositores del proyecto denunciaron hoy una serie de correos electr\u00f3nicos que evidencian que la EPA ha gu\u00edado a la compa\u00f1\u00eda para que tramite los permisos de la incineradora efectivamente.<\/p>\n<p>&#8216;Lo que m\u00e1s nos sorprende es que hemos podido corroborar en la correspondencia que revisamos de los propios expedientes, que funcionarios de la EPA llevaron de la mano a los proponentes para que finalmente pudieran completar su solicitud de permiso, asunto que no es permitido por ley&#8217;, se\u00f1al\u00f3 el ingeniero y Planificador, profesor Iv\u00e1n El\u00edas.<\/p>\n<p>El\u00edas tambi\u00e9n se\u00f1al\u00f3 que lo que m\u00e1s llama la atenci\u00f3n es que la correspondencia entre Steven Riva, director de la divisi\u00f3n de permisos de aire de la EPA en Puerto Rico, y Mark Green, vice presidente de Energy Answers (nombre de la compa\u00f1\u00eda desarrolladora), est\u00e1 clasificada &#8216;confidencial&#8217;.<\/p>\n<p>&#8216;Nos parece que es necesario paralizar los tr\u00e1mites y evaluaci\u00f3n de los permisos para Energy Answer y se proceda a revisar el expediente para fijar responsabilidades para aquellos funcionarios de EPA que han incurrido en violaciones, no permitidas por las leyes federales&#8217;, exhort\u00f3 el presidente del Comit\u00e9 de Salud Ambiental del Colegio de M\u00e9dicos Cirujanos de Puerto Rico, Angel Bobby Gonz\u00e1lez.<\/p>\n<p>De este mismo modo, los miembros de las organizaciones que combaten la construcci\u00f3n de la planta indicaron que enviaron una carta a la Administradora de la EPA, Lisa Jackson, haciendo estos se\u00f1alamientos y solicitando que se les ofrezca un taller a la comunidad de Arecibo sobre el permiso de aire antes de volver a celebrar <a href=\"http:\/\/www.miprv.com\/epa-realizara-cinco-vistas-publicas-en-arecibo-sobre-la-incineradora-energy-answers\/\">vistas p\u00fablicas los d\u00edas 25, 26 y 27 de agosto en el Club de Leones de Arecibo.<\/a><\/p>\n<p>Para ver la correspondencia presione <a href=\"http:\/\/www.arecibo.inter.edu\/reserva\/epa\/epa.htm\">aqu\u00ed<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Indignados por lo que han llamado una relaci\u00f3n de ?panismo? entre la Agencia Federal de Protecci\u00f3n Ambiental de los Estados Unidos (EPA) y los desarrolladores de una planta incineradora de basura en Arecibo, opositores del proyecto denunciaron hoy una serie de correos electr\u00f3nicos que evidencian que la EPA ha gu\u00edado a la compa\u00f1\u00eda para que [&hellip;]<\/p>","protected":false},"author":0,"featured_media":488165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-145613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=145613"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145613\/revisions"}],"predecessor-version":[{"id":488167,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145613\/revisions\/488167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/488165"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=145613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=145613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=145613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}