{"id":145530,"date":"2012-08-30T21:44:00","date_gmt":"2012-08-31T01:44:00","guid":{"rendered":"https:\/\/www.noticel.com\/vida\/20120830\/jon-lee-anderson-testigo-de-la-guerra-que-quiere-incomodar\/"},"modified":"2025-07-17T01:32:38","modified_gmt":"2025-07-17T01:32:38","slug":"jon-lee-anderson-testigo-de-la-guerra-que-quiere-incomodar","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20120830\/jon-lee-anderson-testigo-de-la-guerra-que-quiere-incomodar\/","title":{"rendered":"Jon Lee Anderson: testigo de la guerra que quiere &#8216;incomodar&#8217;"},"content":{"rendered":"<p>Las bombas hab\u00edan aplastado la ciudad siria de Alepo. Por doquier se alzaban penachos de carros en llamas y civiles continuaban un \u00e9xodo a Turqu\u00eda y otros pa\u00edses vecinos, escapando de la guerra civil. Era finales de julio pasado cuando el periodista y escritor Jon Lee Anderson entr\u00f3 a esas calles y pasillos laber\u00ednticos para entender y contar el conflicto en su \u00faltima cr\u00f3nica de la revista The New Yorker.<\/p>\n<p>El pr\u00f3ximo martes 4 de septiembre a las 6:30 p.m. hablar\u00e1 en el Museo de Arte de Puerto Rico, sobre literatura, cine y lo que ha visto en sus coberturas como corresponsal de guerra internacional.<\/p>\n<p>En Alepo, los rebeldes resist\u00edan el bombardeo de la fuerza a\u00e9rea y el asedio de francotiradores apostados sobre minaretes de las mezquitas, mientras esperaban el contrataque del ej\u00e9rcito del presidente Bashar Al Assad. As\u00ed estaban las cosas cuando Jon Lee fue a una casa en la que hab\u00eda ocurrido algo grave.<\/p>\n<p>Hombres llegaron en un veh\u00edculo y bajaron el cuerpo de un joven insurgente. Lo dejaron en el suelo del jard\u00edn y sus parientes se acercaron a ver el cuerpo vejado por los paramilitares afines al r\u00e9gimen. El cad\u00e1ver mostraba una tortura descomunal, al punto de que Jon Lee tuvo que contener la descripci\u00f3n en su cr\u00f3nica. La carga emotiva hab\u00eda sido tan fuerte que \u00e9l, reportero de guerra desde su juventud, hab\u00eda tenido que salir a tomar aire. Fue entonces cuando lleg\u00f3 F\u00e1tima, la madre del joven.<\/p><div class=\"notic-content-middle\" id=\"notic-1552456285\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;Ella grit\u00f3 algo que no entend\u00ed pero era un quejido. Alguien le dijo que pensara en Mahoma, y ella solo gritaba que no hay ning\u00fan Mahoma, que no pod\u00eda tenerlo en cuenta. Eso es una blasfemia en el mundo musulm\u00e1n, pero todos lo entendieron porque sab\u00edan que era el desgarre m\u00e1s duro que puede vivir una madre&#8217;, cuenta el reportero estadounidense, desde el otro lado de la pantalla, en una entrevista por Skype desde Ciudad M\u00e9xico.<\/p>\n<p>Hace una pausa y se lleva los pu\u00f1os a la boca. Le duele contar lo que ha visto. &#8216;F\u00e1tima se sent\u00f3 en el suelo, puso la cabeza de su hijo en la falda y entr\u00f3 en un trance. Era un trance de dolor. La guerra se trata de matar y morir. Tuve que contar la historia de F\u00e1tima porque no hab\u00eda una escena m\u00e1s elocuente&#8217;.<\/p>\n<p>Para el resto de la entrevista, vea el <a href=\"http:\/\/cpipr.org\/historias\/48-actualidad-en-portada\/365-jon-lee-anderson-testigo-de-la-guerra-que-quiere-qincomodarq.html\" target=\"_blank\">Centro de Periodismo Investigativo<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Las bombas hab\u00edan aplastado la ciudad siria de Alepo. Por doquier se alzaban penachos de carros en llamas y civiles continuaban un \u00e9xodo a Turqu\u00eda y otros pa\u00edses vecinos, escapando de la guerra civil. Era finales de julio pasado cuando el periodista y escritor Jon Lee Anderson entr\u00f3 a esas calles y pasillos laber\u00ednticos para [&hellip;]<\/p>","protected":false},"author":0,"featured_media":488437,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-145530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=145530"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145530\/revisions"}],"predecessor-version":[{"id":488439,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145530\/revisions\/488439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/488437"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=145530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=145530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=145530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}