{"id":145330,"date":"2012-10-17T06:25:23","date_gmt":"2012-10-17T10:25:23","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/20121017\/lluvias-se-concentraran-en-el-oeste\/"},"modified":"2025-07-17T01:45:08","modified_gmt":"2025-07-17T01:45:08","slug":"lluvias-se-concentraran-en-el-oeste","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20121017\/lluvias-se-concentraran-en-el-oeste\/","title":{"rendered":"Lluvias se concentrar\u00e1n en el oeste"},"content":{"rendered":"<p>Los vientos alisios del sureste retornar\u00e1n gradualmente al \u00e1rea el miercoles por lo que se anticipan aguaceros y tronadas sobre secciones del norte central y oeste de la Isla y a traves de porciones de la zona metropolitana de San Juan, seg\u00fan el Servicio Nacional de Meteorolog\u00eda (SNM).<\/p>\n<p>Una onda tropical deber\u00e1 alcanzar las islas locales para el jueves trayendo aguaceros y tronadas adicionales.<\/p>\n<p>.Alguna mejor\u00eda leve es anticipada para el viernes al moverse la onda tropical al Caribe central y aire m\u00e1s seco entre al \u00e1rea local.<\/p><div class=\"notic-content-middle\" id=\"notic-954785376\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>A trav\u00e9s de las aguas costeras el oleaje ser\u00e1 de cinco pies o menos y los vientos de 18 nudos o menos el mi\u00e9rcoles.<\/p>\n<p>Entretanto, el SNM indic\u00f3 que aguaceros dispersos y tronadas aisladas afectaron las aguas costeras del Atl\u00e1ntico y del Caribe.<\/p>\n<p>Algunos aguaceros alcanzaron la costa sur y sureste dejando solo acumulaciones leves.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los vientos alisios del sureste retornar\u00e1n gradualmente al \u00e1rea el miercoles por lo que se anticipan aguaceros y tronadas sobre secciones del norte central y oeste de la Isla y a traves de porciones de la zona metropolitana de San Juan, seg\u00fan el Servicio Nacional de Meteorolog\u00eda (SNM). Una onda tropical deber\u00e1 alcanzar las islas [&hellip;]<\/p>","protected":false},"author":0,"featured_media":489207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-145330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=145330"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145330\/revisions"}],"predecessor-version":[{"id":489209,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145330\/revisions\/489209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/489207"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=145330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=145330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=145330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}