{"id":145126,"date":"2012-12-04T13:24:11","date_gmt":"2012-12-04T17:24:11","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/20121204\/companeros-de-jose-recuerdan-la-vida-del-publicista\/"},"modified":"2025-07-17T02:00:20","modified_gmt":"2025-07-17T02:00:20","slug":"companeros-de-jose-recuerdan-la-vida-del-publicista","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20121204\/companeros-de-jose-recuerdan-la-vida-del-publicista\/","title":{"rendered":"Compa\u00f1eros de Jos\u00e9 recuerdan la vida del publicista"},"content":{"rendered":"<p>El publicista Jose Enrique G\u00f3mez Salad\u00edn fue un excelente trabajador que, pese al &#8216;stress&#8217; que conlleva el trabajo publicitario, nunca dej\u00f3 de sonre\u00edr.<\/p>\n<p>Por ello, sus compa\u00f1eros de trabajo lo recordar\u00e1n siempre por lo que fue en vida y no por su lamentable y horrendo deceso, destac\u00f3 en entrevista con NotiCel, Marina Puello, gerente de operaciones de Mediapol, donde el publicista laboraba desde el 2011.<\/p>\n<p>&#8216;Jos\u00e9 era un ser humano maravilloso. Nosotros queremos, en el \u00e1mbito del trabajo aqu\u00ed ahora mismo, recordarlo en vida, no queremos recordar las circunstancias de su muerte porque es muy triste para nosotros&#8217;, dijo Puello a NotiCel, quien fungi\u00f3 como portavoz de sus colegas porque los dem\u00e1s empleados todav\u00eda no pueden hablar de su p\u00e9rdida, ni digerir lo que ha pasado.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"607741105\" embed-content-groupid=\"593030475\" embed-content-id=\"607741105\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2012\/12\/04\/Marina_Puello_Mediapol_8075966_ver1.0_320_240.jpg\"\/><\/p>\n<p><em>Marina Puello, Gerente de Operaciones de Mediapol. (Roso Sabalones\/NotiCel)<\/em><\/p>\n<p>&#8216;Cooperador, uno de los t\u00edpicos empleados que nunca tiene un no en su boca, con una sonrisa constante. El mejor ejemplo de lo que Jos\u00e9 era, si lo miramos con el coraz\u00f3n, vemos la foto con su carita, su sonrisa, eso era Jos\u00e9: bonach\u00f3n, buen compa\u00f1ero. Tiene la cualidad de que, a pesar de estar un trabajo con tanto estr\u00e9s como trabajamos en publicidad, Jos\u00e9 nunca, nunca tuvo un coraje, ni un mal humor, ni un exabrupto para nada. Siempre respondi\u00f3 de una manera bien positiva y cooperadora y conciliatoria, m\u00e1s que nada, en el ambiente del trabajo&#8217;, destac\u00f3.<\/p>\n<p>Puello indic\u00f3 que G\u00f3mez Salad\u00edn, quien se desempe\u00f1aba como comprador de medios en la agencia desde abril de 2011, colabor\u00f3 en &#8216;campa\u00f1as importantes&#8217; de pol\u00edtica, de restaurantes de comida r\u00e1pida y de telecomunicaciones.<\/p>\n<p>La \u00faltima vez que compartieron con \u00e9l fue durante el evento de una presentaci\u00f3n de medios en el hotel La Concha, en el Condado.<\/p>\n<p>&#8216;Yo no estaba, pero hab\u00edan como 10 o 15 personas de Medianet y Mediapol all\u00ed compartiendo con \u00e9l. A las 10:30 u 11:00 de la noche se fueron despidiendo como siempre \u2018mira nos vamos yendo&#8217; y Jos\u00e9 se fue. Lo \u00faltimo que sabemos es que \u00e9l habl\u00f3 con su esposa y le dijo \u2018mira voy de camino&#8217; y ah\u00ed no supimos m\u00e1s nada hasta el otro d\u00eda cuando llegamos a la oficina que nos fuimos enterando poco a poco que Jos\u00e9 no lleg\u00f3 a su casa&#8217;, record\u00f3.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"607741120\" embed-content-groupid=\"593030475\" embed-content-id=\"607741120\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2012\/12\/04\/escritorio_publicista_8075967_ver1.0_320_240.jpg\"\/><\/p>\n<p><em>El escritorio de G\u00f3mez Salad\u00edn permanec\u00eda intacto en la oficina de Mediapol. (Roso Sabalones\/NotiCel)<\/em><\/p>\n<p>En un intento por localizarlo y ayudar a las autoridades en su b\u00fasqueda, la empresa en conjunto con otras compa\u00f1\u00edas public\u00f3 gigantescas vallas publicitarias, una muy destacada se despleg\u00f3 en la Avenida Baldorioty de Castro, as\u00ed como en los anuncios verticales del principal centro comercial. Puello agradeci\u00f3 ese gran respaldo.<\/p>\n<p>&#8216;M\u00e1s que nada, agradecemos a todos los medios el apoyo que nos dieron incondicional en esto. Fue una iniciativa de todos, todo fue llegando y se fue haciendo cada vez m\u00e1s grande y m\u00e1s grande&#8217;, destac\u00f3 sobre la inusual campa\u00f1a.<\/p>\n<p>Los empleados estuvieron reunidos en la ma\u00f1ana hablando y recordando a G\u00f3mez Salad\u00edn.<\/p><div class=\"notic-content-middle\" id=\"notic-3754051935\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;El tributo m\u00e1s grande que podemos hacerle a Jos\u00e9 es recordarlo como vivi\u00f3, no como muri\u00f3&#8217;, puntualiz\u00f3.<\/p>\n<p>Indic\u00f3 que est\u00e1n en comunicaci\u00f3n constante con la familia del occiso y que estar\u00e1n disponibles para servirles y ayudarle en todo lo que necesiten en este momento de dolor.<\/p>\n<p><strong>Marchar\u00e1n por el publicista<\/strong><\/p>\n<p>Mientras, familiares y amigos anunciaron que el 15 de diciembre celebrar\u00e1n una marcha llamada &#8216;Los buenos somos m\u00e1s&#8217; que partir\u00e1 a las 3:00 de la tarde desde el Colegio San Jos\u00e9 de Caguas hasta la catedral de la ciudad criolla.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"607741135\" embed-content-groupid=\"593030475\" embed-content-id=\"607741135\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2012\/12\/04\/los_buenos_somos_mas_8075968_ver1.0_320_240.jpg\"\/><\/p>\n<p><strong>*Mira tambi\u00e9n:<\/strong><\/p>\n<p><strong><a href=\"https:\/\/noticel.com\/en\/noticia\/134137\/dificil-para-la-familia-identificar-cadaver-del-publicista.html\/\">&#8216;Dif\u00edcil para la familia identificar cad\u00e1ver del publicista&#8217;<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/noticel.com\/en\/noticia\/134136\/federales-asumen-jurisdiccion-en-caso-del-publicista.html\/\">&#8216;Federales asumen jurisdicci\u00f3n en caso del publicista&#8217;<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/noticel.com\/en\/noticia\/134129\/familia-del-publicista-ha-sido-bien-dificil.html\/\">&#8216;Familia del publicista: Ha sido bien dif\u00edcil&#8217;<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/noticel.com\/en\/noticia\/134134\/copur-lamenta-muerte-de-publicista.html\/\">&#8216;COPUR lamenta muerte de publicista&#8217;<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/noticel.com\/en\/noticia\/134106\/policia-entrevista-sospechosos-de-asesinar-publicista.html\/\">&#8216;Polic\u00eda entrevista sospechosos de asesinar publicista&#8217;<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/noticel.com\/en\/noticia\/134120\/dolor-en-canabon-esto-nos-puede-pasar-a-cualquiera.html\/\">&#8216;Dolor en Ca\u00f1ab\u00f3n: Esto nos puede pasar a cualquiera&#8217;<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>El publicista Jose Enrique G\u00f3mez Salad\u00edn fue un excelente trabajador que, pese al &#8216;stress&#8217; que conlleva el trabajo publicitario, nunca dej\u00f3 de sonre\u00edr. Por ello, sus compa\u00f1eros de trabajo lo recordar\u00e1n siempre por lo que fue en vida y no por su lamentable y horrendo deceso, destac\u00f3 en entrevista con NotiCel, Marina Puello, gerente de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":490027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-145126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=145126"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145126\/revisions"}],"predecessor-version":[{"id":490029,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/145126\/revisions\/490029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/490027"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=145126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=145126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=145126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}