{"id":144757,"date":"2013-03-13T17:47:03","date_gmt":"2013-03-13T21:47:03","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/20130313\/tres-tipos-ahi-compiten-con-piti-pa-reirse\/"},"modified":"2025-07-17T02:27:43","modified_gmt":"2025-07-17T02:27:43","slug":"tres-tipos-ahi-compiten-con-piti-pa-reirse","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20130313\/tres-tipos-ahi-compiten-con-piti-pa-reirse\/","title":{"rendered":"Tres tipos ah\u00ed compiten con Piti (pa&#8217; re\u00edrse)"},"content":{"rendered":"<p>San Juan, Puerto Rico &#8211; Fuentes informaron a El \u00d1ame que tres tipos ah\u00ed se creen que el Partido Popular Democr\u00e1tico los considera seriamente para el esca\u00f1o vacante en la C\u00e1mara de Representantes al cual tambien aspira la ex primera dama, Luisa &#8216;Piti&#8217; G\u00e1ndara, esposa del exgobernador y m\u00e1rtir del partido, An\u00edbal Acevedo Vil\u00e1. Los tres tipos esos parece que no saben c\u00f3mo es que brega la dedocracia en el Partido Popular Democr\u00e1tico.<\/p>\n<p>&#8216;En verdad no entiendo el cinismo de este peri\u00f3dico. El partido est\u00e1 tomando en serio a todos los candidatos!&#8217;, asegur\u00f3 uno de los tipos esos para la risa de muchos. &#8216;Y total, An\u00edbal no quiere a Piti en la pol\u00edtica. Ella misma lo dijo los otros d\u00edas! En verdad no s\u00e9 quien est\u00e1 asesorando a esa mujer, deslig\u00e1ndose de los deseos de su esposo&#8217;, se pregunt\u00f3 el tipo ese sin darse cuenta que cualquier estratega pol\u00edtico competente le aconsejar\u00eda precisamente ese tipo de expresi\u00f3n a una candidata como ella para que salga de la sombra de su esposo. Ese mismo esposo, dicho sea de paso, es posiblemente uno de los m\u00e1ximos estrategas pol\u00edticos de su generaci\u00f3n.<\/p><div class=\"notic-content-middle\" id=\"notic-1251597966\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Tratamos de conseguir expresiones de otros miembros del Partido Popular Democr\u00e1tico para ver si era factible que se le diera el esca\u00f1o a uno de los tres tipos eso en vez de a una figura que tendr\u00eda garantizada esa silla de por vida, pero solo escuchamos carcajadas.<\/p>\n<p>Para m\u00e1s humor, vea <a href=\"http:\/\/elname.com\">El\u00d1ame.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>San Juan, Puerto Rico &#8211; Fuentes informaron a El \u00d1ame que tres tipos ah\u00ed se creen que el Partido Popular Democr\u00e1tico los considera seriamente para el esca\u00f1o vacante en la C\u00e1mara de Representantes al cual tambien aspira la ex primera dama, Luisa &#8216;Piti&#8217; G\u00e1ndara, esposa del exgobernador y m\u00e1rtir del partido, An\u00edbal Acevedo Vil\u00e1. Los [&hellip;]<\/p>","protected":false},"author":0,"featured_media":491673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-144757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/144757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=144757"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/144757\/revisions"}],"predecessor-version":[{"id":491675,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/144757\/revisions\/491675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/491673"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=144757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=144757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=144757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}