{"id":143387,"date":"2013-12-30T12:03:52","date_gmt":"2013-12-30T16:03:52","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/20131230\/aprobacion-unanime-de-jose-aponte-como-secretario-de-la-palma\/"},"modified":"2025-08-22T08:43:31","modified_gmt":"2025-08-22T08:43:31","slug":"aprobacion-unanime-de-jose-aponte-como-secretario-de-la-palma","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20131230\/aprobacion-unanime-de-jose-aponte-como-secretario-de-la-palma\/","title":{"rendered":"Aprobaci\u00f3n un\u00e1nime de Jos\u00e9 Aponte como secretario de la Palma"},"content":{"rendered":"<p>El presidente del Partido Nuevo Progresista (PNP), Pedro Pierluisi, anunci\u00f3 el lunes que el directorio de la colectividad aprob\u00f3 un\u00e1nimemente la designaci\u00f3n del represente Jose Aponte Hern\u00e1ndez como secretario general de la colectividad. La certificaci\u00f3n de Aponte ocurri\u00f3 mediante el mecanismo de referendum, sometido a los miembros del directorio.<\/p>\n<p>&#8216;Me complace que el directorio haya recibido la designaci\u00f3n de Jos\u00e9 Aponte con tanto entusiasmo. Este a\u00f1o que acaba de concluir fue un a\u00f1o de mucho trabajo, de mucha reflexi\u00f3n y de much\u00edsimo trabajo de base. Escuchamos de nuestra gente las razones por las que entendieron que el partido no prevaleci\u00f3 en las pasadas elecciones y comenzamos a fortalecer la colectividad con la creaci\u00f3n del Instituto de Pol\u00edtica P\u00fablica Luis A. Ferr\u00e9 y las actividades de Misi\u00f3n Estadista&#8217;, dijo Pierluisi en un comunicado de prensa.<\/p>\n<p>El l\u00edder del PNP destac\u00f3 que el trabajo realizado este a\u00f1o sent\u00f3 las bases para un 2014 en el que continuar\u00e1 la reorganizaci\u00f3n de la colectividad, sin abandonar el trabajo de fiscalizaci\u00f3n y de preparaci\u00f3n para el triunfo en el 2016.<\/p><div class=\"notic-content-middle\" id=\"notic-743695547\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;La administraci\u00f3n del Partido Popular ha provocado un a\u00f1o devastador para Puerto Rico. Estamos atravesando la crisis econ\u00f3mica m\u00e1s importante de tiempos recientes y en el PNP no s\u00f3lo hemos estado presente para indicarles cu\u00e1les han sido sus errores. Tambi\u00e9n hemos estado presentes para presentarles ideas y soluciones que no han sido acogidas. Jos\u00e9 Aponte tiene una encomienda clara de parte de nuestro partido y es continuar organizando la estructura para que a partir del 2016 Puerto Rico vuelva a contar con un partido en el poder que cumpla con las necesidades del pueblo&#8217;, expres\u00f3 Pierluisi.<\/p>\n<p>Aponte, quien fue presidente de la C\u00e1mara de Representantes de Puerto Rico, dijo, por su parte, que durante el 2014 &#8216;el PNP se reorganizar\u00e1, se fortalecer\u00e1 y se posicionar\u00e1 como la alternativa que Puerto Rico necesita para volver al progreso&#8217;.<\/p>\n<p>Aponte agradeci\u00f3 la aprobaci\u00f3n de su designaci\u00f3n y asegur\u00f3 continuar\u00e1 trabajando por el progreso y la estadidad.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente del Partido Nuevo Progresista (PNP), Pedro Pierluisi, anunci\u00f3 el lunes que el directorio de la colectividad aprob\u00f3 un\u00e1nimemente la designaci\u00f3n del represente Jose Aponte Hern\u00e1ndez como secretario general de la colectividad. La certificaci\u00f3n de Aponte ocurri\u00f3 mediante el mecanismo de referendum, sometido a los miembros del directorio. &#8216;Me complace que el directorio haya [&hellip;]<\/p>","protected":false},"author":0,"featured_media":888903,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-143387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/143387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=143387"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/143387\/revisions"}],"predecessor-version":[{"id":888937,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/143387\/revisions\/888937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/888903"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=143387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=143387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=143387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}