{"id":143028,"date":"2014-03-18T22:23:44","date_gmt":"2014-03-19T02:23:44","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/20140318\/fideicomiso-de-ciencia-por-primera-vez-se-trabaja-la-economia-del-conocim\/"},"modified":"2025-08-21T04:10:04","modified_gmt":"2025-08-21T04:10:04","slug":"fideicomiso-de-ciencia-por-primera-vez-se-trabaja-la-economia-del-conocim","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20140318\/fideicomiso-de-ciencia-por-primera-vez-se-trabaja-la-economia-del-conocim\/","title":{"rendered":"Fideicomiso de Ciencia: &#8216;Por primera vez se trabaja la econom\u00eda del conocim"},"content":{"rendered":"<p>El director del Fideicomiso de Ciencia, Tecnolog\u00eda e Investigaci\u00f3n, Iv\u00e1n R\u00edos Mena, asegur\u00f3 que prepara varias estrategias para ayudar a la comunidad cient\u00edfica de Puerto Rico a traves de programas de subvenciones a infraestructura, recursos humanos y procesos de comercializaci\u00f3n de resultados de investigaci\u00f3n.<\/p>\n<p>Seg\u00fan R\u00edos Mena, ser\u00eda la primera vez en la historia de la comunidad cient\u00edfica de Puerto Rico que se har\u00eda un esfuerzo oficial y concertado para facilitarle a los investigadores tener la infraestructura f\u00edsica y humana para poder llevar a cabo sus investigaciones y poder comercializar su tecnolog\u00eda si ese es el paso que desearan tomar.<\/p>\n<p>&#8216;El rol del Fideicomiso en el ecosistema cient\u00edfico es que se multipliquen historias de \u00e9xito. Tenemos que retomar esa iniciativa de proveerles a la comunidad cient\u00edfica de Puerto Rico instrumentos estandarizados, transparentes, que tengan consistencia y con criterios claves.&#8217;<\/p>\n<p>Otro objeto del Fideicomiso es ayudar al proceso de transferencia de tecnolog\u00eda o comercializaci\u00f3n. &#8216;Estamos trabajando con una serie de comit\u00e9s de asesores para ir implantado una serie de acciones e insertarnos en el proceso de comercializaci\u00f3n de ciencia y tecnolog\u00eda en Puerto Rico&#8217;.<\/p>\n<p>Al pregunt\u00e1rsele sobre los planes para el \u00e1rea Oeste, regi\u00f3n que en alg\u00fan momento se design\u00f3 como punta de lanza del desarrollo de una econom\u00eda del conocimiento por ser sede de la mayor\u00eda de las actividades investigativas cient\u00edficas en el sector acad\u00e9mico de la Isla, R\u00edos Mena adelant\u00f3 que el Fideicomiso trabaja en alianzas con distintos entes gubernamentales para retomarlos.<\/p>\n<p>&#8216;El BDTC (Bioprocess Development and Training Complex) es una de las misiones primordiales del Fideicomiso en su ley y en sus tareas. Se est\u00e1 trabajando un plan estrat\u00e9gico para el BDTC en alianza con la Universidad de Puerto Rico, la Compa\u00f1\u00eda de Fomento Industrial y el Fideicomiso para afinar esa estrategia y que refleje los cambios en el ecosistema, recobrando su valor e importancia en el Oeste y a nivel nacional.&#8217; El plan visualiza que el BDTC sea un taller para estudiantes universitarios y tambi\u00e9n sea una incubaci\u00f3n de empresas. En la actualidad el BDTC, administrado por la organizaci\u00f3n sin fines de lucro PRTEC, alberga varias empresas incipientes de ciencia y tecnolog\u00eda. Una de ellas es Protein Dynamic Solutions de la doctora Belinda Pastrana quien recientemente anunci\u00f3 un descubrimiento importante con aplicaci\u00f3n en la lucha contra el c\u00e1ncer. Otro inquilino del BDTC es CDI Laboratories, que ha logrado exportar una subsidiaria de sus operaciones a Baltimore, Maryland.<\/p>\n<p>&#8216;Estamos tratando de verlo (al BDTC) no como una cosa aislada o independiente, sino incorporarlos como una pieza angular importante,&#8217; se\u00f1al\u00f3 R\u00edos Mena. &#8216;Se est\u00e1 desarrollando una oficina de transferencia de tecnolog\u00eda en la Universidad de Puerto Rico, liderada por el vicepresidente de la Universidad de Puerto Rico Jos\u00e9 Lasalde y dirigida por el licenciado Salvatore Casale. Es un paso muy grande que se est\u00e1 desarrollando por primera vez en la historia de Puerto Rico&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-2400424294\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Reiter\u00f3 la importancia de fomentar la investigaci\u00f3n en tecnolog\u00eda y ciencia a niveles de escuela elemental y superior para que los estudiantes reconozcan estos campos como opci\u00f3n a la hora de escoger carreras profesionales.<\/p>\n<p>El efecto de estas estrategias, por la naturaleza de la actividad econ\u00f3mica, educativa y social que impactan, tendr\u00eda resultados a mediano y largo plazo en la econom\u00eda general.<\/p>\n<p>&#8216;Independientemente de la particularidad o individualidad de los proyectos, estas iniciativas tienen que darse ya porque al tener su efecto a mediano y largo plazo, en 10 a\u00f1os no se ha visto el resultado. A corto plazo, lo que el Fideicomiso ha estado apoyando es el sector de tecnolog\u00edas de informaci\u00f3n. Abrimos el espacio a esos eventos y proyectos, programas de incubaci\u00f3n y aceleraci\u00f3n. Esas son las iniciativas que tiene impacto a corto plazo por ser baratos de desarrollar y f\u00e1cil de determinar si son comercialmente desarrollables,&#8217; indic\u00f3 R\u00edos Mena.<\/p>\n<p>&#8216;Se est\u00e1 materializando lo que se ha hablado hace a\u00f1os de la econom\u00eda del conocimiento,&#8217; opin\u00f3.<\/p>\n<p><em>*Parte de una serie de art\u00edculos sobre la investigaci\u00f3n cient\u00edfica en las universidades.<\/em><\/p>\n<p>Vea tambi\u00e9n:<\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/noticia\/157468\/universidades-en-puerto-rico-no-llevan-la-investigacion-a-la-practica.html\/\">Universidades en Puerto Rico no llevan la investigaci\u00f3n a la pr\u00e1ctica<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El director del Fideicomiso de Ciencia, Tecnolog\u00eda e Investigaci\u00f3n, Iv\u00e1n R\u00edos Mena, asegur\u00f3 que prepara varias estrategias para ayudar a la comunidad cient\u00edfica de Puerto Rico a traves de programas de subvenciones a infraestructura, recursos humanos y procesos de comercializaci\u00f3n de resultados de investigaci\u00f3n. Seg\u00fan R\u00edos Mena, ser\u00eda la primera vez en la historia de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":883477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-143028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/143028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=143028"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/143028\/revisions"}],"predecessor-version":[{"id":883481,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/143028\/revisions\/883481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/883477"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=143028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=143028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=143028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}