{"id":142838,"date":"2014-04-20T18:33:17","date_gmt":"2014-04-20T22:33:17","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/20140420\/decenas-marchan-para-modernizar-a-pr-liberando-la-marihuana-galeria-y-vi\/"},"modified":"2025-08-19T18:10:21","modified_gmt":"2025-08-19T18:10:21","slug":"decenas-marchan-para-modernizar-a-pr-liberando-la-marihuana-galeria-y-vi","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20140420\/decenas-marchan-para-modernizar-a-pr-liberando-la-marihuana-galeria-y-vi\/","title":{"rendered":"Decenas marchan para modernizar a PR &#8216;liberando&#8217; la marihuana (galer\u00eda y vi"},"content":{"rendered":"<p>Al son de una batucada, entre 80 y 100 defensores de la marihuana marcharon el Domingo de Resurrecci\u00f3n desde el Parque Luis Mu\u00f1oz Rivera hasta las escalinatas de lado norte del Capitolio para abogar a favor de la descriminalizaci\u00f3n del uso de esta droga.<\/p>\n<p>&#8216;Free Juana, Free Juana&#8217;, cantaron como consigna a su llegada al Capitolio como parte del ejercicio para crear conciencia de los beneficios del cannabis y terminar con el estereotipo de que todos los que abogan por la legalizaci\u00f3n de la marihuana son unos drogadictos.<\/p>\n<p>La marcha, organizada por el grupo Free Juana y otras organizaciones, coincidi\u00f3 con la celebraci\u00f3n mundial el domingo de la planta cannabis globalmente como parte del Rally 4\/20.<\/p>\n<p>El grupo abog\u00f3 porque se apruebe la medida senatorial que impone multas en vez de c\u00e1rcel para las personas convictas de poseer cantidades peque\u00f1as de cannabis aunque la mayor\u00eda de los entrevistados por NotiCel entienden que no debe de haber ni multas ni c\u00e1rcel para este tipo de caso.<\/p>\n<p>El proyecto del Senado 517, el cual est\u00e1 siendo evaluado en la C\u00e1mara, dispone que la posesi\u00f3n de 14 gramos o menos de marihuana ser\u00e1 sancionable con una multa que no podr\u00e1 exceder de los $100. Cuando la violaci\u00f3n a la Ley de Sustancias Controladas se repite en un t\u00e9rmino de tres a\u00f1os, la multa por una segunda infracci\u00f3n ser\u00e1 de $200, y $300 por la tercera violaci\u00f3n o subsiguientes. El dinero de la multa ser\u00e1 dirigido a los gastos de tratamiento y la multa puede ser sustituida por la prestaci\u00f3n de servicios comunitarios. Los manifestantes tambi\u00e9n apoyaron una medida cameral que permite el uso medicinal del cannabis.<\/p>\n<p>Las razones para abogar por la legalizaci\u00f3n de la marihuana fueron desde que podr\u00eda producir empleos hasta ayudar a pacientes enfermos con c\u00e1ncer y otras enfermedades as\u00ed como aliviar las tensiones mediante su uso recreacional.<\/p>\n<p>La licenciada Shadiff M. Repullo, una de las portavoces del movimiento Free Juana, insisti\u00f3 en que Puerto Rico debe de seguir los movimientos internacionales que ha recomendado que se despenalice el uso de la marihuana y eliminar tanto multas como penalidades por poseer marihuana.<\/p>\n<p>&#8216;No tenemos problema con que se regulen las cantidades&#8217;, dijo Repullo.<\/p>\n<p>Dijo que entiende que la C\u00e1mara aprobar\u00e1 la medida para despenalizar el uso de peque\u00f1as cantidades de la marihuana pero NotiCel supo que la medida no tiene los votos.<\/p>\n<p>Seg\u00fan algunos de los manifestantes, adem\u00e1s de los beneficios para los usuarios, el pa\u00eds en s\u00ed ganar\u00eda y no solo en t\u00e9rminos econ\u00f3micos, sino de una manera social ya que en los pa\u00edses donde se ha legalizado la marihuana, no ha aumentado ni el crimen ni el consumo. Adem\u00e1s, ha bajado el uso de otras sustancias fuertes como la hero\u00edna.<\/p><div class=\"notic-content-middle\" id=\"notic-1281635323\"><div class=\"notic-adlabel\">Advertisements<\/div><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/15123809\/JP-Monopoly-Launch-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/15123809\/JP-Monopoly-Launch-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/15123809\/JP-Monopoly-Launch-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/15123809\/JP-Monopoly-Launch-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/15123809\/JP-Monopoly-Launch-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/div>\n<p>Al preguntar sobre estudios recientes que muestran cambios en el cerebro debido al uso recreacional de la marihuana y un aumento en el nivel de psicosis, Eduardo Urayo Gonz\u00e1lez, quien tiene una microempresa de edici\u00f3n y grabaci\u00f3n, dijo que todo en exceso hace da\u00f1o y que el alcohol y las pastillas causan trastornos.<\/p>\n<p>Urayo Gonz\u00e1lez dijo la organizaci\u00f3n no aboga porque menores usen la droga y que su mensaje est\u00e1 dirigido a los adultos. &#8216;Nadie debe ir preso tres, cuatro o cinco a\u00f1os por usar marihuana\u2026El gobierno debe enfocarse en otros cr\u00edmenes m\u00e1s importantes&#8217;, dijo.<\/p>\n<p>El senador Ram\u00f3n Luis Nieves dijo que esperaba que la actividad cree conciencia y que sirva para &#8216;alejarnos del moralismo sin fundamento\u2026Nadie debe ir preso por posesi\u00f3n simple&#8217;.<\/p>\n<p>Aunque el proyecto original radicado por el Senado despenalizaba el uso de hasta una onza de marihuana, los senadores lo modificaron para imponer multas. Nieves entiende que eso era lo que pol\u00edticamente se pod\u00eda aprobar.<\/p>\n<p>De paso, Nieves pidi\u00f3 a los miembros del Partido Nuevo Progresista que son Dem\u00f3cratas que apoyen la medida porque la despenalizaci\u00f3n de la marihuana es parte de la plataforma de ese partido.<\/p>\n<p>Durante la actividad, el activista gay, Pedro Julio Serrano, dijo que hay que romper el prejuicio que existe contra los usuarios de la marihuana y pidi\u00f3 a las personas que &#8216;salieran del closet&#8217; en torno al tema de usar la marihuana.<\/p>\n<p>Serrano compar\u00f3 la lucha por los derechos de la comunidad homosexual con la de aquellos que abogan por la despenalizaci\u00f3n de la marihuana.<\/p>\n<p>&#8216;Debemos hacer un llamado para obligar a promover la igualdad y a descriminalizar aquello que no se debe penalizar&#8217;, dijo. &#8216;Nadie debe estar en la c\u00e1rcel por cargar 10 onzas. Es absurdo&#8217;.<\/p>\n<p>Mientras el grupo caminaba a lo largo de la avenida hacia el Capitolio, bocinazos en aparente apoyo a la causa se escucharon constantemente. Los caminantes portaban pancartas con mensajes a favor de la marihuana.<\/p>\n<p>Rafael Torruella, director de Descriminalizacion.org, anuncio a los manifestantes que llenen una petici\u00f3n para envi\u00e1rsela a los legisladores para que se aprueben los los proyectos de descriminalizaci\u00f3n de la marihuana y la medida que legaliza el uso medicinal de la marihuana,el proyecto de la C\u00e1mara de Representantes 1363.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"610545245\" embed-content-groupid=\"593030471\" embed-content-id=\"610545246\" embed-content-index=\"0\" embed-content-type=\"GALLERY\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2014\/04\/20\/605fbaa78b35941001dd725811bb5f10_8168281_ver1.0_320_240.jpg\"\/>\u00a0\u00a0\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Al son de una batucada, entre 80 y 100 defensores de la marihuana marcharon el Domingo de Resurrecci\u00f3n desde el Parque Luis Mu\u00f1oz Rivera hasta las escalinatas de lado norte del Capitolio para abogar a favor de la descriminalizaci\u00f3n del uso de esta droga. &#8216;Free Juana, Free Juana&#8217;, cantaron como consigna a su llegada al [&hellip;]<\/p>","protected":false},"author":0,"featured_media":875242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-142838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=142838"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142838\/revisions"}],"predecessor-version":[{"id":875563,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142838\/revisions\/875563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/875242"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=142838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=142838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=142838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}