{"id":142622,"date":"2014-05-30T19:26:50","date_gmt":"2014-05-30T23:26:50","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/20140530\/la-escuela-es-el-medio-para-el-desarrollo-comunitario\/"},"modified":"2025-08-20T00:54:12","modified_gmt":"2025-08-20T00:54:12","slug":"la-escuela-es-el-medio-para-el-desarrollo-comunitario","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20140530\/la-escuela-es-el-medio-para-el-desarrollo-comunitario\/","title":{"rendered":"&#8216;La escuela es el medio para el desarrollo comunitario&#8217;"},"content":{"rendered":"<p>De ni\u00f1a, Gloria Bonilla Santiago nunca se enter\u00f3 que era pobre. Hija de inmigrantes puertorrique\u00f1os que trabajaban en los campos agr\u00edcolas de Estados Unidos, comprendi\u00f3 a temprana edad que so\u00f1ar era el \u00fanico lujo que ten\u00eda. As\u00ed que no escatim\u00f3 en sue\u00f1os. Se form\u00f3 como doctora en Sociolog\u00eda logrando superar mediante la educaci\u00f3n no s\u00f3lo su propia pobreza, sino la de todo un barrio, en lo que ha denominado &#8216;El milagro de la Calle Cooper&#8217;.<\/p>\n<p>En incontables ocasiones ha mencionado que el milagro que ocurri\u00f3 en Camden, una de las ciudades m\u00e1s violentas y pobres de Estados Unidos, tom\u00f3 la forma de los ni\u00f1os y ni\u00f1as, que como ella estaban destinados a ser un estorbo para el Estado, una cifra m\u00e1s de delincuencia juvenil o de desempleo. Nadie esperaba nada de ellos. Mas la escuela charter que fund\u00f3 Bonilla Santiago en esa ciudad, est\u00e1 logrando graduar, desde hace diez a\u00f1os, el 100% de su matr\u00edcula, y una admisi\u00f3n de 100% en las mejores universidades del pa\u00eds.<\/p>\n<p>El trabajo que realiza en una zona donde todas las semanas ocurre un asesinato, le ha permitido reafirmar que la educaci\u00f3n es la \u00fanica herramienta real para lograr una transformaci\u00f3n social. &#8216;La escuela es el medio para el desarrollo comunitario&#8217;, mencion\u00f3 convencida.<\/p>\n<p>De visita en Puerto Rico para presentar el libro &#8216;El milagro de la calle Cooper&#8217;, habl\u00f3 con NotiCelsobre el sistema de educaci\u00f3n en la isla y la visi\u00f3n que tiene de c\u00f3mo debe ser un modelo educativo que lleve a la transformaci\u00f3n de las estad\u00edsticas actuales de violencia, desempleo y pobreza.<\/p>\n<p><strong>NC: Si estuviera en sus manos, c\u00f3mo empezar\u00eda a transformar la educaci\u00f3n p\u00fablica del Pa\u00eds?<\/strong><\/p>\n<p>GBS: &#8216;Empezar\u00eda por entender las necesidades de los ni\u00f1os. Los ni\u00f1os deben ser la prioridad. Hay que hacer di\u00e1logos con el Gobernador y el Secretario de Educaci\u00f3n para replicar los modelos que han sido exitosos. Trabajar con los alcaldes y los municipios locales, que tienen m\u00e1s oportunidad de ser innovadores. Hay que descentralizar el sistema educacional. La transformaci\u00f3n del sistema tiene que venir de abajo hacia arriba. Los padres son cr\u00edticos en este proceso. Los maestros hay que tratarlos como profesionales, que se sientan con el empoderamiento necesario para transformar la educaci\u00f3n porque tenemos muchos maestros a los que no se les dan los recursos que necesitan&#8217;.<\/p>\n<p>&#8216;Veo posibilidades de que se hagan Juntas de los edificios escolares locales para que manejen los fondos y las prioridades. Hay mucho dinero federal. Es cuesti\u00f3n de c\u00f3mo se utiliza para que llegue a los ni\u00f1os. Eso es cr\u00edtico. Si no, nunca va a haber cambios de excelencia para que la escuela llegue a ser el sitio donde las personas van a buscar soluciones&#8217;.<\/p>\n<p><strong>NC: Qu\u00e9 fue lo primero que hizo con el presupuesto de $1.5 millones, en Camden?<\/strong><\/p>\n<p>GBS: &#8216;Ese presupuesto me dio la oportunidad de crear un plan acad\u00e9mico y preparar a los l\u00edderes escolares con una ideolog\u00eda innovadora, enfocada en las ciencias, las matem\u00e1ticas y la tecnolog\u00eda. Invertimos suficiente tiempo en la planificaci\u00f3n, el dise\u00f1o del programa, los cursos y los horarios. Est\u00e1bamos anticipando que ten\u00eda que ser un modelo diferente que proveyera las necesidades a los ni\u00f1os pobres&#8217;.<\/p>\n<p>&#8216;Quince a\u00f1os despu\u00e9s la excelencia se da porque creamos un modelo que respond\u00eda a las necesidades de esos ni\u00f1os con un curr\u00edculo agresivo, con las clases m\u00e1s fuertes en la ma\u00f1ana, y las clases de arte y m\u00fasica en la tarde. Con programas de tutor\u00eda y deportes. En las noches, programas para los padres porque muchos de ellos no sab\u00edan c\u00f3mo ayudar a sus hijos, no sab\u00edan leer. (Quer\u00edamos) que los padres se sintieranenamorados de las escuelas. Creamos una cultura y un clima donde el amor es bien importante, que los ni\u00f1os sientan que se les quiere y se les cuida.<\/p>\n<p><strong>NC: Ha hablado sobre la necesidad de que se le pague bien a los maestros. Qu\u00e9 piensa sobre la disminuci\u00f3n de beneficios al Sistema de Retiro de los maestros, que est\u00e1 en pugna ahora mismo?<\/strong><\/p>\n<p>GBS: &#8216;No s\u00e9 mucho acerca de la situaci\u00f3n del SRM. Pero lo que s\u00ed te puedo decir es que a los maestros se les debe pagar bien. Y si tienen un sistema de retiro estatal, hay que hacer paquetes de incentivos atractivos. Despu\u00e9s de los ni\u00f1os, los maestros son el elemento m\u00e1s importante que tiene la escuela&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-1849654925\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Como sociedad tenemos que atender las necesidades de los maestros. No s\u00f3lo la preparaci\u00f3n, sino c\u00f3mo se les cuida y como se les recompensa. Ense\u00f1ar es una profesi\u00f3n noble, pero tambi\u00e9n es una de las profesiones m\u00e1s dif\u00edciles. Es parte de lo que estamos hablando a nivel nacional: como creamos unas compensaciones mucho m\u00e1s vigorosas para atraer a los maestros? Tienen que tener todo disponible para que puedan ense\u00f1ar, libros recursos, y buenos salarios&#8217;.<\/p>\n<p><strong>NC: Mucho se teme la privatizaci\u00f3nde la educaci\u00f3n por parte de un sector quepiensa que el Gobierno no puede manejar las escuelas adecuadamente. Usted que rechaz\u00f3 una oferta de trabajo como Secretaria de Educaci\u00f3n en Camden, piensa que es posible una transformaci\u00f3n desde el Gobierno?<\/strong><\/p>\n<p>GBS: &#8216;No creo en la privatizaci\u00f3n. Mi filosof\u00eda es que el sistema p\u00fablico fue creado para que cada ni\u00f1o tenga una educaci\u00f3n superior. Ese es un deber civil. El problema es el modelo. Mientras todo ha evolucionado, las escuelas no han cambiado su modelo. Yo lo que hice fue cambiar ese modelo. El Gobierno tiene que ser parte de la soluci\u00f3n, pero no la soluci\u00f3n total. Tienen que descentralizar. Tenemos que hacer colaboraciones con los municipios y las universidades. Hay que empezar de forma peque\u00f1a con programas pilotos para que la gente se sienta c\u00f3moda. Si empujas un cambio al que la gente no est\u00e1 listo, no va a pasar nada. Pero se me hace que la gente de Puerto Rico est\u00e1 lista para un cambio. Ellos quieren mejores condiciones y mejores escuelas&#8217;.<\/p>\n<p>&#8216;Las compa\u00f1\u00edas privadas que est\u00e1n haciendo dinero en los hombros de los ni\u00f1os pobres, no sirven. No creo que los medios privados entienden lo que es la educaci\u00f3n p\u00fablica. Los ni\u00f1os no son una franquicia. Son seres humanos que necesitan que se les ense\u00f1e a leer, pensar y escribir. Pero no hemos hecho nuestro trabajo. Cuando hagamos a nuestros l\u00edderes escolares y l\u00edderes pol\u00edticos responsables de la educaci\u00f3n, se reinvente lo que sirve, se paguen mejores salarios a los maestros &#8211; que hasta a la gente sin bachillerato se les paga m\u00e1s-, veremos la transformaci\u00f3n. Tenemos que recompensar a los maestros y cambiar los curr\u00edculos&#8217;.<\/p>\n<p><strong>NC: Por qu\u00e9 su propuesta de una escuela Charter provoc\u00f3 problemas con los sindicatos en su momento?<\/strong><\/p>\n<p>GBS: &#8216;Las uniones no estaban de acuerdo con esto. Es lo que ocurre cuando creas cambio. Pero yo vengo del mundo de los sindicatos. Mi padre fue obrero. Entiendo que el movimiento laboral tiene gran importancia, pero ellos son parte de la soluci\u00f3n o parte del problema. Ellos tienen que resolver el problema de que a los maestros se les pague mejor. Lleg\u00f3 un momento en que tuvimos que colaborar porque los maestros empezaron a decir que quer\u00edan que se les pagara mejor y comenzamos a negociar&#8217;.<\/p>\n<p><strong>NC: Por qu\u00e9 crear todo un conglomerado integrado de cl\u00ednicas m\u00e9dicas, legales, centro de consejer\u00eda, educaci\u00f3n continua, y academia para los padres? Cree que sin ello el sistema LEAP no hubiese funcionado?<\/strong><\/p>\n<p>GBS: &#8216;Si no hubi\u00e9ramos tenido eso, hubi\u00e9ramos sido otra escuela en fracaso. Cuando tienes problemas bien grandes tienes que tratarlos agresivamente con nuevas soluciones. No podemos tratar el c\u00e1ncer con la misma medicina de hace a\u00f1os. En los salones de clases hay ni\u00f1os con muchas necesidades, y tenemos que buscar soluciones a esos problemas. En estos barrios los ni\u00f1os vienen traumatizados. Puerto Rico no es diferente. Aqu\u00ed hay barrios que sufren las consecuencias de las drogas y la violencia. Esos son traumas que hay que tratar porque esos ni\u00f1os crecen con conflictos, con miedo. Un sufrimiento de p\u00e9rdida puede ser el final de un ni\u00f1o literalmente. Hay que proveerles las herramientas a esos ni\u00f1os para que se sientan sanos&#8217;.<\/p>\n<p><strong>NC: En tiempos de estrechez, no han menguado los endosos ni la financiaci\u00f3n privada para Leap. C\u00f3mo lo logra?<\/strong><\/p>\n<p>GBS: &#8216;Lo bonito del proyecto es que recibimos menos dinero por estudiante que el distrito escolar. El distrito escolar recibo $28,000 por estudiante. Yo recibo $15,000. No es una cuesti\u00f3n de dinero. El dinero que recibimos se usa de forma creativa, con m\u00e1s responsabilidad (accountability) y con el enfoque en los ni\u00f1os. La parte estructural nuestra es muy peque\u00f1a. Solo tres encargados. Camden tiene 200 administradores. Nosotros no creemos en eso. La administraci\u00f3n no puede seguir cogiendo el dinero para los puestos administrativos. No se necesita tanto dinero para correr un distrito escolar. La administraci\u00f3n tiene que ser bien <em>lean<\/em>, bien peque\u00f1a. El dinero tiene que ir para las escuelas y los recursos&#8217;.<\/p>\n<p><strong>NC: En un tono m\u00e1s personal, no puedo dejar pasar la oportunidad de preguntarle c\u00f3mo se mantuvo firme en todo este proceso, desde su propia emigraci\u00f3n hasta la creaci\u00f3n de Leap y ahora que enfrenta acusaciones de malversaci\u00f3n de fondos.<\/strong><\/p>\n<p>GBS: &#8216;Siempre va a haber gente que te va acusar y tratar de tumbar. Pero es importante mantenerse con una agenda muy clara y la agenda m\u00eda eran los ni\u00f1os. Yo ya ten\u00eda un puesto de catedr\u00e1tica as\u00ed que no ten\u00eda necesidad de hacer esto. Lo hice porque quer\u00eda salvar esos ni\u00f1os. Tienes que estar preparado. Es parte del liderato y de cualquier proceso de cambio. Te van a tratar de tumbar, pero no podemos vivir con miedo. Siempre me manten\u00eda con mucha esperanza, creo mucho en Dios y tengo un compromiso social, que he asumido como una lucha de los que tienen contra los que no tienen&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>De ni\u00f1a, Gloria Bonilla Santiago nunca se enter\u00f3 que era pobre. Hija de inmigrantes puertorrique\u00f1os que trabajaban en los campos agr\u00edcolas de Estados Unidos, comprendi\u00f3 a temprana edad que so\u00f1ar era el \u00fanico lujo que ten\u00eda. As\u00ed que no escatim\u00f3 en sue\u00f1os. Se form\u00f3 como doctora en Sociolog\u00eda logrando superar mediante la educaci\u00f3n no s\u00f3lo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":878355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-142622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=142622"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142622\/revisions"}],"predecessor-version":[{"id":878381,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142622\/revisions\/878381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/878355"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=142622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=142622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=142622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}