{"id":142467,"date":"2014-06-30T09:38:09","date_gmt":"2014-06-30T13:38:09","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20140630\/partido-comunista-chino-continua-con-su-purga-de-exlideres-corruptos\/"},"modified":"2025-08-19T16:40:20","modified_gmt":"2025-08-19T16:40:20","slug":"partido-comunista-chino-continua-con-su-purga-de-exlideres-corruptos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20140630\/partido-comunista-chino-continua-con-su-purga-de-exlideres-corruptos\/","title":{"rendered":"Partido Comunista chino contin\u00faa con su &#8216;purga&#8217; de exl\u00edderes corruptos"},"content":{"rendered":"<p>El Partido Comunista de China (PCCh), formaci\u00f3n pol\u00edtica que ma\u00f1ana celebra el 93 aniversario de su creaci\u00f3n, anunci\u00f3 hoy la expulsi\u00f3n de cuatro importantes ex altos cargos del regimen acusados de corrupci\u00f3n, lo que deja finalmente estos casos en manos de la justicia, tras meses de especulaciones.<\/p>\n<p>El Comit\u00e9 Central del PCCh, formado por los principales l\u00edderes del r\u00e9gimen y encabezado por el presidente Xi Jinping, confirm\u00f3 la expulsi\u00f3n de Xu Caihou (n\u00famero dos de la jerarqu\u00eda militar hasta 2012), Jiang Jiemin (antiguo responsable de gesti\u00f3n de las empresas estatales), Li Dongsheng (viceministro de Seguridad P\u00fablica) y Wang Yongchun, quien fue ejecutivo de la mayor petrolera estatal, CNPC.<\/p>\n<p>Sus nombres sonaban desde hace meses, a\u00f1os incluso, como protagonistas de investigaciones del comit\u00e9 anticorrupci\u00f3n del PCCh, aunque se ignoraba que el partido gobernante desde 1949 iba a sancionarlos simult\u00e1neamente y en la simb\u00f3lica v\u00edspera de su principal efem\u00e9ride.<\/p>\n<p>Destaca especialmente la expulsi\u00f3n de Xu, exgeneral del Ej\u00e9rcito de Liberaci\u00f3n Popular y antiguo vicepresidente de la Comisi\u00f3n Militar Central, ya que confirma el mayor esc\u00e1ndalo de corrupci\u00f3n en las Fuerzas Armadas chinas, una instituci\u00f3n que por su enorme poder sobre el PCCh se consideraba &#8216;blindada&#8217; ante los \u00f3rganos antifraude.<\/p>\n<p>&#8216;Las investigaciones hallaron que Xu se aprovech\u00f3 de su cargo para ayudar en el ascenso de algunas personas, y acept\u00f3 sobornos personalmente o a trav\u00e9s de familiares&#8217;, indic\u00f3 hoy en un comunicado el Comit\u00e9 Central.<\/p>\n<p>Durante meses los analistas barajaron la posibilidad de que el caso de Xu fuera &#8216;sobrese\u00eddo&#8217; por el r\u00e9gimen comunista, debido a su delicado estado de salud, pero tambi\u00e9n a la enorme influencia del Ej\u00e9rcito de Liberaci\u00f3n Popular en la pol\u00edtica china.<\/p>\n<p>Tambi\u00e9n hoy se anunci\u00f3, aunque desde una instancia inferior al Comit\u00e9 Central, el departamento de disciplina del PCCh, la destituci\u00f3n del hasta ahora secretario del partido en Cant\u00f3n, Wan Qingliang, tambi\u00e9n acusado de pr\u00e1cticas corruptas durante su gobierno en la cuarta mayor ciudad del pa\u00eds.<\/p>\n<p>La &#8216;purga&#8217; que hoy ha confirmado la formaci\u00f3n pol\u00edtica da gran publicidad a la campa\u00f1a contra el fraude en las instituciones p\u00fablicas que el presidente Xi ha convertido en una de las principales banderas de su mandato, iniciado en marzo de 2013.<\/p>\n<p>Sin embargo, en los anuncios de hoy sigue habiendo un gran ausente, el exministro de Seguridad P\u00fablica y antiguo miembro del Comit\u00e9 Permanente del PCCh Zhou Yongkang, sobre el que tambi\u00e9n hay sospechas de corrupci\u00f3n y que, de un modo u otro, est\u00e1 ligado a los cuatro exl\u00edderes expulsados por el Comit\u00e9 Central.<\/p>\n<p>Zhou coincidi\u00f3 con Li Dongsheng en la c\u00fapula del Ministerio de Seguridad P\u00fablica, cuya cartera ocup\u00f3 entre 2002 y 2007, y su ascenso pol\u00edtico comenz\u00f3 en los a\u00f1os 90 desde la directiva de CNPC, donde Wang Yongchun ya era un ejecutivo provincial y Jiang Jiemin fue posteriormente director general y presidente.<\/p>\n<p>Menos directa es la relaci\u00f3n de Zhou con el exgeneral Xu, aunque se les considera viejos aliados pol\u00edticos y en 2012 llegaron a publicarse en la prensa sensacionalista informaciones, nunca confirmadas, de que Zhou y Xu hab\u00edan estado detr\u00e1s de un intento de golpe de Estado para apoyar a Bo Xilai, exl\u00edder entonces destituido por corrupci\u00f3n y condenado a cadena perpetua en 2013.<\/p>\n<p>Decenas de pol\u00edticos chinos, especialmente a nivel local y provincial, han sido destituidos o son investigados en la campa\u00f1a contra la corrupci\u00f3n iniciada por el presidente Xi Jinping tras su llegada al poder en 2013.<\/p>\n<p>Junto a los hoy expulsados, importantes &#8216;v\u00edctimas&#8217; de esta campa\u00f1a han sido el exministro de Ferrocarriles Liu Zhijun, condenado a muerte el pasado a\u00f1o (aunque su pena ser\u00e1 probablemente conmutada por cadena perpetua) y el exviceministro de planificaci\u00f3n econ\u00f3mica Liu Tienan, acusado la semana pasada de aceptaci\u00f3n de sobornos (aunque lleva ya 13 meses detenido).<\/p>\n<p>Sin embargo, las autoridades chinas tambi\u00e9n han perseguido desde 2013 a militantes de organizaciones civiles como el movimiento &#8216;Nuevo Ciudadano&#8217; que buscaban, en la misma l\u00ednea, denunciar p\u00fablicamente a altos cargos corruptos o pedir a los l\u00edderes comunistas que hicieran p\u00fablicos sus patrimonios.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Partido Comunista de China (PCCh), formaci\u00f3n pol\u00edtica que ma\u00f1ana celebra el 93 aniversario de su creaci\u00f3n, anunci\u00f3 hoy la expulsi\u00f3n de cuatro importantes ex altos cargos del regimen acusados de corrupci\u00f3n, lo que deja finalmente estos casos en manos de la justicia, tras meses de especulaciones. El Comit\u00e9 Central del PCCh, formado por los [&hellip;]<\/p>","protected":false},"author":0,"featured_media":874896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-142467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=142467"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142467\/revisions"}],"predecessor-version":[{"id":874941,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142467\/revisions\/874941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/874896"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=142467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=142467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=142467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}