{"id":142463,"date":"2014-07-01T06:29:43","date_gmt":"2014-07-01T10:29:43","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20140701\/intensos-combates-en-dos-localidades-proximas-a-donetsk\/"},"modified":"2025-08-18T09:26:00","modified_gmt":"2025-08-18T09:26:00","slug":"intensos-combates-en-dos-localidades-proximas-a-donetsk","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20140701\/intensos-combates-en-dos-localidades-proximas-a-donetsk\/","title":{"rendered":"Intensos combates en dos localidades pr\u00f3ximas a Donetsk"},"content":{"rendered":"<p>Las tropas del Gobierno de Kiev y las milicias prorrusas libran hoy intensos combates en las localidades de Marinka y K\u00e1rlovka, pr\u00f3ximas a la ciudad de Donetsk, capital de la hom\u00f3nima regi\u00f3n suroriental ucraniana, seg\u00fan la agencia local Ostrov.<\/p>\n<p>&#8216;En Marinka, que es lo mismo que decir en Donetsk, hay combates desde hace m\u00e1s de dos horas&#8217;, dijo un testigo citado por el medio digital, que inform\u00f3 tambi\u00e9n de choques armados en K\u00e1rlovka.<\/p>\n<p>Ambas localidades se encuentran a unos 20 kil\u00f3metros al este de Donetsk, ciudad de casi un mill\u00f3n de habitantes, controlada por los separatistas prorrusos desde hace m\u00e1s de dos meses.<\/p>\n<p>&#8216;Esta ma\u00f1ana se reanud\u00f3 la fase activa de la operaci\u00f3n antiterrorista. Nuestras fuerzas armadas asestan golpes a las bases y los puestos fortificados de los terroristas&#8217;, declar\u00f3 hoy el presidente de la Rada Suprema (Parlamento) de Ucrania, Alexandr Turch\u00ednov, al inaugurar la plenaria del Legislativo.<\/p>\n<p>Esta madrugada, el presidente de Ucrania, Petr\u00f3 Poroshenko, dio por terminado el alto el fuego en el enfrentamiento que mantiene Kiev contra los separatistas prorrusos en el sureste del pa\u00eds.<\/p>\n<p>&#8216;Vamos a avanzar y vamos a liberar nuestra tierra. La extraordinaria oportunidad para dar vida al plan de paz ha sido desperdiciada&#8217;, dijo el l\u00edder ucraniano en un mensaje a la naci\u00f3n.<\/p><div class=\"notic-content-middle\" id=\"notic-2351028945\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Poroshenko atribuy\u00f3 ello a las &#8216;acciones criminales&#8217; de los separatistas prorrusos, que -agreg\u00f3- &#8216;p\u00fablicamente declararon su voluntad de no cumplir el plan de paz, en general, y el alto el fuego, en particular&#8217;.<\/p>\n<p>Seg\u00fan el jefe del Estado, &#8216;la direcci\u00f3n pol\u00edtica de los separatistas mostr\u00f3 su falta de deseo o su incapacidad de controlar sus unidades terroristas&#8217;.<\/p>\n<p>&#8216;Las Fuerzas Armadas, la Guardia Nacional, el Servicio Guardafronteras y el Servicio de Seguridad han recibido las \u00f3rdenes pertinentes. Ya no est\u00e1n limitados para abrir fuego en el cumplimiento de los objetivos encaminados a conservar la integridad territorial&#8217;, subray\u00f3.<\/p>\n<p>El presidente ucraniano, asegur\u00f3 que la paz sigue siendo su objetivo y que &#8216;s\u00f3lo cambian los instrumentos para su consecuci\u00f3n&#8217;.<\/p>\n<p>&#8216;El camino hacia la paz es m\u00e1s complejo de lo que hubi\u00e9semos querido. No quiero adornar la realidad: no ser\u00e1 f\u00e1cil ni sencillo&#8217;, agreg\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>Las tropas del Gobierno de Kiev y las milicias prorrusas libran hoy intensos combates en las localidades de Marinka y K\u00e1rlovka, pr\u00f3ximas a la ciudad de Donetsk, capital de la hom\u00f3nima regi\u00f3n suroriental ucraniana, seg\u00fan la agencia local Ostrov. &#8216;En Marinka, que es lo mismo que decir en Donetsk, hay combates desde hace m\u00e1s de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":867976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-142463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=142463"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142463\/revisions"}],"predecessor-version":[{"id":868006,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/142463\/revisions\/868006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/867976"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=142463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=142463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=142463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}