{"id":140392,"date":"2015-11-16T14:10:00","date_gmt":"2015-11-16T18:10:00","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/20151116\/arrestan-a-mujer-en-oficina-comercial-de-la-aee\/"},"modified":"2025-07-28T21:07:02","modified_gmt":"2025-07-28T21:07:02","slug":"arrestan-a-mujer-en-oficina-comercial-de-la-aee","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20151116\/arrestan-a-mujer-en-oficina-comercial-de-la-aee\/","title":{"rendered":"Arrestan a mujer en oficina comercial de la AEE"},"content":{"rendered":"<p>Una femina que se mostr\u00f3 agresiva tras acudir a la Oficina Comercial de la Autoridad de Energ\u00eda Electrica (AEE) de Vega Baja, fue arrestada por agentes de la Polic\u00eda de Puerto Rico quienes consultan con la fiscal\u00eda para someter cargos contra esta.<\/p>\n<p>Seg\u00fan la informaci\u00f3n ofrecida por la directora interina de la Oficina de Servicios al Cliente de la AEE, Carmen Flores Torres, &#8216;en la ma\u00f1ana de hoy, hubo un incidente en la oficina comercial de Vega Baja cuando una cliente de forma violenta agredi\u00f3 verbalmente a una oficinista, as\u00ed como a la supervisora de la oficina, alter\u00f3 la paz en el lugar, procediendo luego a agredir f\u00edsicamente a un cliente y al oficial de seguridad, y caus\u00f3 da\u00f1os a propiedad de la Autoridad. La cliente fue arrestada&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-4073365350\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Al momento, agentes de la uniformada mantienen detenida a la f\u00e9mina, mientras se consulta con la fiscal\u00eda los cargos que le someter\u00edan.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una femina que se mostr\u00f3 agresiva tras acudir a la Oficina Comercial de la Autoridad de Energ\u00eda Electrica (AEE) de Vega Baja, fue arrestada por agentes de la Polic\u00eda de Puerto Rico quienes consultan con la fiscal\u00eda para someter cargos contra esta. Seg\u00fan la informaci\u00f3n ofrecida por la directora interina de la Oficina de Servicios [&hellip;]<\/p>","protected":false},"author":0,"featured_media":603075,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-140392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/140392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=140392"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/140392\/revisions"}],"predecessor-version":[{"id":603089,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/140392\/revisions\/603089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/603075"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=140392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=140392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=140392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}