{"id":138793,"date":"2016-12-15T12:34:00","date_gmt":"2016-12-15T16:34:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/gobierno\/politica\/20161215\/lazaro-se-responsabiliza-por-ascensos-de-compinches-de-anaudi-en-la-aaa\/"},"modified":"2025-07-18T08:35:26","modified_gmt":"2025-07-18T08:35:26","slug":"lazaro-se-responsabiliza-por-ascensos-de-compinches-de-anaudi-en-la-aaa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20161215\/lazaro-se-responsabiliza-por-ascensos-de-compinches-de-anaudi-en-la-aaa\/","title":{"rendered":"L\u00e1zaro se responsabiliza por ascensos de &#8216;compinches&#8217; de Anaudi en la AAA"},"content":{"rendered":"<p>El presidente de la Autoridad de Acueductos y Alcantarillados (AAA), Alberto L\u00e1zaro, asegur\u00f3 que fue el quien ascendi\u00f3 a la exvicepresidenta, Ivonne Falc\u00f3n, quien hoy figura como convicta federal por corrupci\u00f3n p\u00fablica tras el caso judicial contra el Anaudi Hern\u00e1ndez.<\/p>\n<p>&#8216;Yo fui el que decid\u00ed ponerla en esa posici\u00f3n, pero la premisa de que nos cost\u00f3, por lo menos a la autoridad en t\u00e9rminos econ\u00f3micos, los controles que tiene la Autoridad lograron que los coautores de esta estructura no causaran da\u00f1os econ\u00f3micos para la Autoridad&#8217;, declar\u00f3 L\u00e1zaro durante su cita ante el Comit\u00e9 de Transici\u00f3n.<\/p>\n<p>De inmediato el licenciado Ram\u00f3n Rosario, del comit\u00e9 entrante, cuestion\u00f3 a L\u00e1zaro c\u00f3mo no causaron costo econ\u00f3mico a la AAA. El presidente explic\u00f3 que el lucro que esperaban los coautores no se dio por una serie de sucesos externos que ocurrieron en la corporaci\u00f3n p\u00fablica.<\/p>\n<p>Posteriormente, L\u00e1zaro expres\u00f3 ante el comit\u00e9 que est\u00e1 limitado de hablar sobre el asunto por parte de la Oficina de \u00c9tica Gubernamental (OEG) por haber una investigaci\u00f3n en curso. A pesar que tanto Rosario como su compa\u00f1ero de delegaci\u00f3n, el licenciado Alfonso Orona, cuestionaron en reiteradas ocasiones c\u00f3mo la OEG le impide hacer declaraciones sobre un caso que ya culmin\u00f3, L\u00e1zaro se aferr\u00f3 a limitar sus contestaciones.<\/p>\n<p>A\u00fan as\u00ed fue cuestionado tambi\u00e9n por la contrataci\u00f3n de la exdirectora de ventas de la AAA, Sonia Barreto, quien afirm\u00f3 tambi\u00e9n que \u00e9l la nombr\u00f3 a ese cargo. &#8216;Y nadie se la recomend\u00f3?&#8217;, pregunt\u00f3 Rosario, a lo que L\u00e1zaro respondi\u00f3 que el actual secretario de Asuntos P\u00fablicos de la Fortaleza, Jes\u00fas Manuel Ortiz, y el comisionado electoral del Partido Popular Democr\u00e1tico (PPD), Eder Ortiz, se comunicaron con \u00e9l para recomendarla.<\/p><div class=\"notic-content-middle\" id=\"notic-784839593\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Por su parte,Orona cuestion\u00f3 al Presidente de la corporaci\u00f3n p\u00fablicasobre el proceso administrativo contra Barreto, quien luego de ser acusada por las autoridades federales renunci\u00f3 a su puesto de confianza pero continu\u00f3 como empleada de carrera aunque suspendida. &#8216;La informaci\u00f3n que llega a este comit\u00e9 es que ella fue suspendida de empleo, pero no de sueldo&#8217;, lanz\u00f3 Orona, a lo que L\u00e1zaro respondi\u00f3 en la afirmativa y agreg\u00f3 desconoce cu\u00e1ndo fue que dej\u00f3 de cobrar su sueldo.<\/p>\n<p>Sobre los v\u00ednculos entre la AAA y la Administraci\u00f3n de Desarrollo Laboral (ADL), dependencia liderada por la tambi\u00e9n convicta en el caso federal, Sally L\u00f3pez, L\u00e1zaro se\u00f1al\u00f3 que era una relaci\u00f3n mediante contratos, en espec\u00edfico aquellos de adiestramiento. Estos contratos fueron costeados por el programa federal <em>Workforce Investment Act<\/em> (WIA) y seg\u00fan el Presidente una auditor\u00eda federal no arrojo irregularidades en el uso de esos fondos, que seg\u00fan L\u00e1zaro eran de \u00edndole estatal.<\/p>\n<p>&#8216;Qu\u00e9 compa\u00f1\u00eda se contrato para ofrecer el adiestramiento al personal de nuevo ingreso que fueron contratados con fondos WIA?&#8217;, pregunt\u00f3 Orona. &#8216;Links Group&#8217;, respondi\u00f3 L\u00e1zaro. &#8216;Y de qui\u00e9n es esa compa\u00f1\u00eda?&#8217; continu\u00f3 el licenciado, lo que el Presidente dijo no tener el nombre pero que sali\u00f3 p\u00fablicamente.<\/p>\n<p>&#8216;Y usted conoce personalmente al se\u00f1or Anaudi Hern\u00e1ndez?&#8217; cuestion\u00f3 Orona. &#8216;Nunca lo conoc\u00ed&#8217;, asegur\u00f3 L\u00e1zaro.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente de la Autoridad de Acueductos y Alcantarillados (AAA), Alberto L\u00e1zaro, asegur\u00f3 que fue el quien ascendi\u00f3 a la exvicepresidenta, Ivonne Falc\u00f3n, quien hoy figura como convicta federal por corrupci\u00f3n p\u00fablica tras el caso judicial contra el Anaudi Hern\u00e1ndez. &#8216;Yo fui el que decid\u00ed ponerla en esa posici\u00f3n, pero la premisa de que nos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,7,2],"tags":[],"class_list":["post-138793","post","type-post","status-publish","format-standard","hentry","category-gobierno","category-politica","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/138793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=138793"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/138793\/revisions"}],"predecessor-version":[{"id":500039,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/138793\/revisions\/500039"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=138793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=138793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=138793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}