{"id":138304,"date":"2017-04-20T11:12:00","date_gmt":"2017-04-20T15:12:00","guid":{"rendered":"https:\/\/www.noticel.com\/deportes\/lai\/20170420\/justas-lai-2017-gallitos-dedican-campeonato-a-sus-companeros-que-estan-en\/"},"modified":"2025-07-22T18:47:07","modified_gmt":"2025-07-22T18:47:07","slug":"justas-lai-2017-gallitos-dedican-campeonato-a-sus-companeros-que-estan-en","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20170420\/justas-lai-2017-gallitos-dedican-campeonato-a-sus-companeros-que-estan-en\/","title":{"rendered":"Justas LAI 2017: Gallitos dedican campeonato a sus compa\u00f1eros que est\u00e1n en"},"content":{"rendered":"<p>Los Gallitos de la Universidad de Puerto Rico (UPR) de R\u00edo Piedras dedicaron su segundo campeonato consecutivo en el baloncesto de la LAI a su estudiantado que es parte de una huelga que mantiene paralizado al primer sistema universitario del Pa\u00eds desde hace 15 d\u00edas.<\/p>\n<p>Los Gallitos se alzaron con el cetro tras derrotar a los los Cocodrilos de la Universidad Metropolitana en el partido decisivo celebrado en el Palacio de los Deportes en Mayag\u00fcez.<\/p>\n<p>El equipo de los Gallitos estuvo cumpliendo sus pr\u00e1cticas y compromisos en la LAI con el patrocinio y apoyo de los huelguistas del recinto riopedrese.<\/p>\n<p>En ese sentido, el experimentado mentor riopedrense Danny Ortiz se manifest\u00f3 agradecido por el apoyo recibido de los estudiantes huelguistas a su quinteto.<\/p>\n<p>&#8216;En ning\u00fan momento nos afect\u00f3 la huelga, porque el estudiantado ha estado bien consiente. Nos han abierto los portes y la cancha para que fu\u00e9ramos a practicar, por lo que no perdimos ninguna pr\u00e1ctica. Lo \u00fanico que no pudimos hacer fue jugar en nuestra cancha donde ten\u00edamos ventaja local. Pero, los muchachos donde quieran que juegan, parecen que est\u00e1n jugando en la IUPI. Muy agradecido de los estudiantes, no solo porque nos dejaron practicar, sino por el respaldo en todos los partidos&#8217;, dijo emocionado y sonriente el dirigente bicampe\u00f3n de la UPR de R\u00edo Piedras.<\/p>\n<p>En la victoria lucieron Esteban Cordero con 24 puntos, Kristian Medina con 14 puntos y Jos\u00fae Erazo con 13 tantos. En causa perdida H\u00e9ctor Rodr\u00edguez y Javier Rivera con 13 puntos cada uno.<\/p>\n<p>Ortiz explic\u00f3 que su equipo merec\u00eda el campeonato pues vienen trabajando desde el 15 de octubre con sobre ochenta pr\u00e1cticas.<\/p>\n<p>&#8216;Tengo que estar bien contento. Agradecido de Dios primero y de los muchachos que hicieron un trabajo excelente. Ellos verdaderamente se lo merec\u00edan, hemos jugado treinta y picos de juego. As\u00ed, que se lo merec\u00edan&#8217;, expres\u00f3 el gallo mayor quien consigui\u00f3 por primera un back to back campeonil en su extensa carrera universitaria.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los Gallitos de la Universidad de Puerto Rico (UPR) de R\u00edo Piedras dedicaron su segundo campeonato consecutivo en el baloncesto de la LAI a su estudiantado que es parte de una huelga que mantiene paralizado al primer sistema universitario del Pa\u00eds desde hace 15 d\u00edas. Los Gallitos se alzaron con el cetro tras derrotar a [&hellip;]<\/p>","protected":false},"author":0,"featured_media":558654,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-138304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/138304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=138304"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/138304\/revisions"}],"predecessor-version":[{"id":558655,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/138304\/revisions\/558655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/558654"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=138304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=138304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=138304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}