{"id":136625,"date":"2015-02-06T16:57:40","date_gmt":"2015-02-06T20:57:40","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20150206\/alcaldes-federados-anclados-al-celi-de-la-aee-piden-uno-de-la-aaa\/"},"modified":"2025-08-17T22:25:58","modified_gmt":"2025-08-17T22:25:58","slug":"alcaldes-federados-anclados-al-celi-de-la-aee-piden-uno-de-la-aaa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20150206\/alcaldes-federados-anclados-al-celi-de-la-aee-piden-uno-de-la-aaa\/","title":{"rendered":"Alcaldes federados anclados al CELI de la AEE, piden uno de la AAA"},"content":{"rendered":"<p>El presidente de la Federaci\u00f3n de Alcaldes de Puerto Rico, Hector O&#8217;Neill reiter\u00f3 hoy viernes que si la Autoridad de Energ\u00eda Electrica (AEE) tuviera que pagarle a los municipios los arbitrios por concepto de construcci\u00f3n, patentes y contribuciones sobre la propiedad mueble e inmueble, dicho pago ser\u00eda aproximadamente tres veces m\u00e1s que la cantidad anual de la contribuci\u00f3n en lugar de impuesto (CELI) que la corporaci\u00f3n p\u00fablica le paga a los municipios.<\/p>\n<p>Actualmente, unos 67 municipios est\u00e1n muy lejos de cumplir la meta establecida por la Ley de Reforma Energ\u00e9tica de reducir su consumo de energ\u00eda en un 15% en tres a\u00f1os. La AEE ha paga una cantidad estimada de $336 millones en CELI.<\/p>\n<p>El Alcalde de Guaynabo sugiri\u00f3 de paso, que a la Autoridad de Acueductos y Alcantarillados (AAA) se le imponga el pago de un CELI a los municipios porque los tiempos han cambiado y el costo del agua ya no es el mismo que cuando se cre\u00f3 dicha Corporaci\u00f3n en 1945.<\/p>\n<p>Las expresiones de O&#8217;neill fueron hechas ante la Comisi\u00f3n de Asuntos Energ\u00e9ticos y Recursos de Agua del Senado, presidida por el senador Ram\u00f3n Luis Nieves, que estudia alternativas a la contribuci\u00f3n que hace AEE a los municipios por el CELI para lograr una rebaja en las facturas de los abonados y fomentar la innovaci\u00f3n tecnol\u00f3gica para reducir los costos energ\u00e9ticos en los municipios.<\/p>\n<p>O&#8217;Neill plante\u00f3 que la situaci\u00f3n bajo an\u00e1lisis ya fue resuelta. &#8216;Est\u00e1 recogido en la Ley 57 de 2014, espec\u00edficamente en el Art\u00edculo 2.10: &#8216;la Autoridad no ser\u00e1 requerida para pagar ningunas contribuciones estatales o municipales, o impuestos de cualquier tipo sobre ninguna de las propiedades muebles e inmuebles adquiridas por ella o bajo su potestad, dominio, posesi\u00f3n o inspecci\u00f3n, o sobre sus actividades en la explotaci\u00f3n y conservaci\u00f3n de cualquier empresa, o sobre los ingresos derivados de cualesquiera de sus empresas y actividades, o sobre su volumen de negocios. Las personas que celebren contratos con la Autoridad no estar\u00e1n sujetas al impuesto gubernamental sobre contratos, establecido en la Ley 1-2011, seg\u00fan enmendada, conocida como el &#8216;C\u00f3digo de Rentas Internas de Puerto Rico de 2011&#8217;, dijo.<\/p><div class=\"notic-content-middle\" id=\"notic-812142739\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El Alcalde de Guaynabo rechaz\u00f3 adem\u00e1s, las alegaciones de los Ejecutivos y los L\u00edderes de la UTIER de que la posici\u00f3n de los municipios no es v\u00e1lida porque no es com\u00fan que las entidades p\u00fablicas de utilidades el\u00e9ctricas paguen por dichos tributos y porque en Puerto Rico ninguna otra entidad p\u00fablica de utilidades ha pagado una CELI.<\/p>\n<p>En su defensa del CELI, O&#8217;Neill cit\u00f3 que en Estados Unidos la utilidades el\u00e9ctricas con sobre 50,000 clientes tienen programas de pagos en lugar de impuestos, o contribuciones similares a la CELI, establecida por Ley en la AEE, seg\u00fan el estudio &#8216;Accounts Receivable and CILT Report&#8217; realizado por la oficial de reestructuraci\u00f3n de la corporaci\u00f3n, Lisa Donahue.<\/p>\n<p>Vea tambi\u00e9n<\/p>\n<p><a href=\"http:\/\/noticel.com\/en\/noticia\/171911\/someten-propuestas-para-bajar-consumo-energetico-en-municipios.html\/\" target=\"_blank\">Someten propuestas para bajar consumo energ\u00e9tico en municipios<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente de la Federaci\u00f3n de Alcaldes de Puerto Rico, Hector O&#8217;Neill reiter\u00f3 hoy viernes que si la Autoridad de Energ\u00eda Electrica (AEE) tuviera que pagarle a los municipios los arbitrios por concepto de construcci\u00f3n, patentes y contribuciones sobre la propiedad mueble e inmueble, dicho pago ser\u00eda aproximadamente tres veces m\u00e1s que la cantidad anual [&hellip;]<\/p>","protected":false},"author":0,"featured_media":863062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-136625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/136625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=136625"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/136625\/revisions"}],"predecessor-version":[{"id":863113,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/136625\/revisions\/863113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/863062"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=136625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=136625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=136625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}