{"id":136502,"date":"2020-06-12T09:17:00","date_gmt":"2020-06-12T13:17:00","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20200612\/cientificos-identifican-patron-estacional-en-el-coronavirus\/"},"modified":"2025-07-20T00:16:33","modified_gmt":"2025-07-20T00:16:33","slug":"cientificos-identifican-patron-estacional-en-el-coronavirus","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20200612\/cientificos-identifican-patron-estacional-en-el-coronavirus\/","title":{"rendered":"Cient\u00edficos identifican patr\u00f3n estacional en el coronavirus"},"content":{"rendered":"<h3>Establecen que el virus prospera mejor en climas frescos y secos<\/h3>\n<p>Cient\u00edficos internacionales sugieren en un estudio que la COVID-19 sigue un patr\u00f3n estacional y prospera mejor en climas frescos y secos, un hallazgo que ayudar\u00e1 a dise\u00f1ar estrategias de prevenci\u00f3n y vigilancia para evitar o contener nuevos brotes en todo el mundo.<\/p>\n<p>El estudio, liderado por la Universidad de Maryland, en Baltimore (Estados Unidos), se ha publicado en la revista Journal of the America Medical Association (JAMA).<\/p>\n<p>Los investigadores analizaron la asociaci\u00f3n del clima con la propagaci\u00f3n de la infecci\u00f3n por COVID-19 y, para ello, examinaron los datos clim\u00e1ticos de cincuenta ciudades de todo el mundo con y sin coronavirus, entre el 1 de enero y el 10 de marzo de este a\u00f1o.<\/p>\n<p>As\u00ed, compararon ocho ciudades con una fuerte expansi\u00f3n de la epidemia (Wuhan, China; Tokio, Jap\u00f3n; Daegu, Corea del Sur; Qom, Ir\u00e1n; Mil\u00e1n, Italia; Par\u00eds, Francia; Seattle, EE.UU.; y Madrid, Espa\u00f1a) con 42 que no se han visto afectadas o que no han registrado muchos contagios.<\/p><div class=\"notic-content-middle\" id=\"notic-978951033\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>El estudio constat\u00f3 que las ciudades m\u00e1s afectadas por la pandemia est\u00e1n en el corredor de latitud de entre 30 y 50 grados al norte (N) y sus patrones clim\u00e1ticos son similares: tienen una temperatura media de entre 5 y 11 grados cent\u00edgrados y baja humedad espec\u00edfica y absoluta (de entre 44 y 84%), cuando el virus se propagaba m\u00e1s r\u00e1pidamente.<\/p>\n<p>Los mapas producidos por el equipo de investigaci\u00f3n mostraron una franja clim\u00e1tica en el hemisferio norte que contiene unas condiciones atmosf\u00e9ricas amables con el virus, y en la que cayeron las ocho ciudades.<\/p>\n<p>As\u00ed pues, el estudio determina que la distribuci\u00f3n de brotes comunitarios sustanciales de COVID seg\u00fan determinados valores de latitud, temperatura y humedad son coherentes con el comportamiento de un virus respiratorio estacional, y que el virus del SARS-CoV-2 tiene m\u00e1s dificultades para propagarse en condiciones de mayor temperatura y humedad.<\/p>\n<p>El an\u00e1lisis de la distribuci\u00f3n de los brotes de coronavirus podr\u00eda ayudar a prever las \u00e1reas con m\u00e1s riesgo de transmisi\u00f3n en el futuro, si bien, los autores del estudio advierten de que para ello ser\u00e1n necesarias nuevas investigaciones sobre modelos clim\u00e1ticos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Establecen que el virus prospera mejor en climas frescos y secos Cient\u00edficos internacionales sugieren en un estudio que la COVID-19 sigue un patr\u00f3n estacional y prospera mejor en climas frescos y secos, un hallazgo que ayudar\u00e1 a dise\u00f1ar estrategias de prevenci\u00f3n y vigilancia para evitar o contener nuevos brotes en todo el mundo. El estudio, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":530524,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-136502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/136502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=136502"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/136502\/revisions"}],"predecessor-version":[{"id":530525,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/136502\/revisions\/530525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/530524"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=136502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=136502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=136502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}