{"id":135766,"date":"2020-06-07T15:24:00","date_gmt":"2020-06-07T19:24:00","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20200607\/miles-de-personas-se-manifiestan-en-belgica-por-la-muerte-de-floyd\/"},"modified":"2025-07-20T01:02:14","modified_gmt":"2025-07-20T01:02:14","slug":"miles-de-personas-se-manifiestan-en-belgica-por-la-muerte-de-floyd","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20200607\/miles-de-personas-se-manifiestan-en-belgica-por-la-muerte-de-floyd\/","title":{"rendered":"Miles de personas se manifiestan en B\u00e9lgica por la muerte de Floyd"},"content":{"rendered":"<h3>Sobre 10,000 personas se reunieron este domingo.<\/h3>\n<p>M\u00e1s de 10,000 personas se manifestaron en Bruselas, unas 1,200 en Amberes y varios centenares en Gante, Ostende y otras localidades belgas contra el racismo y en recuerdo del afroamericano George Floyd, que muri\u00f3 asfixiado por un polic\u00eda en Mine\u00e1polis (Estados Unidos).<\/p>\n<p>En Bruselas m\u00e1s de 10,000 personas se reunieron este domingo frente al palacio de Justicia, en el centro de la capital.<\/p>\n<p>Aunque la mayor\u00eda de los participantes llevaba m\u00e1scara, la distancia f\u00edsica no siempre se respet\u00f3 debido a la multitud presente.<\/p>\n<p>\u00abLa muerte de George Floyd ha despertado a mucha gente\u00bb, dijo Ange Kaze, portavoz de \u00abBelgian Network for Black Lives\u00bb (Red belga por las vidas negras), que convoc\u00f3 la acci\u00f3n.<\/p>\n<p>\u00abMuchas personas est\u00e1n hartas de la violencia polic\u00eda, que afecta sistem\u00e1ticamente a los negros\u00bb, a\u00f1adi\u00f3, informa la agencia Belga.<\/p>\n<p>En Amberes, los manifestantes se congragaron en Steenplein, seg\u00fan la polic\u00eda local.<\/p>\n<p>La mayor\u00eda respet\u00f3 las consigas sobre distanciaci\u00f3n f\u00edsica impuestas en la lucha contra el coronavirus.<\/p>\n<p>El grupo Youth Against Racism (La juventud contra el racismo) llam\u00f3 la semana pasada a concentrarse a trav\u00e9s de las redes sociales en distintas ciudades belgas.<\/p>\n<p>Las autoridades municipales no hab\u00edan autorizado la marcha, que se desarroll\u00f3 sin incidentes.<\/p>\n<p>El s\u00e1bado, unas 700 personas se reunieron en la Place Verte de Amberes para protestar.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sobre 10,000 personas se reunieron este domingo. M\u00e1s de 10,000 personas se manifestaron en Bruselas, unas 1,200 en Amberes y varios centenares en Gante, Ostende y otras localidades belgas contra el racismo y en recuerdo del afroamericano George Floyd, que muri\u00f3 asfixiado por un polic\u00eda en Mine\u00e1polis (Estados Unidos). En Bruselas m\u00e1s de 10,000 personas [&hellip;]<\/p>","protected":false},"author":0,"featured_media":530954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-135766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/135766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=135766"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/135766\/revisions"}],"predecessor-version":[{"id":530955,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/135766\/revisions\/530955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/530954"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=135766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=135766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=135766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}