{"id":135289,"date":"2020-05-31T13:09:00","date_gmt":"2020-05-31T17:09:00","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20200531\/ceremonia-de-apertura-de-la-capsula-de-space-x\/"},"modified":"2025-07-20T02:10:55","modified_gmt":"2025-07-20T02:10:55","slug":"ceremonia-de-apertura-de-la-capsula-de-space-x","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20200531\/ceremonia-de-apertura-de-la-capsula-de-space-x\/","title":{"rendered":"Ceremonia de apertura de la c\u00e1psula de Space X"},"content":{"rendered":"<h3>La nave espacial Dragon Endeavour de SpaceX se acopl\u00f3 sin problemas a la EEI.<\/h3>\n<p>Mira la transmisi\u00f3n en directo oprimiendo <a href=\"https:\/\/www.facebook.com\/noticelpr\/videos\/560326211338562\/\" id=\"link-a6bd12295a9cd75a3c5aedbe14c9d9ca\" target=\"_blank\">aqu\u00ed<\/a>.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2Fnoticelpr%2Fvideos%2F560326211338562%2F&#038;show_text=0&#038;width=560\" width=\"560\" height=\"315\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowtransparency=\"true\" allowfullscreen=\"true\"><\/iframe><\/p>\n<p>La c\u00e1psula Dragon Endeavour de la compa\u00f1\u00eda SpaceX lleg\u00f3 este domingo a la Estaci\u00f3n Espacial Internacional (EEI) con dos astronautas de la NASA a bordo, unas 19 horas despu\u00e9s de su exitoso lanzamiento desde el Centro Espacial Kennedy, en Cabo Ca\u00f1averal (Florida, EE.UU.)<\/p><div class=\"notic-content-middle\" id=\"notic-3421300104\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Por el momento, se desconoce la duraci\u00f3n de la misi\u00f3n Demo-2 que tiene como objetivo certificar la capacidad de la compa\u00f1\u00eda SpaceX, fundada por Elon Musk, de realizar viajes espaciales comerciales, pero se estima que los astronautas pasen entre 6 y 16 semanas en la EEI.<\/p>\n<p>Durante ese tiempo realizar\u00e1n investigaciones t\u00e9cnicas y cient\u00edficas hasta su regreso a la Tierra, que, de ser satisfactorio, supondr\u00e1 el paso final antes de comenzar las misiones operacionales de la NASA apoyadas por compa\u00f1\u00edas privadas.<\/p>","protected":false},"excerpt":{"rendered":"<p>La nave espacial Dragon Endeavour de SpaceX se acopl\u00f3 sin problemas a la EEI. Mira la transmisi\u00f3n en directo oprimiendo aqu\u00ed. La c\u00e1psula Dragon Endeavour de la compa\u00f1\u00eda SpaceX lleg\u00f3 este domingo a la Estaci\u00f3n Espacial Internacional (EEI) con dos astronautas de la NASA a bordo, unas 19 horas despu\u00e9s de su exitoso lanzamiento desde [&hellip;]<\/p>","protected":false},"author":0,"featured_media":531563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-135289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/135289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=135289"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/135289\/revisions"}],"predecessor-version":[{"id":531564,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/135289\/revisions\/531564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/531563"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=135289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=135289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=135289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}