{"id":134571,"date":"2020-05-21T12:43:00","date_gmt":"2020-05-21T16:43:00","guid":{"rendered":"https:\/\/www.noticel.com\/el-tiempo\/huracanes\/20200521\/se-espera-una-temporada-de-huracanes-sobre-lo-normal\/"},"modified":"2025-07-20T03:49:34","modified_gmt":"2025-07-20T03:49:34","slug":"se-espera-una-temporada-de-huracanes-sobre-lo-normal","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/el-tiempo\/20200521\/se-espera-una-temporada-de-huracanes-sobre-lo-normal\/","title":{"rendered":"Se espera una temporada de huracanes \u00absobre lo normal\u00bb"},"content":{"rendered":"<h3>Urgen a prepararse para la temporada de huracanes pese a la pandemia.<\/h3>\n<p>La temporada de huracanes para el Atl\u00e1ntico se prev\u00e9 \u201csobre lo normal\u201d en el a\u00f1o 2020, seg\u00fan el estimado del Centro de Predicci\u00f3n del Clima del Servicio Nacional de Meteorolog\u00eda (SNM).<\/p>\n<p>\u201cMientras nos hemos concentrado en la seguridad y la salud para reabrir el pa\u00eds, es altamente importante que recordemos tomar las precauciones necesarias para la temporada de huracanes\u201d, dijo el secretario de Comercio, Wilbur Ross en declaraciones escritas.<\/p>\n<p>El estimado prev\u00e9 que ser\u00e1 60 por ciento de una temporada \u201csobre lo normal\u201d, 30 por ciento de probabilidad de una temporada \u201ccerca de lo normal\u201d y un 10 por ciento de probabilidad \u201cdebajo de lo normal\u201d. La temporada de huracanes en el Atl\u00e1ntico comienza el primero de junio hasta el 30 de noviembre.<\/p><div class=\"notic-content-middle\" id=\"notic-62833802\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Adem\u00e1s, el SNM pronostica que habr\u00e1 entre 13 a 19 tormentas que se podr\u00e1n formar (que se les dar\u00e1 nombre) con vientos de 39 millas por hora o m\u00e1s. De estas, entre 6 a 10 pueden convertirse en huracanes (que fluct\u00faan entre las 74 millas por hora en adelante) y de esos de 3 a 6 pueden ser de categor\u00eda 3,4 o 5 (con vientos de 111 millas por hora o m\u00e1s).<\/p>\n<p>El SNM dio un grado de certeza a este pron\u00f3stico de 70 por ciento. Seg\u00fan la entidad federal, una temporada promedio produce 12 tormentas con nombre de las cuales 6 pueden convertirse en huracanes y 3 de ellos huracanes de fuerza mayor.<\/p>","protected":false},"excerpt":{"rendered":"<p>Urgen a prepararse para la temporada de huracanes pese a la pandemia. La temporada de huracanes para el Atl\u00e1ntico se prev\u00e9 \u201csobre lo normal\u201d en el a\u00f1o 2020, seg\u00fan el estimado del Centro de Predicci\u00f3n del Clima del Servicio Nacional de Meteorolog\u00eda (SNM). \u201cMientras nos hemos concentrado en la seguridad y la salud para reabrir [&hellip;]<\/p>","protected":false},"author":0,"featured_media":532368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[18,19],"tags":[],"class_list":["post-134571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-tiempo","category-huracanes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/134571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=134571"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/134571\/revisions"}],"predecessor-version":[{"id":532369,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/134571\/revisions\/532369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/532368"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=134571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=134571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=134571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}