{"id":134482,"date":"2020-05-19T19:21:00","date_gmt":"2020-05-19T23:21:00","guid":{"rendered":"https:\/\/www.noticel.com\/economia\/gobierno\/20200519\/clave-posponer-el-pago-de-la-deuda-para-atender-la-crisis-economica-de-pr\/"},"modified":"2025-07-20T04:04:34","modified_gmt":"2025-07-20T04:04:34","slug":"clave-posponer-el-pago-de-la-deuda-para-atender-la-crisis-economica-de-pr","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/gobierno\/20200519\/clave-posponer-el-pago-de-la-deuda-para-atender-la-crisis-economica-de-pr\/","title":{"rendered":"Clave posponer el pago de la deuda para atender la crisis econ\u00f3mica de PR"},"content":{"rendered":"<h3>La organizaci\u00f3n Espacios Abiertos ofreci\u00f3 sus recomendaciones ante el panorama que vive Puerto Rico tras varias crisis, incluyendo la del COVID-19.<\/h3>\n<p>La posibilidad de una moratoria temporal en el pago de la deuda, un an\u00e1lisis de sostenibilidad de esta, y la eliminaci\u00f3n de medidas de austeridad son acciones contundentes que deber\u00edan tomarse por parte del gobierno y de la Junta de Supervisi\u00f3n Fiscal para lidiar con la situaci\u00f3n econ\u00f3mica que enfrenta el pa\u00eds despu\u00e9s de la pandemia del COVID-19, a juicio de Daniel Santamar\u00eda Ots, economista y analista senior de Pol\u00edtica P\u00fablica de la organizaci\u00f3n Espacios Abiertos.<\/p>\n<p>La organizaci\u00f3n, dedicada a promover la transparencia, la rendici\u00f3n de cuentas gubernamental, y la participaci\u00f3n ciudadana en en el marco de la crisis econ\u00f3mica que atraviesa Puerto Rico, hizo un an\u00e1lisis a ra\u00edz de las proyecciones econ\u00f3micas en el plan fiscal m\u00e1s reciente, que fue publicado por la Autoridad de Asesor\u00eda Financiera y Agencia Fiscal (Aafaf) el pasado 3 de mayo, y ofreci\u00f3 sus recomendaciones en un intento por paliar el cr\u00edtico panorama que se vive en medio de la pandemia por coronavirus.<\/p>\n<p>\u201cEs evidente que las pol\u00edticas de austeridad propuestas en todos los planes fiscales certificados hasta la fecha contribuyen a empeorar el estado de la actual crisis y ayudan en \u00faltima instancia \u00a0a la insostenibilidad de la deuda p\u00fablica\u201d, expres\u00f3 Santamar\u00eda Ots durante una mesa redonda en la que se discuti\u00f3 el tema.<\/p>\n<p>La situaci\u00f3n del COVID-19 ha provocado intervenciones de emergencia en la mayor\u00eda de econom\u00edas del mundo, tanto en el \u00e1rea de pol\u00edtica fiscal, con grandes paquetes de est\u00edmulo en el gasto p\u00fablico, como en el \u00e1rea de pol\u00edtica monetaria, con intervenciones coordinadas en los mercados financieros de la mayor\u00eda de los bancos centrales.<\/p>\n<p>\u201cComo ejemplo del \u00e1rea de pol\u00edtica fiscal est\u00e1 el mayor est\u00edmulo fiscal de la historia de los Estados Unidos, el CARES Act, por un valor de $2.3 millones. Y en cuanto a la pol\u00edtica monetaria est\u00e1 la intervenci\u00f3n de la Reserva Federal en la compra de activos financieros por valor de hasta $4.0 trillones. A estas se sumar\u00eda la solicitud por parte del G20 de realizar una moratoria en el pago de la deuda p\u00fablica e intereses por valor de $20 billones de por lo menos doce meses, afectando a 76 pa\u00edses de econom\u00edas emergentes\u201d, se explic\u00f3.<\/p>\n<p>Santamar\u00eda Ots recomend\u00f3 que, en el a\u00f1o fiscal 2020-2021, todos los recursos del presupuesto del Fondo General del gobierno, adem\u00e1s de todos los fondos federales destinados a atender la crisis, se inviertan en robustecer la econom\u00eda del pa\u00eds y atender las necesidades m\u00e1s apremiantes de la gente.<\/p>\n<p>Adem\u00e1s, propuso que se solicite de inmediato una moratoria de no menos de un a\u00f1o a los acreedores de la deuda p\u00fablica de Puerto Rico, lo que supondr\u00eda una suspensi\u00f3n de los pagos actuales. Dijo que esa acci\u00f3n es necesaria hasta que se tenga un panorama m\u00e1s certero sobre la situaci\u00f3n econ\u00f3mica a nivel local y mundial.<\/p>\n<p>Tambi\u00e9n se recomend\u00f3 que se realice y publique un an\u00e1lisis de sostenibilidad de la deuda p\u00fablica que incluya los efectos de la pandemia a largo plazo; la eliminaci\u00f3n, de una vez, de las medidas de austeridad\u00a0como principio rector de las pol\u00edticas p\u00fablicas del pa\u00eds; la culminaci\u00f3n de los estados financieros auditados para los a\u00f1os 2017, 2018 y 2019; y el desarrollo de un plan econ\u00f3mico realista y ajustado a esta nueva realidad.<\/p><div class=\"notic-content-middle\" id=\"notic-938040505\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>El plan fiscal presente interpreta esta nueva situaci\u00f3n como un escenario de riesgos sin precedentes para Puerto Rico.<\/p>\n<p>\u201cEl nuevo plan fiscal presenta unas proyecciones de ca\u00edda del Producto Nacional Bruto real del\u00a0-3.8%\u00a0para el a\u00f1o fiscal\u00a02020\u00a0y del\u00a0-7.8%\u00a0para el a\u00f1o fiscal\u00a02021\u201d, destac\u00f3 Santamar\u00eda Ots.<\/p>\n<p>Asimismo, explic\u00f3 que, de acuerdo al nuevo plan fiscal, una vez se implementen las medidas de austeridad, Puerto Rico enfrentar\u00eda un d\u00e9ficit fiscal nueve a\u00f1os antes de lo previsto, es decir, para 2030. De acuerdo al plan fiscal previo, presentado en febrero de 2020, estos d\u00e9ficit no se presentar\u00edan antes del 2039.<\/p>\n<p>\u201cLa proyecci\u00f3n m\u00e1s optimista sugiere un menor impacto de la crisis que implicar\u00eda un super\u00e1vit promedio de\u00a0$502 millones\u00a0en cada a\u00f1o fiscal. En el escenario base, se asume que habr\u00e1 un mayor impacto de la crisis que generar\u00eda un promedio anual de super\u00e1vits fiscales primarios de cerca de\u00a0$32 millones. La proyecci\u00f3n pesimista supondr\u00eda un promedio anual de d\u00e9ficits fiscales primarios de\u00a0-$578 millones\u00a0cada a\u00f1o fiscal hasta el 2025\u201d, explic\u00f3.<\/p>\n<p>El plan fiscal del gobierno propone tres proyecciones diferentes sobre posibles super\u00e1vits o d\u00e9ficits fiscales primarios entre los a\u00f1os 2020 y 2025, lo que permiti\u00f3 a la organizaci\u00f3n Espacios Abietors estimar los recortes necesarios de los\u00a0$35,000 millones\u00a0de la deuda de los bonos de obligaci\u00f3n general (GOs) seg\u00fan los n\u00fameros y supuestos del propio plan.<\/p>\n<p>En el escenario optimista \u201cse propone un recorte del\u00a090%\u00a0en el que el valor presente de los pagos de la deuda del gobierno central despu\u00e9s de reestructurarse oscilar\u00eda entre\u00a0$3,588 y $3,993 millones. En el escenario base se propone un recorte del\u00a099%\u00a0en el que\u00a0el valor presente de los pagos de la deuda del Gobierno Central despu\u00e9s de reestructurarse oscilar\u00eda entre\u00a0$229 millones y $254 millones, y en el escenario pesimista se propone un recorte del\u00a0100%\u00a0en el que\u00a0el valor presente de los pagos de la deuda del gobierno central despu\u00e9s de reestructurarse ser\u00eda\u00a0$0\u201d, estim\u00f3 la organizaci\u00f3n.<\/p>\n<p>\u201cRecomendamos que el pr\u00f3ximo paso sea un reconocimiento t\u00e1cito de la imposibilidad del pago de la deuda ante la situaci\u00f3n de la pandemia mediante una moratoria de al menos un a\u00f1o, la eliminaci\u00f3n de las pol\u00edticas de austeridad, encaminar una reestructuraci\u00f3n con un an\u00e1lisis de sostenibilidad de la deuda que incluya los efectos del COVID-19, impulsar un plan macroecon\u00f3mico y actualizar los estados financieros auditados\u201d, concluy\u00f3 el economista.<\/p>","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n Espacios Abiertos ofreci\u00f3 sus recomendaciones ante el panorama que vive Puerto Rico tras varias crisis, incluyendo la del COVID-19. La posibilidad de una moratoria temporal en el pago de la deuda, un an\u00e1lisis de sostenibilidad de esta, y la eliminaci\u00f3n de medidas de austeridad son acciones contundentes que deber\u00edan tomarse por parte del [&hellip;]<\/p>","protected":false},"author":0,"featured_media":532512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22,4],"tags":[],"class_list":["post-134482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-gobierno"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/134482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=134482"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/134482\/revisions"}],"predecessor-version":[{"id":532513,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/134482\/revisions\/532513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/532512"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=134482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=134482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=134482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}