{"id":134410,"date":"2020-05-18T17:31:00","date_gmt":"2020-05-18T21:31:00","guid":{"rendered":"https:\/\/www.noticel.com\/article\/20200518\/proponen-revisar-todas-las-convicciones-de-juicios-sin-veredicto-unanime\/"},"modified":"2025-07-20T04:15:41","modified_gmt":"2025-07-20T04:15:41","slug":"proponen-revisar-todas-las-convicciones-de-juicios-sin-veredicto-unanime","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20200518\/proponen-revisar-todas-las-convicciones-de-juicios-sin-veredicto-unanime\/","title":{"rendered":"Proponen revisar todas las convicciones de juicios sin veredicto un\u00e1nime"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"Proponen revisar todas las convicciones de juicios sin veredicto un\u00e1nime\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/X76vQj1097U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>A tono con las recientes decisiones del Tribunal Supremo de Estados Unidos y el de Puerto Rico en torno a los juicios por jurado, el presidente del Senado, Thomas Rivera Schatz, radic\u00f3 el Proyecto del Senado 1590 para que los jurados tengan que rendir veredictos un\u00e1nimes para encontrar culpables a los acusados.<\/p><div class=\"notic-content-middle\" id=\"notic-3022452907\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>A tono con las recientes decisiones del Tribunal Supremo de Estados Unidos y el de Puerto Rico en torno a los juicios por jurado, el presidente del Senado, Thomas Rivera Schatz, radic\u00f3 el Proyecto del Senado 1590 para que los jurados tengan que rendir veredictos un\u00e1nimes para encontrar culpables a los acusados.<\/p>","protected":false},"author":0,"featured_media":532608,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-134410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/134410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=134410"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/134410\/revisions"}],"predecessor-version":[{"id":532610,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/134410\/revisions\/532610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/532608"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=134410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=134410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=134410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}