{"id":133536,"date":"2020-05-06T06:00:00","date_gmt":"2020-05-06T10:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=133536"},"modified":"2025-07-20T05:33:40","modified_gmt":"2025-07-20T05:33:40","slug":"aumentan-las-cremaciones-y-mas-personas-mueren-en-sus-hogares","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200506\/aumentan-las-cremaciones-y-mas-personas-mueren-en-sus-hogares\/","title":{"rendered":"Aumentan las cremaciones y m\u00e1s personas mueren en sus hogares"},"content":{"rendered":"<h3>Mientras disminuyen los homicidios, seg\u00fan los datos del Negociado de Ciencias Forenses.<\/h3>\n<p>Desde que la amenaza del coronavirus asom\u00f3 en la Isla, las cremaciones empezaron a multiplicarse en un pa\u00eds que lentamente se despoja del ritual de enterrar a sus muertos.<\/p>\n<p>La comisionada del Negociado de\u00a0Ciencias Forenses\u00a0(NCF),\u00a0Mar\u00eda Conte\u00a0Miller, confirm\u00f3 a NotiCel que en los pasados dos meses las incineraciones aumentaron en un 43 por ciento.<\/p>\n<p>Hubo 1,449 cremaciones del 15 de marzo al 5 de mayo (ayer) en comparaci\u00f3n con 1,011 para la misma fecha el a\u00f1o pasado, seg\u00fan los datos del NCF.  Del 1 de enero al 5 de mayo, fueron cremados 3,207 cuerpos, comparado con 2,707 durante la misma fecha el a\u00f1o pasado.<\/p>\n<p>\u201cEste cambio s\u00fabito coincide con este periodo de la cuarentena\u201d, respondi\u00f3 Conte Miller sobre la raz\u00f3n para el incremento. \u201cLos velatorios se restringieron a tres personas\u201d, agreg\u00f3.<\/p>\n<p>A pesar del aumento en las cremaciones, en la Isla todav\u00eda no se creman ni la mitad de las personas que mueren. Seg\u00fan el Registro Demogr\u00e1fico, en Puerto Rico fallecen unas 2,500 personas al mes.<\/p>\n<p>Conte Miller se\u00f1al\u00f3 que quiz\u00e1s la incertidumbre generalizada por la pandemia y esa limitaci\u00f3n de tiempo para despedir a sus muertos llev\u00f3 a muchas familias a optar por la cremaci\u00f3n, un m\u00e9todo que el Departamento de Salud recomend\u00f3 para disponer de los cuerpos de personas contagiadas o sospechosas de haber padecido el peligroso virus al momento de su deceso.<\/p>\n<p>Hasta el momento, el NCF ha realizado 64 pruebas diagn\u00f3sticas post mortem. Cuatro arrojaron un resultado positivo a COVID-19 y 58 resultaron negativas. Los resultados de dos pruebas quedan pendientes.<\/p><div class=\"notic-content-middle\" id=\"notic-1512912671\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>En momentos que las estad\u00edsticas oficiales se miran con sospecha, Conte Miller asegur\u00f3 que la informaci\u00f3n que ofrece el Negociado es confiable porque esta dependencia autoriza todas las cremaciones.<\/p>\n<p>\u201cIndependientemente de la causa de muerte, todo caso que vaya a ser creamado tiene que someter una  documentaci\u00f3n. El cad\u00e1ver no llega a Forense, pero se requiere una documentaci\u00f3n post-forense, que el pat\u00f3logo forense eval\u00faa junto al certificado de defunci\u00f3n para dar el &#8216;okay&#8217;\u201d, indic\u00f3.<\/p>\n<p>Pero no solo se trata de un aumento en las cremaciones. Las estad\u00edsticas del NCF tambi\u00e9n revelan que m\u00e1s personas han muerto en sus hogares.<\/p>\n<p>Desde marzo al presente, 150 personas fallecieron en sus hogares, una cifra superior a los 97 que murieron en su casa el a\u00f1o pasado para el mismo periodo.<\/p>\n<p>\u201cLa raz\u00f3n por la cual llegan a Forense esas personas que fallecen en sus hogares de muerte natural es porque no hay un m\u00e9dico que certifique la muerte. A estos casos, no se le practica autopsia. Nuestros m\u00e9dicos forenses realizan un examen externo del cad\u00e1ver y ellos certifican esas muertes. No interviene un pat\u00f3logo\u201d, precis\u00f3 sobre el proceso de manejo de las muertes naturales.<\/p>\n<p>Por otro lado, el rengl\u00f3n de las muertes violentas baj\u00f3.<\/p>\n<p>Conte Miller apunt\u00f3 que las muertes violentas disminuyeron desde que la gobernadora Wanda V\u00e1zquez Garced decret\u00f3 un toque de queda el pasado 15 de marzo para paliar la crisis de salud p\u00fablica. Se\u00f1al\u00f3 que entre marzo y abril del a\u00f1o pasado el NCF realiz\u00f3 autopsias en 109 casos de homicidios, pero este a\u00f1o practic\u00f3 63 para la misma fecha.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mientras disminuyen los homicidios, seg\u00fan los datos del Negociado de Ciencias Forenses. Desde que la amenaza del coronavirus asom\u00f3 en la Isla, las cremaciones empezaron a multiplicarse en un pa\u00eds que lentamente se despoja del ritual de enterrar a sus muertos. La comisionada del Negociado de\u00a0Ciencias Forenses\u00a0(NCF),\u00a0Mar\u00eda Conte\u00a0Miller, confirm\u00f3 a NotiCel que en los pasados [&hellip;]<\/p>","protected":false},"author":0,"featured_media":533372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-133536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/133536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=133536"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/133536\/revisions"}],"predecessor-version":[{"id":533373,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/133536\/revisions\/533373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/533372"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=133536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=133536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=133536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}