{"id":132890,"date":"2013-10-20T11:22:21","date_gmt":"2013-10-20T15:22:21","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20131020\/tenis-breves-airosos-haas-woszniaki-y-gasquet\/"},"modified":"2025-08-22T07:19:30","modified_gmt":"2025-08-22T07:19:30","slug":"tenis-breves-airosos-haas-woszniaki-y-gasquet","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20131020\/tenis-breves-airosos-haas-woszniaki-y-gasquet\/","title":{"rendered":"Tenis breves: Airosos Haas, Woszniaki y Gasquet"},"content":{"rendered":"<p>Varios torneos de calidad internacional concluyeron esta madrugada en Europa.<\/p>\n<p>El alem\u00e1n Tommy Haas, segundo cabeza de serie, logr\u00f3 hoy su segundo t\u00edtulo de la temporada al derrotar al holand\u00e9s Robin Haase en la final del torneo de Viena, disputado sobre pista dura bajo techo.<\/p>\n<p>Haas, de 35 a\u00f1os y que este a\u00f1o gan\u00f3 el torneo de M\u00fanich, bati\u00f3 a Haase por 6-3, 4-6 y 6-4 en dos horas y cinco minutos.<\/p>\n<p>La de hoy ha sido la primera vez que ambos tenistas se enfrentaban.<\/p>\n<p>En total, el veterano tenista germano suma ya quince t\u00edtulos ATP en su palmar\u00e9s.<\/p>\n<p><strong>Wozniacki gana en Luxemburgo<\/strong><\/p><div class=\"notic-content-middle\" id=\"notic-4154548852\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>La danesa Caroline Wozniacki, primera cabeza de serie, gan\u00f3 hoy su primer t\u00edtulo de la temporada al derrotar a la alemana Annika Beck en la final del torneo de Luxemburgo.<\/p>\n<p>La danesa, que ya acumula 21 t\u00edtulos en sus vitrinas, bati\u00f3 a Beck por un doble 6-2 en una hora y catorce minutos. Ahora viaja a Estambul en previsi\u00f3n de cubrir una eventual baja que le permita jugar el Masters femenino.<\/p>\n<p><strong>Franc\u00e9s Gasquetdomina en Mosc\u00fa<\/strong><\/p>\n<p>El franc\u00e9s Richard Gasquet, cabeza de serie n\u00famero uno, se adjudic\u00f3 el t\u00edtulo en el torneo de Mosc\u00fa al vencer en la final al kazako Mikhail Kukushkin por 4-6, 6-4 y 6-4 tras casi dos horas y media de partido.<\/p>\n<p>Kukushkin, procedente de la previa, se acerc\u00f3 mucho a la victoria pero Gasquet finalmente impuso su mayor experiencia y mejor r\u00e1nking para conseguir el tercer t\u00edtulo del a\u00f1o y el d\u00e9cimo de su carrera deportiva.<\/p>\n<p>Con anterioridad, ambos tenistas se hab\u00edan enfrentado en una ocasi\u00f3n, el a\u00f1o pasado en Masters 1000 de Canad\u00e1, tambi\u00e9n con victoria del tenista franc\u00e9s.<\/p>","protected":false},"excerpt":{"rendered":"<p>Varios torneos de calidad internacional concluyeron esta madrugada en Europa. El alem\u00e1n Tommy Haas, segundo cabeza de serie, logr\u00f3 hoy su segundo t\u00edtulo de la temporada al derrotar al holand\u00e9s Robin Haase en la final del torneo de Viena, disputado sobre pista dura bajo techo. Haas, de 35 a\u00f1os y que este a\u00f1o gan\u00f3 el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":888272,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-132890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=132890"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132890\/revisions"}],"predecessor-version":[{"id":888283,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132890\/revisions\/888283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/888272"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=132890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=132890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=132890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}