{"id":132877,"date":"2014-02-09T09:00:31","date_gmt":"2014-02-09T13:00:31","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20140209\/tiempo-mayormente-seco-para-el-domingo\/"},"modified":"2025-08-20T09:37:52","modified_gmt":"2025-08-20T09:37:52","slug":"tiempo-mayormente-seco-para-el-domingo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20140209\/tiempo-mayormente-seco-para-el-domingo\/","title":{"rendered":"Tiempo mayormente seco para el domingo"},"content":{"rendered":"<p>Cielos mayormente despejados prevalecieron a trav\u00e9s de Puerto Rico, Culebra y Vieques durante las horas de la noche del s\u00e1bado y la madrugada del domingo.<\/p>\n<p>S\u00f3lo algunas nubes y aguaceros pasajeros fueron detectados por el radar doppler a trav\u00e9s de las aguas regionales.<\/p>\n<p>Durante la madrugada no se observ\u00f3 lluvia sobre las islas.<\/p>\n<p>Los vientos sobre tierra estuvieron generalmente leves y variables.<\/p>\n<p>Fragmentos de humedad incrustada en los vientos alisios continuar\u00e1n transportando nubes y aguaceros de leves a moderados sobre las aguas costeras y porciones de las islas hasta por lo menos el lunes.<\/p><div class=\"notic-content-middle\" id=\"notic-2667737138\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>La humedad disminuir\u00e1 significativamente el martes y mi\u00e9rcoles.<\/p>\n<p>Esto permitir\u00e1 mas sol y menos actividad de aguaceros a trav\u00e9s de las islas.<\/p>\n<p>A trav\u00e9s de las aguas costeras, se espera oleaje de tres a seis pies y vientos de doce a 17 nudos se pueden esperar hasta la noche del domingo.<\/p>\n<p>Los navegantes deben ejercer precauci\u00f3n a trav\u00e9s de las aguas del Atl\u00e1ntico mar afuera debido al oleaje de seis pies.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cielos mayormente despejados prevalecieron a trav\u00e9s de Puerto Rico, Culebra y Vieques durante las horas de la noche del s\u00e1bado y la madrugada del domingo. S\u00f3lo algunas nubes y aguaceros pasajeros fueron detectados por el radar doppler a trav\u00e9s de las aguas regionales. Durante la madrugada no se observ\u00f3 lluvia sobre las islas. Los vientos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":881482,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-132877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=132877"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132877\/revisions"}],"predecessor-version":[{"id":881508,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132877\/revisions\/881508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/881482"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=132877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=132877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=132877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}