{"id":132803,"date":"2017-01-10T19:08:00","date_gmt":"2017-01-10T23:08:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20170110\/obama-y-trump-se-reuniran-poco-antes-de-la-investidura-para-tomar-un-cafe\/"},"modified":"2025-07-21T17:34:05","modified_gmt":"2025-07-21T17:34:05","slug":"obama-y-trump-se-reuniran-poco-antes-de-la-investidura-para-tomar-un-cafe","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20170110\/obama-y-trump-se-reuniran-poco-antes-de-la-investidura-para-tomar-un-cafe\/","title":{"rendered":"Obama y Trump se reunir\u00e1n poco antes de la investidura para &#8216;tomar un caf\u00e9&#8217;"},"content":{"rendered":"<p>El presidente de EE.UU., Barack Obama, y su sucesor en la Casa Blanca, Donald Trump, se reunir\u00e1n brevemente para &#8216;tomar un cafe&#8217; poco antes de la ceremonia de investidura del pr\u00f3ximo d\u00eda 20, informaron hoy fuentes oficiales.<\/p>\n<p>&#8216;(Los Obama) han sido muy amables enviando una invitaci\u00f3n para tomar un caf\u00e9 o un t\u00e9 por la ma\u00f1ana&#8217;, confirm\u00f3 a la prensa el presidente del Comit\u00e9 de la Investidura Presidencial, Tom Barrack.<\/p>\n<p>&#8216;Ir\u00e1n a la Casa Blanca (&#8230;) estar\u00e1n ah\u00ed media hora aproximadamente, y luego ir\u00e1n juntos (a la ceremonia de investidura)&#8217;, explic\u00f3 Barrack.El portavoz se\u00f1al\u00f3 asimismo que Trump no contar\u00e1 con la presencia de personajes famosos durante el evento, lo que achac\u00f3 a querer evitar que la proclamaci\u00f3n adquiera &#8216;caracter\u00edsticas circenses&#8217;.<\/p>\n<p>&#8216;Le vamos a rodear de la suave sensualidad del lugar. (&#8230;) Eso es lo que quer\u00eda el presidente electo. Va a ser muy bonito&#8217;, apunt\u00f3 Barrack, que concret\u00f3 que Trump seguir\u00e1 en su mayor parte las tradiciones de otras investiduras.<\/p>\n<p>Los eventos oficiales del acto de proclamaci\u00f3n empezar\u00e1n el 19 de enero con una visita de Trump y su vicepresidente, Mike Pence, al Cementerio Nacional de Arlington, seguido de un concierto de bienvenida.<\/p>\n<p>El viernes, d\u00eda 20, Trump y Pence jurar\u00e1n sus respectivos cargos en el Capitolio de la capital estadounidense, sede del Congreso federal.<\/p>\n<p>Ambos participar\u00e1n despu\u00e9s tanto en el tradicional desfile por la c\u00e9ntrica Avenida de Pensilvania, desde el Capitolio hasta la Casa Blanca, como en los bailes de investidura.<\/p>\n<p>Ya el s\u00e1bado, los nuevos presidente y vicepresidente de EE.UU. asistir\u00e1n a un servicio religioso en la Catedral Nacional de Washington, que pondr\u00e1 fin a los actos oficiales de la investidura.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente de EE.UU., Barack Obama, y su sucesor en la Casa Blanca, Donald Trump, se reunir\u00e1n brevemente para &#8216;tomar un cafe&#8217; poco antes de la ceremonia de investidura del pr\u00f3ximo d\u00eda 20, informaron hoy fuentes oficiales. &#8216;(Los Obama) han sido muy amables enviando una invitaci\u00f3n para tomar un caf\u00e9 o un t\u00e9 por la [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-132803","post","type-post","status-publish","format-standard","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=132803"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132803\/revisions"}],"predecessor-version":[{"id":547527,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132803\/revisions\/547527"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=132803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=132803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=132803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}