{"id":132383,"date":"2020-05-01T10:51:00","date_gmt":"2020-05-01T14:51:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/economia\/top-stories\/20200501\/para-el-lunes-las-guias-que-certificaran-que-los-comercios-operan-adecuadamente\/"},"modified":"2025-07-20T06:09:06","modified_gmt":"2025-07-20T06:09:06","slug":"para-el-lunes-las-guias-que-certificaran-que-los-comercios-operan-adecuadamente","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200501\/para-el-lunes-las-guias-que-certificaran-que-los-comercios-operan-adecuadamente\/","title":{"rendered":"Para el lunes las gu\u00edas que certificar\u00e1n que los comercios operan adecuadamente"},"content":{"rendered":"<h3>Es parte de los criterios de la reapertura escalonada de la econom\u00eda y que busca evitar un brote de coronavirus.<\/h3>\n<p>El secretario del Departamento de Desarrollo Econ\u00f3mico y Comercio (DDEC), Manuel Laboy inform\u00f3 que a partir del lunes, 4 de mayo tendr\u00e1n listas las gu\u00edas que los comercios deben cumplir para garantizar una operaci\u00f3n adecuada de sus operaciones sin poner el riesgo la salud de empleados y clientes como parte de la reapertura escalonada de la econom\u00eda.<\/p>\n<p>Anoche la gobernadora Wanda V\u00e1zquez Garced anunci\u00f3 un regreso gradual a las actividades diarias y econ\u00f3micas a partir del pr\u00f3ximo 4 de mayo cuando entrar\u00eda en vigor la nueva Orden Ejecutiva, que flexibiliza el toque de queda y el cierre de negocios decretados el pasado 14 de marzo.<\/p>\n<p>\u201cEs algo que se discuti\u00f3 bastante en el \u2018Task Force\u2019 Econ\u00f3mico y en el \u2018Task Force\u2019 M\u00e9dico y por eso a partir del lunes vamos a tener una serie de gu\u00edas que estar\u00e1n disponibles en nuestra p\u00e1gina cibern\u00e9tica del Departamento de Desarrollo Econ\u00f3mico como en el Departamento del Trabajo para facilitarle el proceso a los peque\u00f1os comerciantes, que usualmente son los que necesitan alg\u00fan tipo de asistencia en este tipo de asunto. Se han preparado unas gu\u00edas bien sencillas para que se puedan cumplir\u201d, afirm\u00f3 Laboy en entrevista radial (NotiUno).<\/p>\n<p>Detall\u00f3 que las gu\u00edas se podr\u00e1n descargar en las p\u00e1ginas antes mencionadas para aplicarlas y completar un formulario de certificaci\u00f3n que debe remitirse por correo electr\u00f3nico al Departamento del Trabajo.<\/p>\n<p>\u201cConfiamos que los negocios que van a estar abriendo a partir del lunes conforme a la Orden Ejecutiva de la gobernadora, tienen que implementar los protocolos, tienen que implementar las medidas de mitigaci\u00f3n conforme las gu\u00edas que correspondan, se somete la autocertificaci\u00f3n. Creo que los propios empleados y ciudadan\u00eda y la responsabilidad del patrono van a velar que sea as\u00ed\u201d, afirm\u00f3 el funcionario.<\/p><div class=\"notic-content-middle\" id=\"notic-1634859942\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Entretanto, Laboy indic\u00f3 que a\u00fan faltan cerca de 5,000 peque\u00f1os comercios que no han recibido el incentivo de $500. Al momento, han desembolsado $50 de los $60 millones destinados para esta ayuda. Adelant\u00f3 que la agencia espera poder anunciar una segunda ronda de la ayuda federal.<\/p>\n<p>\u201cEstamos hablando con la Aafaf (Autoridad de Asesor\u00eda Financiera y Agencia Fiscal) y con la Junta de Control Fiscal porque parte del dinero del CARES Act permite que tambi\u00e9n podamos dar dinero a los peque\u00f1os negocios y estamos ya finiquitando una propuesta para ver si tenemos una segunda ronda con ese dinero y ayudar con m\u00e1s incentivos. La oportunidad existe y las gu\u00edas del Tesoro Federal lo permiten\u201d, asegur\u00f3.<\/p>\n<p>Indic\u00f3 tambi\u00e9n que como parte del incentivo de prevenci\u00f3n de cesant\u00edas el gobierno otorgar\u00e1 reembolsos de hasta $50,000 por gastos extraordinarios. Para esto, se han procesado cerca de 500 solicitudes. El presupuesto para este incentivo es de $8 millones.<\/p>\n<p>Laboy se\u00f1al\u00f3 que estimados de economistas calculan que existe un riesgo real de que cerca del 20 por ciento de los peque\u00f1os comercios desaparezca como consecuencia de la crisis econ\u00f3mica creada por el COVID-19, al igual que en Estados Unidos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Es parte de los criterios de la reapertura escalonada de la econom\u00eda y que busca evitar un brote de coronavirus. El secretario del Departamento de Desarrollo Econ\u00f3mico y Comercio (DDEC), Manuel Laboy inform\u00f3 que a partir del lunes, 4 de mayo tendr\u00e1n listas las gu\u00edas que los comercios deben cumplir para garantizar una operaci\u00f3n adecuada [&hellip;]<\/p>","protected":false},"author":0,"featured_media":533699,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22,2],"tags":[],"class_list":["post-132383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=132383"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132383\/revisions"}],"predecessor-version":[{"id":533700,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132383\/revisions\/533700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/533699"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=132383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=132383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=132383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}