{"id":132084,"date":"2017-02-13T14:55:00","date_gmt":"2017-02-13T18:55:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20170213\/la-probabilidad-de-una-destitucion-temprana-de-trump-sube-en-las-apuestas\/"},"modified":"2025-07-23T02:02:30","modified_gmt":"2025-07-23T02:02:30","slug":"la-probabilidad-de-una-destitucion-temprana-de-trump-sube-en-las-apuestas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20170213\/la-probabilidad-de-una-destitucion-temprana-de-trump-sube-en-las-apuestas\/","title":{"rendered":"La probabilidad de una destituci\u00f3n temprana de Trump sube en las apuestas"},"content":{"rendered":"<p>Las probabilidades de que el presidente de Estados Unidos, Donald Trump, renuncie al puesto o sea destituido antes del fin de su mandato han aumentado en la casa de apuestas brit\u00e1nica Ladbrokes, que hoy fija esa posibilidad en un 48 % (11 contra 10).<\/p>\n<p>Tres semanas despu\u00e9s de la investidura del magnate republicano, la irlandesa Paddy Power calcula en un 20 % (4 contra 1) las opciones de que el Congreso estadounidense realice este mismo a\u00f1o un &#8216;impeachment&#8217;, o juicio pol\u00edtico, que acabe con su mandato antes de tiempo.<\/p>\n<p>&#8216;Trump asegura que acabar\u00e1 su trabajo, pero el dinero sugiere lo contrario. Quienes apuestan no est\u00e1n del todo convencidos de que los pr\u00f3ximos cuatro a\u00f1os vayan a ser f\u00e1ciles y creen que podr\u00eda estar fuera de la Casa Blanca, por un &#8216;impeachment&#8217; o una renuncia, m\u00e1s pronto que tarde&#8217;, dijo a Efe Jessica Bridge, portavoz de Ladbrokes.<\/p>\n<p>Seg\u00fan los c\u00e1lculos de la casa de apuestas, las probabilidades de que el presidente de Estados Unidos no finalice su mandato han ido en aumento desde que gan\u00f3 las elecciones a principios de noviembre, cuando las opciones de una retirada temprana se valoraban en el 25 % (3 a 1).<\/p>\n<p>Algunas firmas han abierto secciones de apuestas &#8216;especiales&#8217; sobre el presidente, que ha aprobado en sus primeros d\u00edas de mandato medidas pol\u00e9micas como el veto migratorio a los nacionales de siete pa\u00edses de mayor\u00eda musulmana.<\/p><div class=\"notic-content-middle\" id=\"notic-3092060337\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Los jugadores de Ladbrokes ven m\u00e1s probable que el republicano visite este a\u00f1o el Reino Unido (78 % de posibilidades), que Rusia (45 %), y creen que, en caso de acabar su mandato, no ser\u00e1 reelegido en 2020, con una probabilidad del 67 %.<\/p>\n<p>Apostar por que Trump se mantendr\u00e1 al frente de Estados Unidos hasta 2024 aportar\u00eda a un jugador 50 libras (58,5 euros) para cada libra apostada (1,17 euros), dado que las posibilidades de que eso ocurra est\u00e1n situadas en el 2 %.<\/p>\n<p>Seg\u00fan los usuarios de la casa Paddy Power, la primera visita de Estado de Trump ser\u00e1 a Eslovenia (35 % de posibilidades), pa\u00eds de origen de la primera dama, Melania Trump.<\/p>\n<p>Una primera visita a Canad\u00e1 se paga a 10 contra 3 (un 23 %), a M\u00e9xico a 7 contra 1 (12,5 %) y a China 12 contra 2 (8 %).<\/p>\n<p>Por otra parte, el principal favorito para ser el primero en abandonar el equipo de Trump es el portavoz de la Casa Blanca, Sean Spicer, cuyo despido se paga a cuatro libras por cada libra apostada (20 % de posibilidades).<\/p>","protected":false},"excerpt":{"rendered":"<p>Las probabilidades de que el presidente de Estados Unidos, Donald Trump, renuncie al puesto o sea destituido antes del fin de su mandato han aumentado en la casa de apuestas brit\u00e1nica Ladbrokes, que hoy fija esa posibilidad en un 48 % (11 contra 10). Tres semanas despu\u00e9s de la investidura del magnate republicano, la irlandesa [&hellip;]<\/p>","protected":false},"author":0,"featured_media":561917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-132084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=132084"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132084\/revisions"}],"predecessor-version":[{"id":561918,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/132084\/revisions\/561918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/561917"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=132084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=132084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=132084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}