{"id":131494,"date":"2016-12-19T21:31:00","date_gmt":"2016-12-20T01:31:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/educacion\/gobierno\/upr\/20161219\/recortaran-programas-repetitivos-en-la-upr\/"},"modified":"2025-07-21T17:36:55","modified_gmt":"2025-07-21T17:36:55","slug":"recortaran-programas-repetitivos-en-la-upr","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20161219\/recortaran-programas-repetitivos-en-la-upr\/","title":{"rendered":"Recortar\u00e1n &#8216;programas repetitivos&#8217; en la UPR"},"content":{"rendered":"<p>Antes de culminar el a\u00f1o, la Universidad de Puerto Rico (UPR) tendr\u00e1 un nuevo plan estrategico que trazar\u00e1 el rumbo de esa instituci\u00f3n hasta el 2022 y que podr\u00eda ir acompa\u00f1ado de una eliminaci\u00f3n de &#8216;programas repetitivos&#8217; entre recintos en aras de producir ahorros.<\/p>\n<p>Seg\u00fan declar\u00f3 la presidenta interina de la UPR, Celeste Freytes, ante el Comit\u00e9 de Transici\u00f3n, el plan en s\u00ed redundar\u00eda en ahorros en la medida que puedan identificar estos cursos.<\/p>\n<p>&#8216;Es un proceso que no se puede completar como uno lo quisiera de la noche a la ma\u00f1ana pero ciertamente es el sitio donde comenzar. Hay programas repetidos de un recinto a otro&#8217;, declar\u00f3 durante el \u00faltimo d\u00eda de las vistas de transici\u00f3n.<\/p>\n<p>Su respuesta fue recibida con escepticismo por parte del miembro del Comit\u00e9 Entrante, Ram\u00f3n Rosario, quien insisti\u00f3 si la instituci\u00f3n ha hecho una evaluaci\u00f3n profunda para identificar mejoras a su operaci\u00f3n fiscal m\u00e1s all\u00e1 de revisar su oferta acad\u00e9mica. No obstante,Freytesdefendi\u00f3 la elaboraci\u00f3n del plan y se\u00f1al\u00f3 que a fin de cuentas el plan se tendr\u00e1 que ajustar al presupuesto de laUPR.<\/p>\n<p>La Junta de Gobierno de la UPR tuvo ante su consideraci\u00f3n el lunes el plan estrat\u00e9gico titulado <em>Una Nueva Era de Innovaci\u00f3n y Transformaci\u00f3n para el \u00c9xito Estudiantil<\/em>. El mismo cubre cuatro \u00e1reas para desarrollar: Ambiente educativo, investigaci\u00f3n y creaci\u00f3n, tecnolog\u00eda y sostenibilidad fiscal y fue sometido a la consideraci\u00f3n de la Junta el lunes. Su implementaci\u00f3n podr\u00eda tardar entre seis meses y un a\u00f1o seg\u00fanFreytes.<\/p><div class=\"notic-content-middle\" id=\"notic-4110483238\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Nosotros tenemos que coger ahora este plan y ajustarlo al presupuesto porque eso es requerido por las agencias acreditadoras. No podemos tener un plan alejado del presupuesto&#8217; sentenci\u00f3 la presidenta.<\/p>\n<p>En cuanto el pago de las obligaciones de la instituci\u00f3n el director de finanzas de la administraci\u00f3n central de la UPR, Norberto Gonz\u00e1lez P\u00e9rez, advirti\u00f3 que de suscitarse otra situaci\u00f3n de falta de liquidez en el gobierno central, la UPR se arriesga a incumplir con sus obligaciones con suplidores, que asegur\u00f3 al presente est\u00e1n al d\u00eda.<\/p>\n<p>Por otra parte, afirm\u00f3 que dentro el presupuesto de la instituci\u00f3n se presupuest\u00f3 una partida de $64 millones correspondiente al pago de sus bonos, pero debido a la activaci\u00f3n de estado de emergencia que implement\u00f3 la Fortaleza a la UPR por virtud de la Ley de Moratoria, no pueden emitir dicho pago.<\/p>\n<p>Para continuar cumpliendo con sus bonistas, la administraci\u00f3n opt\u00f3 por separar de manera contable parte de sus ingresos por concepto de matr\u00edcula que suponen ir al pago a acreedores. Esta acci\u00f3n oblig\u00f3 a los dos fideicomisos encargados con ejecutar este pago, US Bank y Bank of New York Mellon, a desembolsar fondos de sus cuentas de reserva para sufragar este pago.<\/p>\n<p>Cuando venza el periodo de moratoria el pr\u00f3ximo mes de febrero, Gonz\u00e1lez P\u00e9rez indic\u00f3 que se aprestan a pagar la cantidad adeudad con los fondos separados.<\/p>","protected":false},"excerpt":{"rendered":"<p>Antes de culminar el a\u00f1o, la Universidad de Puerto Rico (UPR) tendr\u00e1 un nuevo plan estrategico que trazar\u00e1 el rumbo de esa instituci\u00f3n hasta el 2022 y que podr\u00eda ir acompa\u00f1ado de una eliminaci\u00f3n de &#8216;programas repetitivos&#8217; entre recintos en aras de producir ahorros. Seg\u00fan declar\u00f3 la presidenta interina de la UPR, Celeste Freytes, ante [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-131494","post","type-post","status-publish","format-standard","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/131494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=131494"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/131494\/revisions"}],"predecessor-version":[{"id":547970,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/131494\/revisions\/547970"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=131494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=131494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=131494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}