{"id":131412,"date":"2011-08-07T14:00:00","date_gmt":"2011-08-07T18:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20110807\/una-ciudad-donde-solo-se-trabaja\/"},"modified":"2025-08-28T16:05:53","modified_gmt":"2025-08-28T16:05:53","slug":"una-ciudad-donde-solo-se-trabaja","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20110807\/una-ciudad-donde-solo-se-trabaja\/","title":{"rendered":"Una ciudad donde solo se trabaja"},"content":{"rendered":"<p>Sin saber con que se encontrar\u00eda, la artista puertorrique\u00f1a Beatriz Santiago Mu\u00f1oz, junto a otro ocho artistas que no conoc\u00eda, se lanz\u00f3 por un mes a la regi\u00f3n R\u00edo Grande do Sul para documentar la pieza que presentar\u00e1 en la Bienal de MercoSur que se celebra en Brasil.<\/p>\n<p>Antes de llegar a Caxias do Sul, donde hace unos meses el curador de la Bienal Jos\u00e9 Roca la invit\u00f3 a trabajar su documental, Santiago Mu\u00f1oz hab\u00eda intentado conocer un poco sobre la cuidad. Sin embargo, a su llegada los proyectos que hab\u00eda visualizado cambiaron por la forma en que la industrializaci\u00f3n domina la vida de ese pueblo brasile\u00f1o.<\/p>\n<p>&#8216;La manera en que Caxias do Sul se autorepresenta es muy distinta a la experiencia de estar all\u00ed f\u00edsicamente. Todo el mundo con que yo hablaba ten\u00eda algo que ver con las f\u00e1bricas. Si no trabajaba en una ten\u00eda un padre, un t\u00edo, hermano o hijo&#8217;, detall\u00f3 sobre el lugar que fue formado hace poco m\u00e1s de 100 a\u00f1os por inmigrantes italianos que llegaron sin nada al lugar que ahora habitan unas 500 mil personas.<\/p>\n<p>Seg\u00fan sostuvo Santiago Mu\u00f1oz, Folc Industrial se extiende por unos ocho minutos y estuvo inspirado en el hecho de que las f\u00e1bricas son el \u00fanico lugar que abre 24 horas al d\u00eda en la ciudad porque hay turnos corriendo todo el tiempo.<\/p>\n<p>&#8216;Es como las famosas im\u00e1genes de los hermanos Lumi\u00e9re que documentaron la salida de los obreros de la f\u00e1brica pero al mismo tiempo es diferente porque ya no es una salida para reunirse en espacios p\u00fablicos para ellos compartir como individuos y no empleados. Eso ya no existe. Los empleados salen de la f\u00e1brica y se van directo para su casa, a su espacio privado&#8217;, explic\u00f3 sobre su cortometraje.<\/p><div class=\"notic-content-middle\" id=\"notic-2384888098\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>De hecho, la cotidianidad est\u00e1 tan sumida en las &#8216;meta f\u00e1bricas&#8217; que no hay otras formas de subsistir, seg\u00fan denunciaron algunos m\u00fasicos a Santiago Mu\u00f1oz.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"664703967\" embed-content-groupid=\"593030475\" embed-content-id=\"664703967\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2011\/08\/07\/musicos_ciudad_trabajo_9500636_ver1.0_320_240.jpg\"\/><\/p>\n<p>&#8216;A los m\u00fasicos se les hace muy dif\u00edcil desarrollar su pr\u00e1ctica de m\u00fasicos porque la ciudad se auto define por esa idea del trabajador y le dan muy poca importancia a lo cultural, a las artes y a la m\u00fasica. Esto dificulta que el m\u00fasico tuviese una presencia y un di\u00e1logo p\u00fablico. Entonces lo que hice fue invitar a diferentes m\u00fasicos para hacer una banda sonora en vivo para lo que film\u00e9&#8217;, abund\u00f3 sobre la participaci\u00f3n de cinco m\u00fasicos en vivo como parte de una presentaci\u00f3n del cortometraje en el centro cultural de la ciudad.<\/p>\n<p>Santiago Mu\u00f1oz indic\u00f3 que los m\u00fasicos incluso participar\u00e1n en la Bienal que comenzar\u00e1 a partir de septiembre en la ciudad anfitriona de Porto Alegre, que ubica en la misma regi\u00f3n que Caxias do Sul. Esto, como parte del objetivo de los organizadores que persiguen descentralizar el evento y crear v\u00ednculos entre las ciudades y los artistas internacionales que exponen.<\/p>\n<p>Para la Bienal de MercoSur se ha coordinado la asistencia de unos 300 mil estudiantes de escuelas p\u00fablicas (en una ciudad que tiene la misma cantidad de habitantes que Puerto Rico) y con anticipaci\u00f3n se han ido entrenando unos 300 mediadores para atender al p\u00fablico con una perspectiva pedag\u00f3gica.<\/p>\n<p>Santiago Mu\u00f1oz actualmente tiene un trabajo exponi\u00e9ndose en el Museo Rufi\u00f1o Tamayo en M\u00e9xico. Tambi\u00e9n ha presentado su arte en Colombia, California y a nivel local.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sin saber con que se encontrar\u00eda, la artista puertorrique\u00f1a Beatriz Santiago Mu\u00f1oz, junto a otro ocho artistas que no conoc\u00eda, se lanz\u00f3 por un mes a la regi\u00f3n R\u00edo Grande do Sul para documentar la pieza que presentar\u00e1 en la Bienal de MercoSur que se celebra en Brasil. Antes de llegar a Caxias do Sul, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":925204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-131412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/131412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=131412"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/131412\/revisions"}],"predecessor-version":[{"id":925225,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/131412\/revisions\/925225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/925204"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=131412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=131412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=131412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}