{"id":131170,"date":"2020-04-17T14:16:00","date_gmt":"2020-04-17T18:16:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/negocio-de-la-salud\/20200417\/mascarillas-n95-podrian-reusarse-si-se-descontaminan\/"},"modified":"2025-07-20T07:22:07","modified_gmt":"2025-07-20T07:22:07","slug":"mascarillas-n95-podrian-reusarse-si-se-descontaminan","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200417\/mascarillas-n95-podrian-reusarse-si-se-descontaminan\/","title":{"rendered":"Mascarillas N95 podr\u00edan reusarse si se descontaminan"},"content":{"rendered":"<h3>Seg\u00fan estudio realizado por cient\u00edficos del Instituto Nacional de Salud<\/h3>\n<p>Aunque las mascarillas N95 est\u00e1n recomendadas para usarse una solo vez y desecharse, un estudio realizado por investigadores estadounidenses arroj\u00f3 que dichas mascarillas podr\u00edan reusarse hasta tres veces si se descontaminan adecuadamente.<\/p>\n<p>Las mascarillas N95 son utilizadas por m\u00e9dicos y personal hospitalario para evitar contagio del virus que causa el COVID-19.<\/p>\n<p>El estudio principal fue realizado por cient\u00edficos del Instituto Nacional de Salud (NIH, por sus siglas en ingl\u00e9s) en el Rocky Mountain Laboratories en Montana, quienes descontaminaron partes de una mascarilla N95 que hab\u00edan sido contaminadas con coronavirus.<\/p>\n<p>Los m\u00e9todos de descontaminaci\u00f3n incluyeron VHP (vaporized hydrogen peroxide), exponerla a una temperatura seca de 70 grados Celsius (158 grados Fahrenheit), luz ultravioleta y rociarla con un spray con 70% de etanol.<\/p><div class=\"notic-content-middle\" id=\"notic-4047542457\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Los investigadores descubrieron que los cuatro m\u00e9todos eliminaban el virus, pero algunos de ellos da\u00f1aban la mascarilla de alguna manera. El spray con etanol da\u00f1aba el sellado de la mascarilla en la cara luego de dos descontaminaciones por lo que no se recomend\u00f3 este m\u00e9todo.<\/p>\n<p>Las tratadas con calor y luz ultravioleta comenzaron a da\u00f1ar la m\u00e1scara luego de tres descontaminaciones, lo que sugiere que con esos m\u00e9todos la mascarilla se podr\u00eda reusar dos veces, pero el tratamiento de descontaminaci\u00f3n requiere un tratamiento de al menos una hora.<\/p>\n<p>Las tratadas con VHP no mostraron da\u00f1os, lo que llev\u00f3 a los investigadores a concluir que es el mejor m\u00e9todo porque tampoco ning\u00fan virus fue detectado luego de 10 minutos de tratamiento.<\/p>\n<p>El estudio fue rese\u00f1ado en la <a href=\"https:\/\/www.nih.gov\/news-events\/news-releases\/nih-study-validates-decontamination-methods-re-use-n95-respirators\" id=\"link-e458d87d4f5aa59244f496051373866c\" target=\"_blank\">p\u00e1gina web del NIH<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan estudio realizado por cient\u00edficos del Instituto Nacional de Salud Aunque las mascarillas N95 est\u00e1n recomendadas para usarse una solo vez y desecharse, un estudio realizado por investigadores estadounidenses arroj\u00f3 que dichas mascarillas podr\u00edan reusarse hasta tres veces si se descontaminan adecuadamente. Las mascarillas N95 son utilizadas por m\u00e9dicos y personal hospitalario para evitar contagio [&hellip;]<\/p>","protected":false},"author":0,"featured_media":530111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-131170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/131170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=131170"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/131170\/revisions"}],"predecessor-version":[{"id":534510,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/131170\/revisions\/534510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/530111"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=131170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=131170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=131170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}