{"id":130397,"date":"2017-04-25T07:05:00","date_gmt":"2017-04-25T11:05:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/junta-fiscal\/la-calle\/20170425\/grupo-de-manifestantes-se-revela-contra-la-jcf\/"},"modified":"2025-07-22T18:29:12","modified_gmt":"2025-07-22T18:29:12","slug":"grupo-de-manifestantes-se-revela-contra-la-jcf","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20170425\/grupo-de-manifestantes-se-revela-contra-la-jcf\/","title":{"rendered":"Grupo de manifestantes se revela contra la JCF"},"content":{"rendered":"<p>La Polic\u00eda de Puerto Rico inform\u00f3 hoy, martes, sobre una manifestaci\u00f3n que al momento se desarrolla en la carretera #1 frente al Jard\u00edn Bot\u00e1nico en R\u00edo Piedras.<\/p>\n<p>Seg\u00fan se indic\u00f3, en el \u00e1rea de la entrada de este lugar se encuentran aproximadamente 50 personas, quienes se manifiestanen contra de la Junta de Control Fiscal (JCF) y las medidas que este ente creado mediante la Ley Promesa por el Congreso ha impulsado para Puerto Rico.<\/p>\n<p>Al momento, personal de la uniformada se moviliza al lugar.<\/p><div class=\"notic-content-middle\" id=\"notic-1965450474\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Asimismo, seg\u00fan reporta NotiUno, manifestantes encapuchados no dejan entrar personal del Jard\u00edn Bot\u00e1nico a sus labores.<\/p>\n<p>Pendientes a NotiCel para ampliaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda de Puerto Rico inform\u00f3 hoy, martes, sobre una manifestaci\u00f3n que al momento se desarrolla en la carretera #1 frente al Jard\u00edn Bot\u00e1nico en R\u00edo Piedras. Seg\u00fan se indic\u00f3, en el \u00e1rea de la entrada de este lugar se encuentran aproximadamente 50 personas, quienes se manifiestanen contra de la Junta de Control Fiscal (JCF) [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,2],"tags":[],"class_list":["post-130397","post","type-post","status-publish","format-standard","hentry","category-la-calle","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/130397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=130397"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/130397\/revisions"}],"predecessor-version":[{"id":558475,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/130397\/revisions\/558475"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=130397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=130397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=130397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}