{"id":129980,"date":"2020-04-08T15:54:00","date_gmt":"2020-04-08T19:54:00","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20200408\/florida-ya-tiene-mas-de-300-muertes-por-covid-19\/"},"modified":"2025-07-20T08:28:18","modified_gmt":"2025-07-20T08:28:18","slug":"florida-ya-tiene-mas-de-300-muertes-por-covid-19","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20200408\/florida-ya-tiene-mas-de-300-muertes-por-covid-19\/","title":{"rendered":"Florida ya tiene m\u00e1s de 300 muertes por COVID-19"},"content":{"rendered":"<h3>El principal foco de infecci\u00f3n sigue estando en el condado de Miami Dade.<\/h3>\n<p>Los casos confirmados de COVID-19 en Florida desde que en marzo pasado la pandemia lleg\u00f3 a este estado aumentaron a 15,456 y las muertes a 309, lo que significa 709 casos y 13 muertes m\u00e1s que el martes, seg\u00fan las autoridades de salud.<\/p>\n<p>Las hospitalizaciones tambi\u00e9n subieron, de 1,893 a 1,955, y el principal foco de la pandemia en Florida sigue estando en el sur del estado, con el condado de Miami-Dade a la cabeza.<\/p>\n<p>Aunque es donde hay un mayor n\u00famero de casos en Florida (5,334), seguido de Broward (2,358), Miami-Dade no es donde m\u00e1s muertes se han producido por el coronavirus SARS-CoV-2.<\/p>\n<p>El condado de Palm Beach, tambi\u00e9n en la costa sureste del estado aunque m\u00e1s al norte que Miami-Dade, es el primero de la lista en este apartado, con 69 personas fallecidas de un total de 1,206 casos confirmados de la enfermedad.<\/p>\n<p>En Miami-Dade han muerto hasta ahora 58 personas y en Broward 49.<\/p><div class=\"notic-content-middle\" id=\"notic-1532621735\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Hasta ahora se han hecho en Florida 144,570 pruebas de COVID-19.<\/p>\n<p>Los datos actualizados sobre el avance de la pandemia en Florida muestran tambi\u00e9n que los condados floridanos libres de COVID-19 son ya solo dos, aunque en todo el noroeste del estado se registran hasta ahora muchos menos casos que en el sureste.<\/p>\n<p>Salvo Miami-Dade, Broward y Palm Beach, este \u00faltimo donde tiene su domicilio particular el presidente Donald Trump, ning\u00fan condado floridano ha sobrepasado los mil casos.<\/p>\n<p>En cuanto a las medidas preventivas frente al nuevo virus, algunas ciudades de Florida van sum\u00e1ndose a la tendencia de hacer obligatorio que las personas que trabajan en negocios esenciales (los \u00fanicos abiertos) o se dedican a la entrega a domicilios de comida y otros productos lleven tapada la boca y la nariz.<\/p>\n<p>La \u00faltima en sumarse ha sido Miramar, situada al norte de Miami.<\/p>","protected":false},"excerpt":{"rendered":"<p>El principal foco de infecci\u00f3n sigue estando en el condado de Miami Dade. Los casos confirmados de COVID-19 en Florida desde que en marzo pasado la pandemia lleg\u00f3 a este estado aumentaron a 15,456 y las muertes a 309, lo que significa 709 casos y 13 muertes m\u00e1s que el martes, seg\u00fan las autoridades de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":535137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-129980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/129980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=129980"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/129980\/revisions"}],"predecessor-version":[{"id":535138,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/129980\/revisions\/535138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/535137"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=129980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=129980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=129980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}