{"id":129134,"date":"2012-08-01T00:00:00","date_gmt":"2012-08-01T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20120801\/cierra-en-descenso-wall-street-5\/"},"modified":"2025-08-25T07:13:06","modified_gmt":"2025-08-25T07:13:06","slug":"cierra-en-descenso-wall-street-5","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20120801\/cierra-en-descenso-wall-street-5\/","title":{"rendered":"Cierra en descenso Wall Street"},"content":{"rendered":"<p><i>Cierra en descenso Wall Street<\/i><\/p>\n<p>Nueva York.- Wall Street cerr\u00f3 hoy en terreno negativo y el Dow Jones de Industriales, su principal indicador, descendi\u00f3 0,25 % y qued\u00f3 por debajo de los 13.000 puntos, despu\u00e9s de que la Reserva Federal (Fed, banco central) de EE.UU. no anunciara nuevas medidas para estimular la econom\u00eda.<\/p>\n<p>Ese \u00edndice, que agrupa a 30 de las mayores empresas cotizadas de EE.UU., rest\u00f3 32,55 puntos para acabar en las 12.976,13 unidades; al tiempo que el selectivo S&amp;P 500 perdi\u00f3 0,29 % (-4 puntos), hasta las 1.375,32 unidades; y el \u00edndice compuesto del mercado Nasdaq cedi\u00f3 0,66 % (-19,31 puntos) y se situ\u00f3 en 2,920,21 unidades.<\/p>\n<p>El parqu\u00e9 neoyorquino cerr\u00f3 con esos moderados retrocesos despu\u00e9s de que la Fed concluyera su muy esperada reuni\u00f3n de dos d\u00edas sobre pol\u00edtica monetaria manteniendo sin cambios la tasa de inter\u00e9s de referencia, aunque afirm\u00f3 que, si fuera necesario, aplicar\u00e1 m\u00e1s medidas para estimular el crecimiento de la econom\u00eda.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cierra en descenso Wall Street Nueva York.- Wall Street cerr\u00f3 hoy en terreno negativo y el Dow Jones de Industriales, su principal indicador, descendi\u00f3 0,25 % y qued\u00f3 por debajo de los 13.000 puntos, despu\u00e9s de que la Reserva Federal (Fed, banco central) de EE.UU. no anunciara nuevas medidas para estimular la econom\u00eda. Ese \u00edndice, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":908982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-129134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/129134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=129134"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/129134\/revisions"}],"predecessor-version":[{"id":909015,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/129134\/revisions\/909015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/908982"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=129134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=129134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=129134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}