{"id":128978,"date":"2015-12-17T13:31:00","date_gmt":"2015-12-17T17:31:00","guid":{"rendered":"http:\/\/www.noticel.com\/cuidate\/ahora\/20151217\/continua-incremento-en-casos-de-influenza\/"},"modified":"2025-07-29T23:14:20","modified_gmt":"2025-07-29T23:14:20","slug":"continua-incremento-en-casos-de-influenza","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20151217\/continua-incremento-en-casos-de-influenza\/","title":{"rendered":"Contin\u00faa Incremento en casos de influenza"},"content":{"rendered":"<p>La secretaria del Departamento de Salud, Ana R\u00edus Armend\u00e1riz, indic\u00f3 el jueves, que para la semana epidemiol\u00f3gica n\u00famero 49 (6 al 12 de diciembre) se reportaron 193 casos de influenza en la isla y 28 hospitalizaciones relacionadas a la misma.<\/p>\n<p>La Epidemi\u00f3loga del Estado, Brenda Rivera Garc\u00eda, enfatiz\u00f3 la importancia de medidas preventivas como el lavado frecuente de manos y la higiene al toser o estornudar para evitar el esparcir del virus.<\/p>\n<p>&#8216;La vacunaci\u00f3n es la manera id\u00f3nea de prevenir el contagio. La vacuna est\u00e1 disponible y es segura&#8217;, apunt\u00f3 en un comunicado de prensa.<\/p>\n<p>Por otra parte, la epidemi\u00f3loga indic\u00f3 que los n\u00fameros de ambos chikungunya y dengue permanecen bajos.<\/p>","protected":false},"excerpt":{"rendered":"<p>La secretaria del Departamento de Salud, Ana R\u00edus Armend\u00e1riz, indic\u00f3 el jueves, que para la semana epidemiol\u00f3gica n\u00famero 49 (6 al 12 de diciembre) se reportaron 193 casos de influenza en la isla y 28 hospitalizaciones relacionadas a la misma. La Epidemi\u00f3loga del Estado, Brenda Rivera Garc\u00eda, enfatiz\u00f3 la importancia de medidas preventivas como el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":612203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-128978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/128978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=128978"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/128978\/revisions"}],"predecessor-version":[{"id":612223,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/128978\/revisions\/612223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/612203"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=128978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=128978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=128978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}