{"id":12895,"date":"2013-10-09T00:00:00","date_gmt":"2013-10-09T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/hack\/20131009\/samsung-lanza-el-primer-smartphone-con-pantalla-curva\/"},"modified":"2025-07-17T03:25:28","modified_gmt":"2025-07-17T03:25:28","slug":"samsung-lanza-el-primer-smartphone-con-pantalla-curva","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20131009\/samsung-lanza-el-primer-smartphone-con-pantalla-curva\/","title":{"rendered":"Samsung lanza el primer smartphone con pantalla curva"},"content":{"rendered":"<p>El gigante de la tecnolog\u00eda Samsung Electronics anunci\u00f3 hoy el lanzamiento de su nuevo modelo de smartphone, Galaxy Round, el primer dispositivo del mercado con pantalla curva y flexible, que llegar\u00e1 ma\u00f1ana a las tiendas de Corea del Sur.<\/p>\n<p>Este nuevo dispositivo contar\u00e1 con una pantalla curva y flexible de 5.7 pulgadas, la misma medida que la reci\u00e9n estrenada &#8216;phablet&#8217; Galaxy Note 3, y tendr\u00e1 una c\u00e1mara delantera y trasera de 13 megapixeles y un procesador de cuatro n\u00facleos y 2,3 gigahercios.<\/p>\n<p>El flamante terminal, saldr\u00e1 a la venta por el momento solo en Corea a un precio de 1.08 millones de wones (743 euros), seg\u00fan detall\u00f3 el operador SK Telecom.<\/p>\n<p>Adem\u00e1s, contar\u00e1 con sistema operativo Android 4.3 (Jelly Bean), 3 gigas de memoria RAM, 32 gigas de memoria externa y pantalla curva de pl\u00e1stico Full HD Super AMOLED, lo que le permite que sea m\u00e1s ligero y fino.<\/p><div class=\"notic-content-middle\" id=\"notic-3028753899\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>En este sentido, el Galaxy Round pesar\u00e1 154 gramos y tendr\u00e1 un grosor de apenas 7.9 mil\u00edmetros, frente a los 168 gramos y 8.3 mil\u00edmetros del Galaxy Note 3, presentado el pasado 25 de septiembre junto con el &#8216;reloj inteligente&#8217; Galaxy Gear.<\/p>\n<p>Su nuevo dise\u00f1o curvo &#8216;permitir\u00e1 a los usuarios aprovecharse de experiencias \u00fanicas de integraci\u00f3n como el &#8216;Roll Effect&#8217;, que permite acceder a informaci\u00f3n como fecha, hora, llamadas perdidas o de la bater\u00eda de forma sencilla y cuando la pantalla este apagada&#8217;, seg\u00fan desvel\u00f3 la compa\u00f1\u00eda en un comunicado.<\/p>\n<p>Otra de las nuevas experiencias ser\u00e1 el &#8216;Gravity Effect&#8217;, que permitir\u00e1 &#8216;crear interacciones visuales con la pantalla al inclinar el dispositivo&#8217;, a\u00f1adi\u00f3 Samsung.<\/p>\n<p>Despu\u00e9s del anuncio de Samsung, se espera que la tambi\u00e9n surcoreana LG Electronics presente pr\u00f3ximamente su smartphones con pantallas OLED de pl\u00e1stico flexibles, en l\u00ednea con esta nueva tendencia del lucrativo sector de la telefon\u00eda m\u00f3vil.<\/p>","protected":false},"excerpt":{"rendered":"<p>El gigante de la tecnolog\u00eda Samsung Electronics anunci\u00f3 hoy el lanzamiento de su nuevo modelo de smartphone, Galaxy Round, el primer dispositivo del mercado con pantalla curva y flexible, que llegar\u00e1 ma\u00f1ana a las tiendas de Corea del Sur. Este nuevo dispositivo contar\u00e1 con una pantalla curva y flexible de 5.7 pulgadas, la misma medida [&hellip;]<\/p>","protected":false},"author":0,"featured_media":495055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-12895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/12895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=12895"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/12895\/revisions"}],"predecessor-version":[{"id":495057,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/12895\/revisions\/495057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/495055"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=12895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=12895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=12895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}