{"id":128720,"date":"2018-08-14T14:02:11","date_gmt":"2018-08-14T18:02:11","guid":{"rendered":"https:\/\/www.noticel.com\/comercio\/economia\/el-tiempo\/huracanes\/top-stories\/20180814\/retoman-la-venta-de-aeropuertos-regionales\/"},"modified":"2025-07-28T12:59:23","modified_gmt":"2025-07-28T12:59:23","slug":"retoman-la-venta-de-aeropuertos-regionales","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/el-tiempo\/20180814\/retoman-la-venta-de-aeropuertos-regionales\/","title":{"rendered":"Retoman la venta de aeropuertos regionales"},"content":{"rendered":"<p><i>El hurac\u00e1n Mar\u00eda retras\u00f3 dos compra ventas<\/i><\/p>\n<p>El hurac\u00e1n Mar\u00eda retras\u00f3 la venta de dos de los tres aeropuertos regionales de Puerto Rico que la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA por sus siglas en ingles) certific\u00f3 cerrar en 2015. El \u00fanico que fue vendido el pasado 7 de agosto fue el de Patillas por $150,600.<\/p>\n<p>Seg\u00fan confirm\u00f3 a NotiCel el portavoz de prensa de la Autoridad de Puertos (AP), Jose Carmona, el \u00fanico proponente para comprar el aeropuerto regional fue la empresa X-Perts Inc. La propiedad fue tasada en $130,000, y se usar\u00e1 para depositar material vegetativo recogido tras el paso del hurac\u00e1n.<\/p>\n<p>X-Perts Inc. es uno de los contratistas primarios del Cuerpo de Ingenieros del Ejercito de Estados Unidos (USACE) pues tras el paso del fen\u00f3meno atmosferico 69 municipios solicitaron ayuda directa para el recogido de escombros y desperdicios org\u00e1nicos. USACE contrat\u00f3 a X-Perts Inc. por $52 millones, y la empresa a su vez subcontrata para el recogido. Despues del paso de Mar\u00eda, en un periodo de menos de dos meses, la Oficina del Contralor registr\u00f3 90 contratos para el servicio de recogido de escombros.<\/p>\n<p>Cuando la FAA certifica el cierre de alg\u00fan aeropuerto no puede reabrirse para las mismas funciones. En este caso, tambien se suma al hecho de que se encuentra en un \u00e1rea inundaba limitando su uso y valor. Los otros dos aeropuertos que estaban en proceso de ventas son los aeropuertos de Santa Isabel y Fajardo, pero las propiedades tienen que ser tasadas otra vez porque venci\u00f3 la tasaci\u00f3n del a\u00f1o pasado. Completada la tasaci\u00f3n, se abre el proceso de subasta.<\/p>\n<p>El cierre de dos de los aeropuertos se dio por petici\u00f3n de la AP por la escasa demanda de servicios. En el caso de Fajardo, porque las operaciones aereas se trasladaron a Ceiba. No obsatante, la FAA requiere que el dinero de las ventas se utilice en mejoras a los otros siete aeropuertos regionales: Isla Grande, Ceiba, Humacao, Vieques, Culebra, Arecibo y Mayag\u00fcez.<\/p>\n<p>Por el momento, el aeropuerto de Fajardo es alquilado por la Autoridad de Energ\u00eda Electrica (AEE) como aparcadero para su flota y fue valorado en $1.4 millones el a\u00f1o pasado. En el caso de Santa Isabel fue tasado en $840,000 con un \u00e1rea de 56 acres con alto valor agr\u00edcola fuera de \u00e1reas inundables, seg\u00fan rese\u00f1\u00f3 <a href=\"https:\/\/newsismybusiness.com\/authority-patillas-possible\/\" target=\"_blank\">News Is My Business<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>El hurac\u00e1n Mar\u00eda retras\u00f3 dos compra ventas El hurac\u00e1n Mar\u00eda retras\u00f3 la venta de dos de los tres aeropuertos regionales de Puerto Rico que la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA por sus siglas en ingles) certific\u00f3 cerrar en 2015. El \u00fanico que fue vendido el pasado 7 de agosto fue el de Patillas por $150,600. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":600234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[23,22,18,19],"tags":[],"class_list":["post-128720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comercio","category-economia","category-el-tiempo","category-huracanes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/128720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=128720"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/128720\/revisions"}],"predecessor-version":[{"id":600254,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/128720\/revisions\/600254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/600234"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=128720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=128720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=128720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}