{"id":12812,"date":"2018-01-10T00:00:00","date_gmt":"2018-01-10T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/top-stories\/20180110\/quien-es-jose-izquierdo-ii\/"},"modified":"2025-07-26T02:24:28","modified_gmt":"2025-07-26T02:24:28","slug":"quien-es-jose-izquierdo-ii","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20180110\/quien-es-jose-izquierdo-ii\/","title":{"rendered":"Qui\u00e9n es Jos\u00e9 Izquierdo II"},"content":{"rendered":"<p><i>Antes de Turismo, trabaj\u00f3 en boxeo.<\/i><\/p>\n<p>El licenciado Jose Izquierdo II, quien fungi\u00f3 como director ejecutivo de la Compa\u00f1\u00eda de Turismo de Puerto Rico hasta el pasado lunes, se convirti\u00f3 en el eje de un caso de hostigamiento sexual laboral que le cost\u00f3 su cargo y ha provocado desconfianza hacia la administraci\u00f3n de Ricardo Rossell\u00f3 Nevares.<\/p>\n<p>Aunque labor\u00f3 como jefe de agencia, nombrado por el Gobernador, poco se conoce de Izquierdo II, quien previo a su puesto de carrera tuvo un historial de trabajo desligado a Turismo.<\/p>\n<p>Izquierdo II fue exdirector ejecutivo de asuntos legales y legislativos del Departamento de Desarrollo Econ\u00f3mico (DDEC), donde se afirma que colabor\u00f3 en la creaci\u00f3n de programas de incentivos que har\u00edan a Puerto Rico un destino m\u00e1s competitivo. Las \u00e1reas de enfasis de los proyectos eran reforma energetica, finanzas internacionales y el sector de servicios creativos, entre otros.<\/p>\n<p>M\u00e1s adelante, en el 2013, sirvi\u00f3 como exsecretario general de la World Boxing Organization, Vicepresidente del Comite de Campeonatos de la entidad y, un a\u00f1o despues, dirigi\u00f3 la Organizaci\u00f3n Norteamericana de Boxeo (NABO, por sus siglas en ingles) y la Organizaci\u00f3n Internacional de Boxeo (WBO-INT).<\/p>\n<p>En el 2016, meses antes del evento eleccionario, se estren\u00f3 como columnista en uno de los rotativos del pa\u00eds. En sus escritos, se destacaba su apoyo y admiraci\u00f3n hacia la entonces candidata a comisionada residente en Washington, Jenniffer Gonz\u00e1lez Col\u00f3n, con quien parece sostener una estrecha amistad.<\/p>\n<p>Tras su <a href=\"https:\/\/noticel.com\/en\/ahora\/rossell-nombra-a-directores-de-turismo-icp-y-wipr\/609767811\/\" target=\"_blank\">ratificaci\u00f3n como Director Ejecutivo de Turismo<\/a> el 30 de diciembre de 2016 por la Junta de Directores, ocho d\u00edas despues de ser nombrado por el Gobernador, Izquierdo recibi\u00f3 el apoyo de la Comisionada Residente.<\/p>\n<p>En declaraciones escritas en ese momento, Gonz\u00e1lez Col\u00f3n reaccion\u00f3 con benepl\u00e1cito a la determinaci\u00f3n.<\/p>\n<p>&#8216;Me enorgullece el nombramiento del licenciado Izquierdo, conozco y se de su profesionalismo, empe\u00f1o y visi\u00f3n para Puerto Rico. L\u00edder emprendedor con experiencia internacional, quien adem\u00e1s es parte de mi equipo de trabajo en el Partido Republicano y durante mi campa\u00f1a. Se que juntos trabajaremos en sinton\u00eda para potenciar el desarrollo econ\u00f3mico de Puerto Rico en el \u00e1rea de turismo&#8217;, expres\u00f3 la Comisionada Residente.<\/p>\n<p>Este medio intent\u00f3 conseguir a Gonz\u00e1lez Col\u00f3n para una reacci\u00f3n de las imputaciones realizadas a Izquierdo, pero hasta el momento no se ha recibido respuesta.<\/p>\n<p>Me enorgullece el nombramiento<\/p><div class=\"notic-content-middle\" id=\"notic-940412283\"><div class=\"notic-adlabel\">Advertisements<\/div><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/15123521\/JP-Monopoly-Launch-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/15123521\/JP-Monopoly-Launch-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/15123521\/JP-Monopoly-Launch-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/15123521\/JP-Monopoly-Launch-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/div>\n<p><a href=\"https:\/\/twitter.com\/jri2?ref_src=twsrc%5Etfw\">@jri2<\/a> como secretario de Turismo. Trabajaremos en sinton\u00eda para potenciar el desarrollo econ\u00f3mico de PR.<\/p>\n<p><a href=\"https:\/\/t.co\/ELzMDRIW2u\">pic.twitter.com\/ELzMDRIW2u<\/a>&#8212; Jenniffer Gonz\u00e1lez (@Jenniffer2012)<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jenniffer2012\/status\/811970285310189568?ref_src=twsrc%5Etfw\">December 22, 2016<\/a><\/p>\n<p>En terminos academicos, Izquierdo II posee un Bachillerato en Historia, Estudios Latinoamericanos e Ibericos de Haverford College en Pensilvania, habiendo tambien cursado estudios en Gobierno y Pol\u00edtica Econ\u00f3mica en el London School of Economics and Political Science.<\/p>\n<p>Recibi\u00f3 su Juris Doctor de la Facultad de Derecho de la Universidad de Puerto Rico (UPR), donde se destac\u00f3 como editor auxiliar de la Revista Jur\u00eddica, presidente de su clase y presidente del Federal Bar Association.<\/p>\n<p>A traves de las redes sociales se ha alegado, adem\u00e1s, que la conducta hostigadora data desde sus tiempos como estudiante en la UPR.<\/p>\n<p>El pasado lunes, personal de La Fortaleza inform\u00f3 sobre la remoci\u00f3n de Izquierdo II de su cargo, pero los funcionarios de gobierno <a href=\"https:\/\/noticel.com\/en\/ahora\/fortaleza-niega-alegaciones-de-hostigamiento-sexual-en-destitucin-de-izquierdo\/683437398\/\" target=\"_blank\">rechazaron que estuviera relacionado<\/a> al acoso sexual laboral.<\/p>\n<p>Incluso, en declaraciones separadas, tanto el secretario de la gobernaci\u00f3n, Willian Villafa\u00f1e Ramos, como el secretario de Asuntos P\u00fablicos y Pol\u00edtica P\u00fablica, Ram\u00f3n Rosario Cortes, se\u00f1alaron que no exist\u00edan investigaciones en curso a esos fines.<\/p>\n<p>No obstante, el martes en la tarde revirtieron la versi\u00f3n original y <a href=\"https:\/\/noticel.com\/en\/ahora\/activan-protocolo-de-hostigamiento-sexual-en-ddec\/683623294\/\" target=\"_blank\">anunciaron la activaci\u00f3n del protocolo de hostigamiento sexual<\/a> en la Compa\u00f1\u00eda de Turismo ante denuncias de una exempleada.<\/p>\n<p>&#8216;Este caso se est\u00e1 atendiendo por la Oficina de Recursos Humanos bajo estricta confidencialidad para proteger a la empleada por lo que no se emitir\u00e1n comentarios adicionales&#8217;, notific\u00f3 Villafa\u00f1e Ramos.<\/p>\n<p>Pese a que La Fortaleza no ha entrado en detalles sobre el asunto, se alega que tanto Izquierdo como Alfonso Orona Malvilla Amilivia y Christian Sobrino Vega &#8211;asesor legal y representante del Gobernador ante la Junta de Control Fiscal (JCF), respectivamente&#8211; conoc\u00edan de las imputaciones desde el mes de junio y no tomaron acci\u00f3n alguna para remediarlo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Antes de Turismo, trabaj\u00f3 en boxeo. El licenciado Jose Izquierdo II, quien fungi\u00f3 como director ejecutivo de la Compa\u00f1\u00eda de Turismo de Puerto Rico hasta el pasado lunes, se convirti\u00f3 en el eje de un caso de hostigamiento sexual laboral que le cost\u00f3 su cargo y ha provocado desconfianza hacia la administraci\u00f3n de Ricardo Rossell\u00f3 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":578852,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-12812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/12812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=12812"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/12812\/revisions"}],"predecessor-version":[{"id":578871,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/12812\/revisions\/578871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/578852"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=12812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=12812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=12812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}