{"id":127576,"date":"2012-02-21T10:51:00","date_gmt":"2012-02-21T14:51:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20120221\/banco-popular-jamaquea-su-palo\/"},"modified":"2025-07-18T08:53:09","modified_gmt":"2025-07-18T08:53:09","slug":"banco-popular-jamaquea-su-palo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20120221\/banco-popular-jamaquea-su-palo\/","title":{"rendered":"Banco Popular jamaquea su palo"},"content":{"rendered":"<p>Popular, Inc. se propone nombrar un nuevo director para su Junta de Directores, renovar el cargo de otros cuatro y llevar a cabo una divisi\u00f3n inversa de acciones (1 por 10) que haga la acci\u00f3n m\u00e1s atractiva para los inversionistas. Para ello pedir\u00e1 la aprobaci\u00f3n de sus accionistas en la reuni\u00f3n anual que se llevar\u00e1 a cabo el 27 de abril de 2012. La corporaci\u00f3n tambi\u00e9n ha hecho cambios en la estructura de la organizaci\u00f3n y ha creado un &#8216;grupo de 12 sabios&#8217; con la intenci\u00f3n de mejorar los resultados del banco.<\/p>\n<p>Una divisi\u00f3n inversa de acciones significa una reducci\u00f3n en el n\u00famero de acciones en circulaci\u00f3n. Por ejemplo, en una divisi\u00f3n de 1-10 como la propuesta, un accionista que tenga 1,000 acciones comunes antes de la divisi\u00f3n tendr\u00e1n 100 despu\u00e9s. El porcentaje de acciones comunes que cada accionista tiene con respecto al total se mantendr\u00e1 igual despu\u00e9s de la divisi\u00f3n.<\/p>\n<p>Seg\u00fan explica Popular, esta decisi\u00f3n tiene como objetivo hacer m\u00e1s atractiva la acci\u00f3n, que cotizar\u00eda 10 veces por encima de su precio. El viernes los t\u00edtulos cerraron a $1.68, lo que significa que, si la divisi\u00f3n es aprobada, la acci\u00f3n podr\u00eda cotizar alrededor de los $10. Muchos inversionistas institucionales y firmas de corretaje tienen pol\u00edticas que proh\u00edben invertir en acciones con precios bajos, es m\u00e1s atractiva una acci\u00f3n que cotiza a $10 que una que cotiza a $1.<\/p>\n<p><strong>Nuevo director<\/strong><\/p>\n<p>Durante la reuni\u00f3n anual, los accionistas deben aprobar el nombramiento de David Goel (42 a\u00f1os), gerente general y socio de Matrix Capital Management Company, LLC. Goel, con m\u00e1s de 14 millones de acciones, tiene una participaci\u00f3n de 1.43% en Popular, Inc.<\/p>\n<p>La nominaci\u00f3n de Goel se produjo despu\u00e9s de descarta a otros dos nominados recomendados por los accionistas. Uno de ellos fue descartado por su edad. Seg\u00fan las normas de la compa\u00f1\u00eda ning\u00fan director puede permanecer en el cargo despu\u00e9s de los 72 a\u00f1os.<\/p>\n<p>Adem\u00e1s, deben decidir si renuevan hasta el 2015 a los siguientes directores: Alejandro Ballester (45), presidente de Ballester Hermanos, Inc.; Richard L. Carri\u00f3n (59), principal oficial ejecutivo de Popular, Inc.; y Carlos A Unanue (48), presidente de Goya.<\/p>\n<p><strong>Revisi\u00f3n de salarios<\/strong><\/p><div class=\"notic-content-middle\" id=\"notic-2841121104\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>La Junta decidi\u00f3 no modificar la compensaci\u00f3n de los directores, a pesar de que \u2013seg\u00fan un an\u00e1lisis\u2013 est\u00e1 por debajo del mercado. En el 2011, la compensaci\u00f3n total de los directores fluctu\u00f3 entre los $120,000 de William J. Teuber Jr. y los $94,000 de Mar\u00eda Luisa Ferr\u00e9 Rangel, presidenta del Grupo Ferr\u00e9 Rangel. La compensaci\u00f3n est\u00e1 directamente relacionada con la asistencia a las reuniones, y Ferr\u00e9 Rangel es la que m\u00e1s ha faltado a las reuniones de la Junta.<\/p>\n<p>Los accionistas deben aprobar el programa de compensaci\u00f3n de los cinco ejecutivos de mayor rango. En el 2011, Richard L. Carri\u00f3n, presidente de la Junta de Directores y principal oficial ejecutivo, recibi\u00f3 una compensaci\u00f3n total de $2.6 millones, un 42% m\u00e1s que en el 2010, principalmente debido a un aumento en el salario base de $838,260 a $1,316,282. El comit\u00e9 de compensaci\u00f3n se\u00f1al\u00f3 que el aumento se justificaba porque el salario base estaba &#8216;significativamente por debajo&#8217; del que percib\u00edan ejecutivos similares que combinan las responsabilidades de presidente, principal oficial ejecutivo y presidente de la Junta de Directores.<\/p>\n<p>Jorge A. Junquera, vicepresidente y principal oficial financiero, recibi\u00f3 $1.3 millones, 19% m\u00e1s que en el 2010.<\/p>\n<p>La Junta de Directores tiene intenciones de continuar con los servicios de PricewaterhouseCoopers LLP como firma de auditor\u00eda independiente en el 2012, como lleva haciendo desde 1991. El a\u00f1o pasado, Popular pag\u00f3 $5.6 millones a PricewaterhouseCoopers por sus servicios, 28% menos de los $7.9 millones que pag\u00f3 en 2010.<\/p>\n<p><strong>Comit\u00e9 de sabios<\/strong><\/p>\n<p>Algunas fuentes se\u00f1alan que el banco habr\u00eda creado un grupo de 12 altos ejecutivos que se reunir\u00eda los fines de semana, fuera del banco, para discutir estrategias que ayudar\u00eda a mejorar los resultados y la organizaci\u00f3n del banco.<\/p>\n<p>En el 2011, las ganancias de Popular, Inc. fueron de $151.3 millones, un 10.1% m\u00e1s que en el 2010, cuando el ingreso neto fue de $137.4 millones. Para el 2012, la entidad anticipa poder alcanzar los $200 millones.<\/p>\n<p>Para m\u00e1s, vea <a href=\"http:\/\/sincomillas.com\/2012\/02\/popular-reorganizacion-y-division-inversa-de-acciones\/\" target=\"_blank\">Sincomillas.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Popular, Inc. se propone nombrar un nuevo director para su Junta de Directores, renovar el cargo de otros cuatro y llevar a cabo una divisi\u00f3n inversa de acciones (1 por 10) que haga la acci\u00f3n m\u00e1s atractiva para los inversionistas. Para ello pedir\u00e1 la aprobaci\u00f3n de sus accionistas en la reuni\u00f3n anual que se llevar\u00e1 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":502026,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-127576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/127576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=127576"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/127576\/revisions"}],"predecessor-version":[{"id":502033,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/127576\/revisions\/502033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/502026"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=127576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=127576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=127576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}