{"id":126440,"date":"2012-04-23T07:32:00","date_gmt":"2012-04-23T11:32:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20120423\/gobierno-holandes-dimitira-hoy-tras-fracaso-con-deficit\/"},"modified":"2025-07-24T04:15:23","modified_gmt":"2025-07-24T04:15:23","slug":"gobierno-holandes-dimitira-hoy-tras-fracaso-con-deficit","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20120423\/gobierno-holandes-dimitira-hoy-tras-fracaso-con-deficit\/","title":{"rendered":"Gobierno holand\u00e9s dimitir\u00e1 hoy tras fracaso con d\u00e9ficit"},"content":{"rendered":"<p>La Haya &#8211; El primer ministro holand\u00e9s, Mark Rutte, presentar\u00e1 hoy su dimisi\u00f3n ante la reina Beatriz despu\u00e9s de haber fracasado las negociaciones con el partido antimusulm\u00e1n (PVV) para aprobar los recortes necesarios para rebajar el d\u00e9ficit p\u00fablico, indicaron la agencia nacional ANP y la televisi\u00f3n p\u00fablica NOS.<\/p>\n<p>Rutte comunicar\u00e1 la decisi\u00f3n a la reina Beatriz a las 2:00 pm local (12.00 GMT), seg\u00fan esos medios, con lo que la convocatoria de elecciones anticipadas ser\u00e1 inminente.<\/p><div class=\"notic-content-middle\" id=\"notic-1176523151\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>Despu\u00e9s de siete semanas negociando con los liberales y democristianos en el Gobierno, los antimusulmanes de Geert Wilders rechazaron el pasado s\u00e1bado un paquete de medidas de ajuste para rebajar el d\u00e9ficit publico al umbral del 3 por ciento en 2013, desencadenando la crisis pol\u00edtica.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Haya &#8211; El primer ministro holand\u00e9s, Mark Rutte, presentar\u00e1 hoy su dimisi\u00f3n ante la reina Beatriz despu\u00e9s de haber fracasado las negociaciones con el partido antimusulm\u00e1n (PVV) para aprobar los recortes necesarios para rebajar el d\u00e9ficit p\u00fablico, indicaron la agencia nacional ANP y la televisi\u00f3n p\u00fablica NOS. Rutte comunicar\u00e1 la decisi\u00f3n a la reina [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-126440","post","type-post","status-publish","format-standard","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/126440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=126440"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/126440\/revisions"}],"predecessor-version":[{"id":568117,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/126440\/revisions\/568117"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=126440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=126440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=126440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}