{"id":125212,"date":"2016-04-12T16:47:00","date_gmt":"2016-04-12T20:47:00","guid":{"rendered":"http:\/\/www.noticel.com\/cuidate\/ahora\/20160412\/puerto-rico-recibe-9-5-millones-para-el-tratamiento-del-vih\/"},"modified":"2025-07-27T23:07:08","modified_gmt":"2025-07-27T23:07:08","slug":"puerto-rico-recibe-9-5-millones-para-el-tratamiento-del-vih","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160412\/puerto-rico-recibe-9-5-millones-para-el-tratamiento-del-vih\/","title":{"rendered":"Puerto Rico recibe $9.5 millones para el tratamiento del VIH"},"content":{"rendered":"<p>El Departamento de Salud de Puerto Rico inform\u00f3 el martes que el pasado 1 de abril recibi\u00f3 una asignaci\u00f3n de fondos de 9.5 millones de d\u00f3lares para la compra de medicamentos destinados a personas en la isla portadoras del Virus de Inmunodeficiencia Humana (VIH).<\/p>\n<p>La secretaria del Departamento de Salud, Ana R\u00edus Armend\u00e1riz, anunci\u00f3 a trav\u00e9s de un comunicado de que la partida de fondos se incluye en el Programa Ryan White Parte B\/ADAP.<\/p>\n<p>&#8216;A trav\u00e9s de una propuesta altamente competitiva se logr\u00f3 obtener 9,5 millones de d\u00f3lares para beneficio de la poblaci\u00f3n que vive con VIH en la isla&#8217;, se\u00f1al\u00f3 la titular de Salud.<\/p>\n<p>La asignaci\u00f3n de fondos que recibi\u00f3 el programa reconoce nuevamente los servicios de calidad que subvenciona y a la gran cantidad de personas indigentes que viven con VIH que se benefician y dependen del mismo, seg\u00fan el comunicado.<\/p><div class=\"notic-content-middle\" id=\"notic-976371735\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>La directora del Programa Ryan White Parte B\/ADAP, Norma Delgado Mercado, indic\u00f3 que a fecha de abril del 2016 el programa ha ofrecido tratamiento a m\u00e1s de 9,000 personas que viven con VIH en la isla caribe\u00f1a.<\/p>\n<p>&#8216;Nuestros esfuerzos van encaminados a asegurar el acceso a tratamiento de calidad para las personas con VIH. De esta manera aseguramos una vida de calidad a esa comunidad&#8217;, puntualiz\u00f3 Delgado Mercado.<\/p>\n<p>El Programa Ryan White Parte B, adscrito a la Oficina Central para Asuntos del Sida y Enfermedades Transmisibles del Departamento de Salud de Puerto Rico, administra fondos de la Ley Ryan White HIV\/AIDS dirigidos a asegurar el acceso a servicios cl\u00ednicos y medicamentos para la poblaci\u00f3n indigente portadora del VIH y el S\u00edndrome de Inmunodeficiencia Adquirida (Sida).<\/p>","protected":false},"excerpt":{"rendered":"<p>El Departamento de Salud de Puerto Rico inform\u00f3 el martes que el pasado 1 de abril recibi\u00f3 una asignaci\u00f3n de fondos de 9.5 millones de d\u00f3lares para la compra de medicamentos destinados a personas en la isla portadoras del Virus de Inmunodeficiencia Humana (VIH). La secretaria del Departamento de Salud, Ana R\u00edus Armend\u00e1riz, anunci\u00f3 a [&hellip;]<\/p>","protected":false},"author":0,"featured_media":594851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-125212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/125212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=125212"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/125212\/revisions"}],"predecessor-version":[{"id":594872,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/125212\/revisions\/594872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/594851"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=125212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=125212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=125212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}