{"id":124850,"date":"2012-01-17T22:39:00","date_gmt":"2012-01-18T02:39:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/20120117\/a-dar-explicaciones-por-el-servicio-de-lanchas\/"},"modified":"2025-07-18T10:14:16","modified_gmt":"2025-07-18T10:14:16","slug":"a-dar-explicaciones-por-el-servicio-de-lanchas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20120117\/a-dar-explicaciones-por-el-servicio-de-lanchas\/","title":{"rendered":"A dar explicaciones por el servicio de lanchas"},"content":{"rendered":"<p>El Senado aprob\u00f3 el martes una resoluci\u00f3n que ordena interpelar al secretario del Departamento de Transportaci\u00f3n y Obras P\u00fablicas (DTOP), Rub\u00e9n Hern\u00e1ndez Gregorat, y al director de la Oficina de Gerencia y Presupuesto (OGP), Juan Carlos Pav\u00eda, para que expliquen la crisis del servicio de lanchas hacia las islas municipio.<\/p>\n<p>La Resoluci\u00f3n del Senado 2547, radicada por los senadores del distrito de Carolina Lornna Soto Villanueva y Roger Iglesias Su\u00e1rez, as\u00ed como el senador Larry Seilhamer, portavoz de la mayor\u00eda senatorial, fue aprobada con el voto a favor de 27 senadores.<\/p>\n<p>Esta resoluci\u00f3n ordena a los funcionarios del DTOP y OGP responder sobre &#8216;las gestiones realizadas para atender el continuo problema en el ofrecimiento de servicios de transportaci\u00f3n mar\u00edtima a los residentes de Vieques y Culebra y la adquisici\u00f3n de nuevas embarcaciones&#8217;.<\/p>\n<p>&#8216;Este es un paso m\u00e1s en nuestra lucha para que los residentes de Vieques y Culebra tengan un servicio de lanchas eficiente. Ahora tanto el Secretario del DTOP como el Director de OGP tendr\u00e1n que responderle al cuerpo senatorial y tomar acci\u00f3n para que este serio problema se resuelva de una vez y por todas&#8217;, expres\u00f3 Lornna Soto Villanueva, senadora por el distrito de Carolina.<\/p>\n<p>&#8216;De acuerdo con los hallazgos de la investigaci\u00f3n, tomaremos las acciones necesarias para asegurarnos que nuestros hermanos en las islas municipio tengan el servicio de transportaci\u00f3n mar\u00edtima que ellos tanto se merecen, lo que redundar\u00e1 en una mejor calidad de vida para todos ellos y sus familias&#8217;, puntualiz\u00f3 Soto Villanueva.<\/p>\n<p>La Comisi\u00f3n Total deber\u00e1 rendir un informe final con sus hallazgos, conclusiones y recomendaciones a m\u00e1s tardar 10 d\u00edas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Senado aprob\u00f3 el martes una resoluci\u00f3n que ordena interpelar al secretario del Departamento de Transportaci\u00f3n y Obras P\u00fablicas (DTOP), Rub\u00e9n Hern\u00e1ndez Gregorat, y al director de la Oficina de Gerencia y Presupuesto (OGP), Juan Carlos Pav\u00eda, para que expliquen la crisis del servicio de lanchas hacia las islas municipio. La Resoluci\u00f3n del Senado 2547, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":515239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-124850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/124850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=124850"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/124850\/revisions"}],"predecessor-version":[{"id":515246,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/124850\/revisions\/515246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/515239"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=124850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=124850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=124850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}