{"id":12359,"date":"2017-11-28T00:00:00","date_gmt":"2017-11-28T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/legislatura\/20171128\/denuncian-recien-nacidos-post-maria-perderan-seguro-medico\/"},"modified":"2025-07-26T01:31:16","modified_gmt":"2025-07-26T01:31:16","slug":"denuncian-recien-nacidos-post-maria-perderan-seguro-medico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20171128\/denuncian-recien-nacidos-post-maria-perderan-seguro-medico\/","title":{"rendered":"Denuncian reci\u00e9n nacidos post Mar\u00eda perder\u00e1n seguro m\u00e9dico"},"content":{"rendered":"<p><i>Luego de 90 d\u00edas de nacimiento.<\/i><\/p>\n<p>La representante Maricarmen Mas Rodr\u00edguez anunci\u00f3 el martes la radicaci\u00f3n de una resoluci\u00f3n de investigaci\u00f3n para que la Comisi\u00f3n de Salud en la C\u00e1mara baja comience a estudiar la posible perdida de cubierta medica brindada a los recien nacidos en la isla tras el paso del hurac\u00e1n Mar\u00eda a finales del mes de septiembre.<\/p>\n<p>&#8216;Nos han llegado a nuestra oficina legislativa varias cartas de constituyentes relacionadas al temor que existe en que los bebes que nacieron los d\u00edas inmediatamente despues del azote del hurac\u00e1n Mar\u00eda puedan perder su cubierta medica. Seg\u00fan gu\u00edas federales establecidas por el Centro de Servicio de Medicaid y Medicare, los recien nacidos en Puerto Rico est\u00e1n cubiertos por un per\u00edodo de hasta 90 d\u00edas. Pero como hubo un hist\u00f3rico disloque en los servicios de salud en la isla tras el paso de este hurac\u00e1n, muchos bebes no han podido recibir toda la gama de asistencia medica a la cual tienen derecho&#8217;, dijo en un comunicado la legisladora por el Distrito #19, el cual comprende los municipios de Mayag\u00fcez y San Germ\u00e1n.<\/p><div class=\"notic-content-middle\" id=\"notic-2102510965\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>Indic\u00f3 que en muchas de las oficinas de Medicaid en Puerto Rico, los sistemas computarizados no est\u00e1n operando, por lo que no se ha podido hacer las actualizaciones necesarias a los sistemas para extender cubiertas medicas.<\/p>\n<p>&#8216;Vamos a dialogar con el presidente de la Comisi\u00f3n de Salud en la C\u00e1mara, el amigo Juan Oscar Morales, para que agilice esta investigaci\u00f3n. Tambien estaremos contactando a personal de Medicaid en la isla, al igual que sostendremos una reuni\u00f3n con el Comisionado de Seguros, para determinar que se puede hacer en estos casos. Lo que no vamos a permitir es que nuestros ni\u00f1os se queden descubiertos de plan medico en esta emergencia sin precedentes en nuestra historia&#8217;, agreg\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>Luego de 90 d\u00edas de nacimiento. La representante Maricarmen Mas Rodr\u00edguez anunci\u00f3 el martes la radicaci\u00f3n de una resoluci\u00f3n de investigaci\u00f3n para que la Comisi\u00f3n de Salud en la C\u00e1mara baja comience a estudiar la posible perdida de cubierta medica brindada a los recien nacidos en la isla tras el paso del hurac\u00e1n Mar\u00eda a [&hellip;]<\/p>","protected":false},"author":0,"featured_media":578544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-12359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/12359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=12359"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/12359\/revisions"}],"predecessor-version":[{"id":578556,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/12359\/revisions\/578556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/578544"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=12359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=12359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=12359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}